{"id":10170,"date":"2021-08-10T20:48:16","date_gmt":"2021-08-11T01:48:16","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=10170"},"modified":"2021-08-10T20:48:20","modified_gmt":"2021-08-11T01:48:20","slug":"paris-es-una-fiesta-y-messi-la-razon","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/paris-es-una-fiesta-y-messi-la-razon\/","title":{"rendered":"Paris es una fiesta y Messi la raz\u00f3n"},"content":{"rendered":"\n<p><strong>El astro argentino Leonel Messi lleg\u00f3 a Par\u00eds para firmar su contrato con el PSG. La ciudad Luz se enciende y Barcelona lo sufre. \u00a0<\/strong><\/p>\n\n\n\n<p>El futbol es un deporte\nmuy nuevo para la existencia del hombre, que existe hace aproximadamente 300\n000 a\u00f1os. &nbsp;Y de esos a\u00f1os, apenas en los\n\u00faltimos 120 que se juega profesionalmente. Su origen no est\u00e1 del todo aclarado,\npero hoy en d\u00eda pareciera que no hay un solo lugar del mundo donde no se le\nconozca. <\/p>\n\n\n\n<p>Se debe su fama a dos\nrazones, la primera es la simplicidad con la que se puede practicar: algo que\nse pueda patear. Puede ser una piedra, una botella, una bola de papel, un\nchapita, una pelota. Ni siquiera es necesario que existan los arcos. &nbsp;La segunda raz\u00f3n son los jugadores. <\/p>\n\n\n\n<p>En el futbol como en todo deporte existe un olimpo. Una selecta lista de jugadores que han hecho del futbol un escenario de espect\u00e1culo y apasionamiento. Estos astros surgen espor\u00e1dicamente. Dif\u00edcilmente coinciden. Cada cierto tiempo est\u00e1 parado frente a los seguidores el mejor jugador de su tiempo, el hombre de las haza\u00f1as, el que representa a un club o un pa\u00eds, el personaje que hizo lo que nadie hab\u00eda hecho por los colores que vest\u00eda. <\/p>\n\n\n\n<p>Los brasile\u00f1os del 56 en adelante aman a Pel\u00e9, el ni\u00f1o pobre que consigui\u00f3 tres t\u00edtulos mundiales para Brasil; los holandeses y el mundo se rindi\u00f3 ante el \u00c1yax de Johan Cruyff y su expresi\u00f3n de futbol total en los a\u00f1os setenta. Hay quienes ven al dios del futbol en Maradona, quiz\u00e1 el m\u00e1s emblem\u00e1tico de todos los futbolistas. Ese jugador que a la vista parec\u00eda con sobrepeso, bajito, pero que cuando agarraba la pelota no hab\u00eda forma de pararlo. \u00c9l enamor\u00f3 a la ciudad de N\u00e1poles y aument\u00f3 a\u00fan m\u00e1s el amor propio que se tienen los argentinos. Maradona fue ese jugador incomparable hasta la aparici\u00f3n de Leonel Messi. <\/p>\n\n\n\n<p>Messi debe ser un caso\nextra\u00f1o de eterno retorno griego, hubi\u00e9remos dicho reencarnaci\u00f3n si es que\nMessi no hubiera nacido con Maradona estando vivo. Messi se parece mucho a\nMaradona, ambos son argentinos, zurdos, miden menos de 1.70, y ambos vistieron\nla camiseta del Barcelona. <\/p>\n\n\n\n<p>La diferencia recae en que\nMaradona jug\u00f3 en muchos clubes y, hasta hace unos d\u00edas, Messi solo jug\u00f3 en uno:\nEl Barcelona. Hace dos d\u00edas se daba la noticia de la no continuidad del astro\nargentino en tiendas catalanas y para los aficionados es dif\u00edcil imaginar a\nMessi con otra camiseta que no sea la del club cul\u00e9. <\/p>\n\n\n\n<p>Y es que Messi no solo es\nun jugador de pasada en el Barcelona y en la ciudad. Lleg\u00f3 a los 13 a\u00f1os a\npasar una prueba y se qued\u00f3 all\u00ed. Llevaba 21 a\u00f1os ininterrumpidos jugando con\nla camiseta azulgrana. Fue el mejor jugador de la mejor generaci\u00f3n de jugadores\ndel Barcelona. Ha ganado 3 Champions League, 10 Ligas, 7 Copa del rey, 3\nSupercopa de la UEFA, 7 Supercopa de Espa\u00f1a, 3 Mundial de clubes y ha batido\nrecord quiz\u00e1 insuperables, es el jugador con m\u00e1s partidos con el club (778), y\nde yapa es el goleador del club con 672 goles. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"780\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/Dise\u00f1o-sin-t\u00edtulo-10.jpg\" alt=\"\" class=\"wp-image-10173\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/Dise\u00f1o-sin-t\u00edtulo-10.jpg 780w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/Dise\u00f1o-sin-t\u00edtulo-10-300x144.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/Dise\u00f1o-sin-t\u00edtulo-10-768x368.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><figcaption>foto: transfermarkt.es<\/figcaption><\/figure>\n\n\n\n<p>Es dif\u00edcil no imaginar la\ndesilusi\u00f3n de los hinchas al ver partir a su \u00eddolo. Es entendible las l\u00e1grimas\nde los fan\u00e1ticos al no encontrar en el campo a Messi en su \u00faltimo partido\nfrente a la Juventus. Es que muy pocas veces una ciudad vive una pena\ngeneralizada tan grande sin muertos, sin bombas, solo por futbol. <\/p>\n\n\n\n<p>La ciudad que es la otra cara\nde la moneda es Par\u00eds. El 10 de agosto Leonel Messi, en una ceremonia veloz fue\npresentado como jugador del Paris Saint Germain por una temporada y se estima\nque su salario ascender\u00eda a 50 millones anuales. Messi, de 34 a\u00f1os, llega como\njugador libre seg\u00fan &nbsp;<a href=\"https:\/\/www.transfermarkt.es\/lionel-messi\/profil\/spieler\/28003\">https:\/\/www.transfermarkt.es\/lionel-messi\/profil\/spieler\/28003<\/a>\n&nbsp;a su segundo club y usar\u00e1 el dorsal\nn\u00famero 30, que fue el mismo n\u00famero con que debut\u00f3 en el Barcelona, aquella ciudad,\naquel club que disfrut\u00f3 de su magia desde ya el lejano a\u00f1o 2004 cuando entr\u00f3 al\ncampo con apenas 17 a\u00f1os y no sali\u00f3 m\u00e1s. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El astro argentino Leonel Messi lleg\u00f3 a Par\u00eds para firmar su contrato con el PSG. La ciudad Luz se enciende y Barcelona lo sufre. \u00a0 El futbol es un deporte muy nuevo para la existencia del hombre, que existe hace aproximadamente 300 000 a\u00f1os. &nbsp;Y de esos a\u00f1os, apenas en los \u00faltimos 120 que se [&hellip;]<\/p>\n","protected":false},"author":158,"featured_media":10171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[334,78,79,331],"tags":[183,69,185,209],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10170"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/158"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=10170"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10170\/revisions"}],"predecessor-version":[{"id":10175,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10170\/revisions\/10175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/10171"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=10170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=10170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=10170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}