{"id":10336,"date":"2021-08-13T11:14:54","date_gmt":"2021-08-13T16:14:54","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=10336"},"modified":"2021-08-13T11:15:19","modified_gmt":"2021-08-13T16:15:19","slug":"ramos-y-messi-de-rivales-a-companeros-de-equipo","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/ramos-y-messi-de-rivales-a-companeros-de-equipo\/","title":{"rendered":"Ramos y Messi: De rivales a compa\u00f1eros de equipo"},"content":{"rendered":"\n<p><strong>La conocida rivalidad entre los ex capitanes del Real Madrid y Barcelona, Sergio Ramos y Messi respectivamente ser\u00e1 dejada de lado cuando jueguen juntos en el PSG.<\/strong><\/p>\n\n\n\n<p>Solo el\nParis Saint Germain, uno de los clubes m\u00e1s acaudalados del planeta, puede\npermitirse tal barbaridad como la de juntar a dos viejos archirrivales del\ncl\u00e1sico espa\u00f1ol, como lo son Messi y Sergio Ramos. Y es que esta rivalidad\nviene desde sus inicios en el futbol espa\u00f1ol.<\/p>\n\n\n\n<p>El dinero es\ny ser\u00e1 siempre determinante a la hora de cumplir un objetivo, quien diga que no,\ndesconoce lo que este puede lograr. La fortuna del PSG jug\u00f3 un factor\nimportante para que suceda esta antes imprevista combinaci\u00f3n, y es que el club\nparisino pudo hacerse con los servicios del argentino desembolsando la cantidad\nde 35 millones de euros por temporada, factor que fue determinante para\nsu retiro del Barcelona.<\/p>\n\n\n\n<p>En el caso del zaguero espa\u00f1ol, se le permiti\u00f3 conservar su\nanterior sueldo de 14 millones, el mismo que percib\u00eda en el Real Madrid y el\ncu\u00e1l ser\u00eda disminuido al 10% en caso de permanecer una temporada m\u00e1s en el club\nmadridista, propuesta que Ramos descart\u00f3. Hasta el momento, el ex madridista se\npronunci\u00f3 sobre la en su momento, posible, llegada del argentino a Paris. \u201cLeo\nMessi es uno de los mejores del mundo y por supuesto (le gustar\u00eda jugar con\n\u00e9l). Yo siempre lo he dicho: Messi siempre tendr\u00e1 un hueco en mi equipo\u201d,\nsentenci\u00f3 para el medio TNT Sports Brasil.<\/p>\n\n\n\n<p>Ahora con la confirmaci\u00f3n del arribo de \u2018La Pulga\u2019 a las\nfilas del PSG, parece no haber cambiado de opini\u00f3n. &nbsp;\u201cAl final, siempre lo\nhe dicho: Leo es uno de los mejores del mundo, por no decir el mejor. Y en ese\ncaso, no depende de m\u00ed. (\u2026) S\u00ed que es cierto que me gusta estar rodeado de los\nmejores y \u00e9l siempre tendr\u00eda sitio en mi equipo\u201d sostuvo en plena conferencia\nde prensa. Es as\u00ed que dos\nex grandes rivales, m\u00e1ximos referentes en sus clubes y en todo el futbol\nespa\u00f1ol, jugar\u00e1n en un equipo de ensue\u00f1o junto a estrellas como Mbapp\u00e9 y\nNeymar, por mencionar algunas. A disfrutar la magia que nos ofrece el futbol, y\nel dinero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La conocida rivalidad entre los ex capitanes del Real Madrid y Barcelona, Sergio Ramos y Messi respectivamente ser\u00e1 dejada de lado cuando jueguen juntos en el PSG. Solo el Paris Saint Germain, uno de los clubes m\u00e1s acaudalados del planeta, puede permitirse tal barbaridad como la de juntar a dos viejos archirrivales del cl\u00e1sico espa\u00f1ol, [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":10337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[78,79],"tags":[185,209,1553],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10336"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=10336"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10336\/revisions"}],"predecessor-version":[{"id":10338,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10336\/revisions\/10338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/10337"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=10336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=10336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=10336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}