{"id":10630,"date":"2021-12-09T13:29:48","date_gmt":"2021-12-09T18:29:48","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=10630"},"modified":"2021-12-09T13:30:46","modified_gmt":"2021-12-09T18:30:46","slug":"checkmate-el-nuevo-avion-de-combate-que-presenta-rusia-al-mundo","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/checkmate-el-nuevo-avion-de-combate-que-presenta-rusia-al-mundo\/","title":{"rendered":"Checkmate: El nuevo avi\u00f3n de combate que presenta Rusia al mundo"},"content":{"rendered":"\n<p>Seg\u00fan <a href=\"https:\/\/www.dw.com\/es\/actualidad\/s-30684\" class=\"ek-link\">Deutsche Welle<\/a>, el presidente de Rusia, Vladimir Putin ha invertido mucho en nuevo armamento y aviones de guerra, tanto para sus propias fuerzas armadas como para la venta. Por ende, se ha dise\u00f1ado el avi\u00f3n militar Checkmate para enfrentar al F-35 estadounidense, seg\u00fan expertos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/11\/MarcoMendoza.jpg\" alt=\"\" class=\"wp-image-10679\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/11\/MarcoMendoza.jpg 700w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/11\/MarcoMendoza-300x169.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption><em>Foto: Deutsche Welle  <\/em><\/figcaption><\/figure>\n\n\n\n<p>El Checkmate\nfue creado conjuntamente por el complejo militar-industrial Rostec y la United\nAircraft Corporation (UAC), que reagrupa a los principales fabricantes de\naviones civiles y militares rusos.<\/p>\n\n\n\n<p>\u00abLa\naviaci\u00f3n rusa tiene un gran potencial de desarrollo y nuestra industria aeron\u00e1utica\nsigue desarrollando nuevos aparatos competitivos\u00bb, presumi\u00f3 el presidente\nruso Vladimir Putin durante el discurso inaugural del sal\u00f3n MAKS.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Su presentaci\u00f3n se llev\u00f3 a cabo durante la ma\u00f1ana, presentaci\u00f3n que fue hecha por el mandatario ruso, horas m\u00e1s tarde se realiz\u00f3 la presentaci\u00f3n, pero para los periodistas. Adem\u00e1s, el estreno fue mundial y se transmiti\u00f3 en vivo por la plataforma de <strong>Youtube<\/strong>. <\/p>\n\n\n\n<p>Durante la\npresentaci\u00f3n se explica que el Checkmate es un proyecto para un avi\u00f3n de\ncombate ligero que incorpora soluciones t\u00e9cnicas avanzadas que est\u00e1n adaptadas\nde las tecnolog\u00edas ya desarrolladas para aviones como el Sur-57 Felon o el MiG-35\nFulcrum.<\/p>\n\n\n\n<p>As\u00ed mismo, ha\nsido dise\u00f1ado y examinado de manera digital usando supercomputadoras, el\nCheckmate est\u00e1 pensado para ser efectivo y con un costo de compra y operaci\u00f3n\ncontenido.<\/p>\n\n\n\n<p>Contar\u00e1 con un\navanzado sistema computarizado de predicci\u00f3n de fallos y gesti\u00f3n log\u00edstica, que\nbajar\u00e1 los costos de ciclo de vida de cada caza. Tambi\u00e9n se indic\u00f3 que el\nCheckmate tendr\u00e1 un bajo consumo de combustible, al ser de construcci\u00f3n ligera,\ncon un dise\u00f1o aerodin\u00e1mico refinado y estar equipado con el futuro motor\ndefinitivo del Su-57, el Izdeliye 30 m\u00e1s potente y econ\u00f3mico que la actual\ngeneraci\u00f3n de motores de aviaci\u00f3n rusos.<\/p>\n\n\n\n<p>El nuevo avi\u00f3n\nmilitar tiene incorporado una inteligencia artificial (IA) que permanentemente\nrealiza diagn\u00f3sticos de la aeronave e informa al piloto de la condici\u00f3n de la\naeronave, dando incluso el OK para el despegue.<\/p>\n\n\n\n<p>Debido a su excelente\nrelaci\u00f3n empuje peso (cercana o mejor que 1 a 1), su aerodin\u00e1mica y el empuje\nvectorial de su tobera, el Checkmate puede despegar y aterrizar en distancias cortas,\npuede realizar maniobras de 8G y tiene una excelente aceleraci\u00f3n.<\/p>\n\n\n\n<p>En resumen, en\npilones externo o internamente, Checkmate puede llevar casi todas las armas del\narsenal ruso, incluso las de nueva generaci\u00f3n desarrolladas para ser alojadas\nen las bodegas internas del Sukhoi Su-57 Felon.<\/p>\n\n\n\n<p>Finalmente, el\ncaza cuenta con un ca\u00f1\u00f3n, posiblemente el mismo del Su-57 de 30mm, ubicado en\nun pod que se aloja dentro de una de las bah\u00edas de armamento laterales.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/MarcoMendoza2vladimir-put.jpg\" alt=\"\" class=\"wp-image-11244\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/MarcoMendoza2vladimir-put.jpg 700w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/MarcoMendoza2vladimir-put-300x169.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption><em>Vladimir Putin durante la presentaci\u00f3n del Checkmate &#8211; Fuente: Deutsche Welle<\/em><\/figcaption><\/figure>\n\n\n\n<p>Se espera que el avi\u00f3n de guerra realice su viaje inaugural en 2023 y que un primer lote se produzca en 2026, detall\u00f3 la agencia de noticias Interfax al citar una presentaci\u00f3n.<\/p>\n\n\n\n<p>Con Putin, Rusia ha hecho grandes inversiones en aviones militares y nuevo armamento, tanto para sus propias fuerzas armadas como para aumentar los ingresos por exportaciones de la venta de armas. Muchas de sus nuevas armas todav\u00eda se basan en tecnolog\u00eda de la era sovi\u00e9tica de la Guerra Fr\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan Deutsche Welle, el presidente de Rusia, Vladimir Putin ha invertido mucho en nuevo armamento y aviones de guerra, tanto para sus propias fuerzas armadas como para la venta. Por ende, se ha dise\u00f1ado el avi\u00f3n militar Checkmate para enfrentar al F-35 estadounidense, seg\u00fan expertos. El Checkmate fue creado conjuntamente por el complejo militar-industrial Rostec [&hellip;]<\/p>\n","protected":false},"author":235,"featured_media":11243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[331,33,363],"tags":[294,276,1636,1001],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10630"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/235"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=10630"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10630\/revisions"}],"predecessor-version":[{"id":11245,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10630\/revisions\/11245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/11243"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=10630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=10630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=10630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}