{"id":10790,"date":"2021-12-01T14:38:02","date_gmt":"2021-12-01T19:38:02","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=10790"},"modified":"2021-12-01T14:38:18","modified_gmt":"2021-12-01T19:38:18","slug":"presentan-mocion-de-vacancia-contra-el-presidente-pedro-castillo","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/presentan-mocion-de-vacancia-contra-el-presidente-pedro-castillo\/","title":{"rendered":"Presentan moci\u00f3n de vacancia contra el presidente Pedro Castillo"},"content":{"rendered":"\n<p>El\n\u00faltimo jueves 25 de noviembre de 2021, las bancadas de Fuerza Popular, Renovaci\u00f3n\nPopular y Avanza Pa\u00eds presentaron, de manera formal ante la mesa de partes del <a href=\"https:\/\/www.congreso.gob.pe\/\">Congreso\nde la Rep\u00fablica<\/a>, la <strong>moci\u00f3n\nde vacancia presidencial<\/strong> por <strong>incapacidad moral permanente<\/strong> contra el\npresidente <a href=\"https:\/\/www.gob.pe\/presidencia#alta-direccion\">Pedro Castillo<\/a> con la firma de 28 congresistas. Sin\nembargo, la mayor\u00eda de las bancadas se ha mostrado en contra de la destituci\u00f3n\ndel mandatario.<\/p>\n\n\n\n<p>Se\nnecesita de 52 votos a favor para que sea admitida la moci\u00f3n a debate. Por otro\nlado, para concretar una vacancia, se requiere una votaci\u00f3n calificada no menor\na los dos tercios (2\/3) del n\u00famero legal de congresistas; es decir, 87 votos. Si\nse consiguen los 52 votos a favor, el Parlamento tendr\u00eda que acordar el d\u00eda y\nla hora para el debate y votaci\u00f3n del pedido de vacancia.<\/p>\n\n\n\n<p>De\nacuerdo con la sucesi\u00f3n constitucional, en el caso de que se apruebe la\nvacancia, el cargo de presidente de la rep\u00fablica es asumido por el\nvicepresidente. En la actualidad, la persona que ocupa el cargo de\nvicepresidente es <a href=\"https:\/\/www.gob.pe\/institucion\/midis\/funcionarios\/43737-dina-ercilia-boluarte-zegarra\">Dina Boluarte<\/a>, quien tambi\u00e9n se desempe\u00f1a como\nministra de <a href=\"https:\/\/www.gob.pe\/midis\">Desarrollo e Inclusi\u00f3n Social<\/a>.<\/p>\n\n\n\n<p>Como fundamentos, la moci\u00f3n alega <strong>un presunto uso ilegal de fondos p\u00fablicos<\/strong> del <a href=\"http:\/\/www.regionjunin.gob.pe\/\">Gobierno Regional de Jun\u00edn<\/a> en la campa\u00f1a electoral 2021 de Per\u00fa Libre. Asimismo, la <strong>designaci\u00f3n de altos funcionarios vinculados<\/strong>, seg\u00fan los firmantes, <strong>al terrorismo y acusados de apolog\u00eda al terrorismo<\/strong>. Adem\u00e1s, <strong>al tr\u00e1fico de influencias en ascensos en las Fuerza Armadas y en la Sunat<\/strong>. Del mismo modo, <strong>un supuesto debilitamiento del sistema democr\u00e1tico<\/strong> al fortalecer las relaciones con gobiernos antidemocr\u00e1ticos, como Venezuela, y avalar <strong>la intervenci\u00f3n de personajes extranjeros en asuntos internos<\/strong>. Igualmente, <strong>la generaci\u00f3n de inestabilidad econ\u00f3mica<\/strong>, <strong>maltrato a medios de comunicaci\u00f3n<\/strong> y <strong>negativa a rendir cuentas<\/strong> a la sociedad, y <strong>permisibilidad a la violencia contra la mujer<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/11\/Patricia-Chirinos.jpg\" alt=\"\" class=\"wp-image-10792\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/11\/Patricia-Chirinos.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/11\/Patricia-Chirinos-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: Andina<\/figcaption><\/figure>\n\n\n\n<p>Ante\nel anuncio de tener elaborada la petici\u00f3n de vacancia presidencial contra Pedro\nCastillo ante el Pleno del Congreso el pasado jueves 18 de noviembre de 2021, distintos\ncongresistas de Per\u00fa Libre y Podemos Per\u00fa cuestionaron que se trate ese\nplanteamiento. Tambi\u00e9n, las bancadas de Acci\u00f3n Popular y Juntos por el Per\u00fa informaron\nsu rechazo ante la propuesta de la legisladora de Avanza Pa\u00eds, <a href=\"https:\/\/www.congreso.gob.pe\/congresistas2021\/PatriciaChirinos\/\">Patricia Chirinos<\/a>.<\/p>\n\n\n\n<p>Por\notra parte, los parlamentarios de las bancadas de Per\u00fa Libre y Juntos por el\nPer\u00fa presentaron una moci\u00f3n de censura contra la congresista Patricia Chirinos,\nquien plante\u00f3 la vacancia presidencial. Los congresistas se\u00f1alaron que el planteamiento\nde Patricia Chirinos la \u201cdescalifica moral y \u00e9ticamente\u201d para seguir ejerciendo\nel puesto de tercera vicepresidencia del Congreso. Asimismo, los funcionarios\nmencionaron en la moci\u00f3n que el pedido de la legisladora promueve la\ninestabilidad pol\u00edtica y la ingobernabilidad del pa\u00eds. No obstante, previo al\ndebate del presupuesto nacional para el periodo 2022, con 76 votos en contra,\n42 votos a favor y una abstenci\u00f3n, el Pleno del Congreso decidi\u00f3 no admitir a\ndebate la moci\u00f3n de censura contra Patricia Chirinos.<\/p>\n\n\n\n<p>La\nmoci\u00f3n de la vacancia presidencial es una decisi\u00f3n extrema que se est\u00e1 empleando\ncontinuamente en los \u00faltimos a\u00f1os. Este reciente pedido ser\u00eda el quinto desde\nel 2016. El expresidente de la rep\u00fablica <a href=\"https:\/\/twitter.com\/ppkamigo\">Pedro\nPablo Kuczynski<\/a> afront\u00f3\ndos pedidos de vacancia, al igual que el exmandatario <a href=\"https:\/\/twitter.com\/MartinVizcarraC\">Mart\u00edn\nVizcarra<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u00faltimo jueves 25 de noviembre de 2021, las bancadas de Fuerza Popular, Renovaci\u00f3n Popular y Avanza Pa\u00eds presentaron, de manera formal ante la mesa de partes del Congreso de la Rep\u00fablica, la moci\u00f3n de vacancia presidencial por incapacidad moral permanente contra el presidente Pedro Castillo con la firma de 28 congresistas. Sin embargo, la [&hellip;]<\/p>\n","protected":false},"author":195,"featured_media":10793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[329,359,33],"tags":[1532,1659,1288,1658],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10790"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/195"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=10790"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10790\/revisions"}],"predecessor-version":[{"id":11035,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/10790\/revisions\/11035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/10793"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=10790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=10790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=10790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}