{"id":11150,"date":"2021-12-02T02:31:07","date_gmt":"2021-12-02T07:31:07","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=11150"},"modified":"2021-12-02T02:31:56","modified_gmt":"2021-12-02T07:31:56","slug":"los-museos-en-el-peru-y-el-mundo-durante-la-pandemia","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/los-museos-en-el-peru-y-el-mundo-durante-la-pandemia\/","title":{"rendered":"Los museos en el Per\u00fa y el mundo durante la pandemia"},"content":{"rendered":"\n<p><strong>Gracias a diferentes medidas tomadas por\ncada gobierno, los museos tuvieron que detener sus actividades presenciales,\nafect\u00e1ndolos en mayor medida en el \u00e1mbito econ\u00f3mico, pero aumentando su presencia\nen los medios digitales. Esto tambi\u00e9n se vivi\u00f3 en el Per\u00fa, pero poco a poco, se\ncomienzan a recuperar.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"449\" height=\"220\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Louvre.jpeg\" alt=\"\" class=\"wp-image-11157\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Louvre.jpeg 449w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Louvre-300x147.jpeg 300w\" sizes=\"(max-width: 449px) 100vw, 449px\" \/><figcaption>Museo de Louvre vac\u00edo por la pandemia. Fuente: La Vanguardia.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Los museos en todo el mundo han sufrido\nde un gran impacto desde la llegada de la pandemia, ya sea por las medidas que\nadoptaron sus gobiernos para evitar su mayor propagaci\u00f3n o porque el virus les\nhaya afectado directamente a su personal. Seg\u00fan cifras de la <a href=\"https:\/\/es.unesco.org\/news\/apoyo-museos-informe-unesco-senala-opciones-futuro\">UNESCO<\/a>, los museos estuvieron cerrados para el p\u00fablico alrededor\nde 155 d\u00edas, sin tomar en consideraci\u00f3n los pa\u00edses que tuvieron que pasar por\nun segundo periodo de confinamiento, como el caso peruano. Esto ha afectado\ndirectamente a su nivel de ingresos, ya que gran parte de ellos se manten\u00edan en\nbase a las entradas y no siempre se contaba con apoyo del Estado. Los ingresos\necon\u00f3micos normalmente van destinados a las conservaciones de las muestras, la\ninversi\u00f3n en sistemas de seguridad y el salario de los empleados. Por ello,\neste periodo de tiempo donde se vivi\u00f3 la pandemia ha sido muy duro para ello,\nya sea en su sostenimiento o en su objetivo de difusi\u00f3n de la cultura.<\/p>\n\n\n\n<p>Cuando todav\u00eda la situaci\u00f3n era cr\u00edtica,\nentre los meses de abril y mayo del a\u00f1o 2020, el <a href=\"https:\/\/icom.museum\/wp-content\/uploads\/2020\/05\/Informe-museos-y-COVID-19.pdf\">Consejo Internacional de Museos<\/a> (ICOM) consider\u00f3 hacer una evaluaci\u00f3n\nde la realidad en los cincos continentes. Con esto, se pudo confirmar que, de\nlas 1600 instituciones que participaron en ella, casi un tercio redujeron su\npersonal y m\u00e1s de una d\u00e9cima parte se ver\u00edan obligados a cerrar\npermanentemente. Espec\u00edficamente, en Am\u00e9rica Latina, solo el 12% de museos\ncorr\u00edan el peligro que clausurarse. Otro dato que proporcionan es que los\nmuseos han estado m\u00e1s al pendiente de no bajar los niveles de seguridad en sus\ninstalaciones, pero en algunos casos a\u00fan las cre\u00edan insuficientes, como el 20%\nen Am\u00e9rica Latina. Con respecto a los trabajadores, el 60,2% afirm\u00f3 trabajar\ndesde casa, dando pie a una digitalizaci\u00f3n en el \u00e1mbito laboral y una\nmodernizaci\u00f3n en la manera de presentarse.<\/p>\n\n\n\n<p>Con respecto al \u00faltimo punto, con la finalidad de seguir mostrando ante el p\u00fablico lo que pueden ofrecer dentro de este contexto, los museos han incursionado o les han dado una mayor actividad a sus medios digitales, ya sean en sus propias p\u00e1ginas o redes sociales. En las cifras otorgadas por el ICOM, las interacciones en redes sociales son las que mayor aumento han tenido, siendo el caso del 47,49% de los encuestados. La digitalizaci\u00f3n es una de las caracter\u00edsticas de la pandemia que es m\u00e1s probable que se mantenga una vez estabilizada la pandemia, gracias a las inversiones que tomaron para que se logre y la especializaci\u00f3n que el personal est\u00e1 siguiendo para poder aplicarlas. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Museo-M\u00e9xico.png\" alt=\"\" class=\"wp-image-11152\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Museo-M\u00e9xico.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Museo-M\u00e9xico-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Recorrido virtual del Museo del Palacio de Bellas Artes en M\u00e9xico. Fuente: Zacatecas<\/figcaption><\/figure>\n\n\n\n<p>Centr\u00e1ndonos en la realidad peruana, el <a href=\"https:\/\/cdn.www.gob.pe\/uploads\/document\/file\/2257093\/Reporte%20%23EstamosDeVuelta.pdf.pdf\">Ministerio de Cultura<\/a> afirm\u00f3 haber estado apoyando a los\nmuseos desde el inicio del confinamiento y el cierre de establecimientos\np\u00fablicos, ya sea promoviendo los medios digitales y una mayor participaci\u00f3n en\nlas redes sociales, o creando actividades para la conservaci\u00f3n de sus\ncolecciones y el mantenimiento de sus infraestructuras. As\u00ed tambi\u00e9n, cuando se\ncomenzaron a preparar para la reapertura, proporcionaron implementos para\ncubrir las medidas de prevenci\u00f3n, como mascarillas, protectores faciales,\nalcohol, entre otros, adem\u00e1s de acondicionar los espacios para el recibimiento\ndel p\u00fablico. El 30 de junio, se public\u00f3 el Decreto Supremo N\u00b0 117-2020-PCM, donde\nse iniciaba la Fase 3 de la reanudaci\u00f3n de las actividades econ\u00f3micas, entre\nellas los museos, por lo que pudieron recibir a los visitantes a nivel\nnacional, sin dejar de seguir estrictos protocolos de bioseguridad.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" loading=\"lazy\" width=\"359\" height=\"202\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Museos-abiertos-1.png\" alt=\"\" class=\"wp-image-11155\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Museos-abiertos-1.png 359w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Museos-abiertos-1-300x169.png 300w\" sizes=\"(max-width: 359px) 100vw, 359px\" \/><figcaption>Fuente:  LimaEasy<\/figcaption><\/figure><\/div>\n\n\n\n<p>Despu\u00e9s de un retorno al confinamiento a\ninicios del a\u00f1o 2021, el 1 de marzo de reabrieron oficialmente los museos en\nnuestro pa\u00eds, algunos de forma progresiva hasta que estuvieran todas las\nmedidas preventivas adecuadas. En Lima, son muchos los museos que actualmente\npueden ser visitados. Entre ellos, tenemos al Museo \u201cJos\u00e9 Carlos Mari\u00e1tegui\u201d,\nel \u201cLugar de la Memoria, la Tolerancia y la Inclusi\u00f3n social (LUM)\u201d, el \u201cMuseo\nde Arte Italiano\u201d, \u201cMuseo Nacional de la Cultura Peruana\u201d, \u201cMuseo Nacional de\nArqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa, entre otros m\u00e1s\u201d, con tem\u00e1ticas\ny colecciones variadas para todo tipo de intereses. Los primeros domingos de\ncada mes, el Ministerio de Cultura organiza <a href=\"https:\/\/museos.cultura.pe\/actividad\/museos-abiertos\">\u201cMuseos Abiertos (MUA)\u201d<\/a>, donde los museos brindaran acceso\ngratuito a estos, con actividades de manera virtual y presencial. Esto necesita\nser m\u00e1s difundido no solo para que se puedan mantener, sino para fomentar el\ninter\u00e9s de los peruanos hacia la cultura, siendo lugares educativos e interesantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias a diferentes medidas tomadas por cada gobierno, los museos tuvieron que detener sus actividades presenciales, afect\u00e1ndolos en mayor medida en el \u00e1mbito econ\u00f3mico, pero aumentando su presencia en los medios digitales. Esto tambi\u00e9n se vivi\u00f3 en el Per\u00fa, pero poco a poco, se comienzan a recuperar. Los museos en todo el mundo han sufrido [&hellip;]<\/p>\n","protected":false},"author":205,"featured_media":11151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,34],"tags":[906,535,916,124,1690],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11150"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/205"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=11150"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11150\/revisions"}],"predecessor-version":[{"id":11159,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11150\/revisions\/11159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/11151"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=11150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=11150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=11150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}