{"id":11399,"date":"2021-12-02T22:21:53","date_gmt":"2021-12-03T03:21:53","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=11399"},"modified":"2021-12-02T22:36:22","modified_gmt":"2021-12-03T03:36:22","slug":"la-vacancia-cada-vez-mas-cerca-para-pedro-castillo","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/la-vacancia-cada-vez-mas-cerca-para-pedro-castillo\/","title":{"rendered":"La vacancia cada vez m\u00e1s cerca para Pedro Castillo"},"content":{"rendered":"\n<p style=\"text-align:justify\">El presidente Pedro\nCastillo afronta hoy una moci\u00f3n de vacancia en su contra que fue impulsada por\nla congresista Patricia Chirinos y respaldada por las bancadas de Fuerza\nPopular, Renovaci\u00f3n Popular y Avanza Pa\u00eds. Las bancadas de oposici\u00f3n sostienen\nque son 7 los motivos por los que buscan vacar al presidente Pedro Castillo,\nentre ellos la investigaci\u00f3n fiscal por el caso de los din\u00e1micos del Centro,\nalgunos nombramientos cuestionables, y principalmente el ser causante de la\ninestabilidad econ\u00f3mica, seg\u00fan se\u00f1alaron, pero \u00bfCu\u00e1les son los pasos que se\ndebe seguir en la moci\u00f3n de vacancia en el congreso?<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/PATRICIA-CHIRINOS-CORDOVA-YOMAIRA.jpg\" alt=\"\" class=\"wp-image-11468\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/PATRICIA-CHIRINOS-CORDOVA-YOMAIRA.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/PATRICIA-CHIRINOS-CORDOVA-YOMAIRA-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption><em>Fuente: La Rep\u00fablica<\/em><\/figcaption><\/figure>\n\n\n\n<p style=\"text-align:justify\">Tras su presentaci\u00f3n con 28 firmas, el 25 de noviembre pasado se dio cuenta de los votos en la misma sesi\u00f3n plenaria, despu\u00e9s de presentada la moci\u00f3n de vacancia, contaba con el respaldo de 45 congresistas, adem\u00e1s un grupo de parlamentarios ven\u00eda evaluando su posici\u00f3n; sin embargo, hasta este momento, de acuerdo con las proyecciones, se cuenta por lo menos con 48 congresistas, m\u00e1s a\u00fan&nbsp; los votos de los aquellos parlamentarios que presentaron el pedido de vacancia y otros que se sumaron despu\u00e9s, ya que se han adherido \u00faltimamente otros 7 votos, estos provienen de bancadas como Podemos Per\u00fa, Alianza para el Progreso, Acci\u00f3n Popular y Somos Per\u00fa, de esta forma, faltar\u00edan solo 2 votos para que se pueda admitir a debate la moci\u00f3n de vacancia contra el presidente Castillo.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-editorskit-rounded\"><figure class=\"alignleft is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/CORDOVA-YOMAIRA-KARELYN-1.jpg\" alt=\"\" class=\"wp-image-11472\" width=\"363\" height=\"196\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/CORDOVA-YOMAIRA-KARELYN-1.jpg 980w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/CORDOVA-YOMAIRA-KARELYN-1-300x162.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/CORDOVA-YOMAIRA-KARELYN-1-768x414.jpg 768w\" sizes=\"(max-width: 363px) 100vw, 363px\" \/><figcaption><em>Fuente: El Comercio<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p style=\"text-align:justify\">En el momento de los votos se registr\u00f3 im\u00e1genes, donde se revelaban las reuniones que manten\u00eda el jefe de Estado en un inmueble que se ubicaba en el distrito de Bre\u00f1a, uno de estos encuentros fue con Karelyn L\u00f3pez Arredondo, asesora de la empresa que gan\u00f3 la licitaci\u00f3n de una obra de 232 millones de soles de prov\u00edas descentralizado, seg\u00fan <a href=\"https:\/\/elcomercio.pe\/\">El Comercio<\/a>.<\/p>\n\n\n\n<p style=\"text-align:justify\">El congresista Alejandro Cavero de Avanza Pa\u00eds, se\u00f1al\u00f3 que la votaci\u00f3n para definir si se emit\u00eda o no a debate la moci\u00f3n de vacancia, estar\u00eda previsto para el 7 de Diciembre, el parlamentario agreg\u00f3 que de llegar a los votos ese d\u00eda, es posible que en el siguiente pleno se vea el fondo del pedido de vacancia, de alcanzar los votos, el pleno del congreso debe acordar la fecha y hora del d\u00eda en que se debatir\u00e1 y votar\u00e1 el fondo del pedido de vacancia contra el presidente Castillo, de acuerdo al reglamento, esta sesi\u00f3n no puede realizarse antes del tercer d\u00eda siguiente de la votaci\u00f3n sobre la admisi\u00f3n a debate, ni despu\u00e9s del d\u00e9cimo, es decir, esta sesi\u00f3n se podr\u00eda realizar entre el viernes 10 y el viernes 17 de Diciembre, as\u00ed como sucedi\u00f3 con los ex presidentes Pedro Pablo Kuczynski y Martin Vizcarra.<\/p>\n\n\n\n<p style=\"text-align:justify\">El presidente Pedro Castillo, tambi\u00e9n podr\u00e1 hacer uso de su derecho a la defensa personal o mediante un abogado durante la sesi\u00f3n donde se debata  la moci\u00f3n a la vacancia en su contra, esto por un plazo de 60 minutos. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/PEDRO-CASTILLO-CORDOVA-YOMAIRA.jpg\" alt=\"\" class=\"wp-image-11469\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/PEDRO-CASTILLO-CORDOVA-YOMAIRA.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/PEDRO-CASTILLO-CORDOVA-YOMAIRA-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption><em>Fuente: Per\u00fa 21<\/em><\/figcaption><\/figure>\n\n\n\n<p style=\"text-align:justify\">Para declarar la vacancia de la presidencia de la Rep\u00fablica por la causal de incapacidad moral permanente, se requieren de una votaci\u00f3n calificada no menor de 87 votos, la resoluci\u00f3n que declara la vacancia tiene que ser publicada en el diario oficial \u201cEl Peruano\u201d dentro de las 24 horas siguientes de la recepci\u00f3n de esta resoluci\u00f3n. El art\u00edculo 115 de <a href=\"http:\/\/www.pcm.gob.pe\/wp-content\/uploads\/2013\/09\/Constitucion-Pol%C3%ADtica-del-Peru-1993.pdf\">la constituci\u00f3n<\/a> establece que ante el impedimento temporal o permanente de la presidencia de la Rep\u00fablica, asuman sus funciones el primer vicepresidente o en su defecto el segundo vicepresidente, en el caso de que ambos se vean impedidos, es el presidente del congreso de la rep\u00fablica el que ejercer\u00eda esta funci\u00f3n. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Pedro Castillo afronta hoy una moci\u00f3n de vacancia en su contra que fue impulsada por la congresista Patricia Chirinos y respaldada por las bancadas de Fuerza Popular, Renovaci\u00f3n Popular y Avanza Pa\u00eds. Las bancadas de oposici\u00f3n sostienen que son 7 los motivos por los que buscan vacar al presidente Pedro Castillo, entre ellos [&hellip;]<\/p>\n","protected":false},"author":207,"featured_media":11480,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[329,359,33],"tags":[1573,1731,89,1729,1658],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11399"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/207"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=11399"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11399\/revisions"}],"predecessor-version":[{"id":11489,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11399\/revisions\/11489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/11480"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=11399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=11399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=11399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}