{"id":11400,"date":"2021-12-02T21:06:48","date_gmt":"2021-12-03T02:06:48","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=11400"},"modified":"2021-12-02T21:06:53","modified_gmt":"2021-12-03T02:06:53","slug":"biden-vs-omicron-nuevas-medidas-y-restricciones-en-ee-uu","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/biden-vs-omicron-nuevas-medidas-y-restricciones-en-ee-uu\/","title":{"rendered":"Biden vs \u00f3micron: nuevas medidas y restricciones en EE. UU"},"content":{"rendered":"\n<p>Tras el surgimiento de una nueva variante del covid-19 el presidente de los Estados Unidos, Joe Biden, anunci\u00f3 un plan para combatir el virus con nuevas medidas tanto para los turistas como para los residentes.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized is-style-default\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/biden.jpg\" alt=\"\" class=\"wp-image-11436\" width=\"464\" height=\"348\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/biden.jpg 800w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/biden-300x225.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/biden-768x576.jpg 768w\" sizes=\"(max-width: 464px) 100vw, 464px\" \/><figcaption>Fuente: Excelsior<\/figcaption><\/figure>\n\n\n\n<p>En estos momentos la nueva variante<strong> \u00f3micron<\/strong>\nmantiene alerta a todo el mundo que, en algunos pa\u00edses, ya cre\u00eda haber superado\nel pico de contagios por la pandemia; por lo que en distintos pa\u00edses vuelve a\nsurgir la incertidumbre sobre una posible nueva cuarentena, cierre de fronteras\ny otras restricciones.<\/p>\n\n\n\n<p>Sin embargo, en Estados Unidos ya se ha registrado su primer caso con esta variante. Seg\u00fan la <a href=\"https:\/\/www.dw.com\/es\/detectan-el-primer-caso-de-la-variante-%C3%B3micron-en-estados-unidos\/a-59990908\" class=\"ek-link\">DW<\/a> el Dr. Anthony Fauci anunci\u00f3 que el caso habr\u00eda sido detectado en California a un paciente que retornaba a Estados Unidos desde Sud\u00e1frica. Tambi\u00e9n se mencion\u00f3 que la persona contaba con las dos dosis de su vacuna contra la covid-19, mas no habr\u00eda obtenido su dosis de refuerzo.<\/p>\n\n\n\n<p>Ante esta situaci\u00f3n, el presidente Joe Biden ha pedido calma a la poblaci\u00f3n, y en su \u00faltimo discurso, que fue transmitido por <a href=\"https:\/\/www.youtube.com\/watch?v=tpgXhx0YvAk\" class=\"ek-link\">Noticias Telemundo<\/a>, aprovech\u00f3 en se\u00f1alar las nuevas restricciones que se han propuesto para salvaguardar la salud de los habitantes. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"650\" height=\"357\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/terceraimg.jpg\" alt=\"\" class=\"wp-image-11438\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/terceraimg.jpg 650w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/terceraimg-300x165.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption>Fuente: El Caribe<\/figcaption><\/figure>\n\n\n\n<p>Como parte de la nueva campa\u00f1a contra el covid-19 se han planteado nuevos requisitos para los viajeros. Antes estos deb\u00edan presentar una prueba negativa 72 horas antes de su partida; en cambio, ahora todos los <strong>turistas<\/strong>, ingresen o salgan del pa\u00eds,  tienen que presentar una prueba negativa realizada <strong>24 horas<\/strong> antes de su vuelo, asimismo deber\u00e1n estar vacunados con sus dosis completas, sin excepci\u00f3n. <\/p>\n\n\n\n<p>Mientras que, en el interior del pa\u00eds, se ha regresado a la <strong>obligatoriedad del uso de la mascarilla<\/strong> en el interior de los medios de transporte p\u00fablico como trenes, aviones, etc. Esto con la finalidad de no exponerse a un posible contagio por encontrase en lugares con poca circulaci\u00f3n de aire.<\/p>\n\n\n\n<p>Otra de las medidas propuestas en su discurso es <strong>ampliar la campa\u00f1a de dosis de refuerzo<\/strong>, por lo que las aseguradoras correr\u00e1n con los gastos de las pruebas caseras; mientras que para los ciudadanos que no tengan seguro se les instalar\u00e1 lugares donde podr\u00e1n recoger pruebas para llevarlas a su domicilio.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"382\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/cuarta-img.jpg\" alt=\"\" class=\"wp-image-11440\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/cuarta-img.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/cuarta-img-300x169.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: BBC<\/figcaption><\/figure>\n\n\n\n<p>Ante la expectativa de muchos negocios y empresas el presidente\nanunci\u00f3 que no se retornar\u00e1 a los cierres masivos, a diferencia de lo ocurrido en\nlos inicios de la pandemia. Todo esto con el objetico de no retrasar la\nrecuperaci\u00f3n econ\u00f3mica que atraviesa el pa\u00eds.<\/p>\n\n\n\n<p>Por otra parte, otro sector preocupado por el\nsurgimiento de la nueva variante era el educativo. Sobre ello, el mandatario\nmencion\u00f3 que intentar\u00e1 no volver al cierre masivo de escuelas, pues hoy en d\u00eda\nm\u00e1s del 99 % de escuelas se encuentran abiertas, adem\u00e1s de que en Estados Unidos\nse ha puesto en funcionamiento una vacuna para ni\u00f1os de cinco a\u00f1os en adelante.<\/p>\n\n\n\n<p>No obstante, para que las nuevas medidas tengan efecto\nla poblaci\u00f3n debe obedecer y protegerse lo m\u00e1s que pueda. En el discurso, el\npresidente pidi\u00f3 a la poblaci\u00f3n acatar a las medidas propuestas y tomarlas como\n\u201cuna responsabilidad patri\u00f3tica\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el surgimiento de una nueva variante del covid-19 el presidente de los Estados Unidos, Joe Biden, anunci\u00f3 un plan para combatir el virus con nuevas medidas tanto para los turistas como para los residentes. En estos momentos la nueva variante \u00f3micron mantiene alerta a todo el mundo que, en algunos pa\u00edses, ya cre\u00eda haber [&hellip;]<\/p>\n","protected":false},"author":224,"featured_media":11442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[331,482],"tags":[54,959],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11400"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/224"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=11400"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11400\/revisions"}],"predecessor-version":[{"id":11444,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11400\/revisions\/11444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/11442"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=11400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=11400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=11400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}