{"id":11412,"date":"2021-12-02T20:22:21","date_gmt":"2021-12-03T01:22:21","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=11412"},"modified":"2021-12-02T20:39:44","modified_gmt":"2021-12-03T01:39:44","slug":"arqueologos-de-la-universidad-nacional-mayor-de-san-marcos-encuentran-momia-en-lima","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/arqueologos-de-la-universidad-nacional-mayor-de-san-marcos-encuentran-momia-en-lima\/","title":{"rendered":"Arque\u00f3logos de la Universidad Nacional Mayor de San Marcos encuentran momia en Lima"},"content":{"rendered":"\n<p><strong>Mientras se llevaba a cabo un trabajo de investigaci\u00f3n en la zona, arque\u00f3logos encuentran \u00a0una momia preinca en excelentes condiciones de conservaci\u00f3n en el Complejo Arqueol\u00f3gico de Cajamarquilla, en Lurigancho-Chosica.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/59972418_403.jpg\" alt=\"\" class=\"wp-image-11415\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/59972418_403.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/59972418_403-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente:  <em>Deutsche Welle<\/em>\u00a0(<em>DW<\/em>) <\/figcaption><\/figure>\n\n\n\n<p>Miembros de la <a href=\"https:\/\/www.unmsm.edu.pe\/\">Universidad Nacional Mayor de San Marcos<\/a> (UNMSM), en colaboraci\u00f3n con estudiantes de la Universidad Nacional de San Crist\u00f3bal de Huamanga (UNSAAC) y la Universidad Nacional de San Antonio Abad del Cusco (UNSAAC), hallaron la momia de un hombre de aproximadamente 800 a 1200 a\u00f1os de antig\u00fcedad .<\/p>\n\n\n\n<p>El cuerpo correspond\u00eda\nal de un var\u00f3n que habr\u00eda fallecido a los 25 a\u00f1os de edad aproximadamente. Este,\nfue encontrado en una c\u00e1mara funeraria de unos 3 metros de largo y a una\nprofundidad de 1.40 metros.<\/p>\n\n\n\n<p>La momia fue encontrada en posici\u00f3n fetal, con sus manos cubriendo su rostro y envuelto con cuerdas por todo su cuerpo. Adem\u00e1s, se encontraron restos de llama y, muy cerca de \u00e9l,\u00a0 se hallaron varios moluscos marinos.<\/p>\n\n\n\n<p><strong>Hablan los expertos <\/strong><\/p>\n\n\n\n<p>Para los\nexpertos, &nbsp;la ubicaci\u00f3n de la &nbsp;momia, en medio de la plaza, puede reflejar el\nalto estatus que tuvo en vida. Adem\u00e1s,&nbsp;\nresaltan que&nbsp; el hecho de haberlo\nencontrado envuelto en estas sogas demostrar\u00eda que se trata de un poblador de\nla zona sierra del Per\u00fa, pues est\u00e1s t\u00e9cnicas de entierro fueron comunes en esas\nzonas del pa\u00eds.<\/p>\n\n\n\n<p>Las caracter\u00edsticas de este hallazgo, corroborar\u00edan lo dicho por <a href=\"https:\/\/doi.org\/10.15381\/arqueolsoc.2021n34.e20634\">Yomira Huam\u00e1n Santill\u00e1n<\/a>, l\u00edder de esta investigaci\u00f3n junto\u00a0 con el Dr. Pieter Van Dalen, en una de sus anteriores investigaciones para la revista <em>Arqueolog\u00eda y Sociedad <\/em>de la UNMSM, la cual refiere:  \u00abDurante el Periodo Intermedio Tard\u00edo, Cajamarquilla se \u00a0convirti\u00f3 en un centro comercial multi\u00e9tnico, donde resid\u00edan personas de diversos \u00a0grupos \u00e9tnicos, aunque principalmente poblaci\u00f3n local (ichma perif\u00e9rica) y chacllas \u00a0dedicados a esta actividad cultural\u00bb.<\/p>\n\n\n\n<p>Tras el hallazgo, Yomira Huam\u00e1n\u00a0 coment\u00f3 lo siguiente en un <a href=\"https:\/\/elcomercio.pe\/tecnologia\/ciencias\/arqueologos-de-san-marcos-hallan-momia-preinca-en-lima-noticia\/?ref=ecr\">conocido medio local<\/a>: \u00abLa momia se encontr\u00f3 al interior de una estructura funeraria subterr\u00e1nea ovalada, que presentaba una plataforma en el lado norte a la cual se accede por una escalinata de siete gradas y casi al terminar la investigaci\u00f3n, encontraron la boca de la tumba y a la momia que se encontraba en posici\u00f3n fetal\u00bb.<\/p>\n\n\n\n<p>\u00abEl descubrimiento de este residente arroja una nueva\nluz sobre las interacciones y relaciones en tiempos prehisp\u00e1nicos\u00bb, <a href=\"https:\/\/cnnespanol.cnn.com\/2021\/11\/29\/arqueologos-momia-lima-peru-trax\/\">dijo\n&nbsp;por su parte<\/a> el Dr. Pieter Van Dalen\n.<\/p>\n\n\n\n<p>Se sabe que los trabajos de excavaci\u00f3n iniciaron en esta zona a mediados de octubre con un equipo de 40 personas y que\u00a0 al momento del hallazgo ya se dispon\u00edan a retirarse del lugar, por lo que se trat\u00f3 de una sorpresa hasta para los mismos investigadores.<\/p>\n\n\n\n<p><strong>Algunos datos sobre el Complejo Arqueol\u00f3gico de\nCajamarquilla<\/strong><\/p>\n\n\n\n<p>El complejo arqueol\u00f3gico, que se ubica a 24 km al este de Lima, se construy\u00f3 aproximadamente 200 a\u00f1os antes de Cristo y es uno de los m\u00e1s grandes estudiados en Lima.<\/p>\n\n\n\n<p>En este se llevaron a cabo m\u00faltiples labores administrativas y comerciales. Por ello, lleg\u00f3 a albergar entre 10.000 y 20.000 personas \u00a0en un \u00e1rea de 167 hect\u00e1reas y estuvo habitada hasta el a\u00f1o 1500.<\/p>\n\n\n\n<p>Su ubicaci\u00f3n fue estrat\u00e9gica, pues funcion\u00f3 como&nbsp;centro\nde interacci\u00f3n interregional y comercial, pues estaba ubicado en el distrito de\nLurigancho &#8211; Chosica, a 3 km del margen derecho del valle del r\u00edo R\u00edmac.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras se llevaba a cabo un trabajo de investigaci\u00f3n en la zona, arque\u00f3logos encuentran \u00a0una momia preinca en excelentes condiciones de conservaci\u00f3n en el Complejo Arqueol\u00f3gico de Cajamarquilla, en Lurigancho-Chosica. Miembros de la Universidad Nacional Mayor de San Marcos (UNMSM), en colaboraci\u00f3n con estudiantes de la Universidad Nacional de San Crist\u00f3bal de Huamanga (UNSAAC) y [&hellip;]<\/p>\n","protected":false},"author":200,"featured_media":11417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,357,359],"tags":[850,81,599,66],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11412"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/200"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=11412"}],"version-history":[{"count":5,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11412\/revisions"}],"predecessor-version":[{"id":11423,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11412\/revisions\/11423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/11417"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=11412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=11412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=11412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}