{"id":11425,"date":"2021-12-02T21:22:01","date_gmt":"2021-12-03T02:22:01","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=11425"},"modified":"2021-12-02T21:22:58","modified_gmt":"2021-12-03T02:22:58","slug":"pantanos-de-villa-pequeno-paraiso-de-flora-y-fauna-en-lima","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/pantanos-de-villa-pequeno-paraiso-de-flora-y-fauna-en-lima\/","title":{"rendered":"Pantanos de Villa: peque\u00f1o para\u00edso de flora y fauna en Lima"},"content":{"rendered":"\n<p>Los Pantanos de Villa, es un refugio de vida silvestre cuyo objetivo es el cuidado y la conservaci\u00f3n de todas las especies de vida silvestre que habitan en este lugar. Adem\u00e1s, el uso racional y sostenible de sus recursos. <\/p>\n\n\n\n<p>El 31 de agosto de 2006, se hizo oficial la creaci\u00f3n del \u00c1rea Natural Protegida mediante el <a href=\"https:\/\/legislacionanp.org.pe\/refugio-de-vida-silvestre-pantanos-de-villa\/\" class=\"ek-link\">Decreto Supremo N\u00b0055-2006-AG<\/a>. Se encuentra en el distrito de Chorrillos a 40 minutos del centro de Lima y cuenta con una extensi\u00f3n de 263,27 hect\u00e1reas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"592\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/LRM_EXPORT_20210130_205658-1024x592.jpg\" alt=\"\" class=\"wp-image-11430\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/LRM_EXPORT_20210130_205658-1024x592.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/LRM_EXPORT_20210130_205658-300x173.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/LRM_EXPORT_20210130_205658-768x444.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Maudy Chirito<\/figcaption><\/figure>\n\n\n\n<p>Si bien su nombre hace uso del t\u00e9rmino \u201cpantano\u201d, los mismos gu\u00edas del lugar explican que propiamente hablando no deber\u00edan ser catalogados como \u00abpantanos\u00bb, ya que no est\u00e1n constituidos de agua empozada que despida un olor caracter\u00edstico y no tan agradable como lo hace un pantano naturalmente, sino que se conforma de la filtraci\u00f3n de distintos r\u00edos, como el R\u00edmac y el Lur\u00edn. Por lo tanto, Los \u201cPantanos\u201d de Villa, correctamente hablando, son humedales, seg\u00fan una nota de <a href=\"https:\/\/peru21.pe\/ciencia\/nerdgasmo-los-pantanos-de-villa-el-humedal-de-lima-que-se-resiste-a-desaparecer-fotos-video-pantanos-de-villa-noticia\/?ref=p21r\" class=\"ek-link\">Per\u00fa21<\/a>.<\/p>\n\n\n\n<p>Esta ANP se encuentra en una depresi\u00f3n natural que permite el libre flujo de aguas, integrando el sistema hidrol\u00f3gico del R\u00edmac y a trav\u00e9s del acu\u00edfero Ate \u2013 Surco \u2013 Chorrillos. Gracias a ello, contamos con la presencia de puquiales, ojos de agua y lagunas; sin embargo, este aporte del r\u00edo R\u00edmac est\u00e1 disminuyendo debido a la contaminaci\u00f3n ambiental, inform\u00f3 el <a href=\"https:\/\/lospantanosdevilla.wordpress.com\/ubicacion\/\" class=\"ek-link\">WordPress de los Pantanos de Villa<\/a>. <\/p>\n\n\n\n<p>En esta \u00e1rea natural el clima es muy similar al de la costa central del Per\u00fa, se conserva una temperatura promedio a 18.6\u00b0C, un cielo gris con suaves lloviznas y una intensa humedad que oscila entre 85 y 99%.<\/p>\n\n\n\n<p>Este Refugio de Vida Silvestre alberga una gran cantidad no solo de vegetaci\u00f3n sino que tambi\u00e9n de distintas especies, entre ellas, aves, roedores, murci\u00e9lagos, ar\u00e1cnidos, peces, reptiles, entre otros. <\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Secado.jpg\" alt=\"\" class=\"wp-image-11435\" width=\"577\" height=\"383\" \/><figcaption>Foto: David Bonifacio<\/figcaption><\/figure>\n\n\n\n<p>Seg\u00fan <a href=\"https:\/\/peru21.pe\/ciencia\/nerdgasmo-los-pantanos-de-villa-el-humedal-de-lima-que-se-resiste-a-desaparecer-fotos-video-pantanos-de-villa-noticia\/?ref=p21r\" class=\"ek-link\">Per\u00fa21<\/a>, los Pantanos de Villa registran alrededor de 213 especies de aves, 8 especies de mam\u00edferos, 13 especies de peces, 55 tipos de ara\u00f1as, 3 tipos de culebras y una gran variedad de insectos.  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Garza-blanca-2.jpg\" alt=\"\" class=\"wp-image-11448\" width=\"264\" height=\"169\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Garza-blanca-2.jpg 1000w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Garza-blanca-2-300x192.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Garza-blanca-2-768x492.jpg 768w\" sizes=\"(max-width: 264px) 100vw, 264px\" \/><figcaption>Foto: Maudy Chirito<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Salicornia-3.jpg\" alt=\"\" class=\"wp-image-11447\" width=\"294\" height=\"194\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Salicornia-3.jpg 1000w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Salicornia-3-300x198.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Salicornia-3-768x508.jpg 768w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/><figcaption>Foto: David Bonifacio<\/figcaption><\/figure><\/div>\n\n\n\n<p> Seg\u00fan la <a href=\"https:\/\/www.gob.pe\/institucion\/sernanp\/informes-publicaciones\/1833908-refugio-de-vida-silvestre-los-pantanos-de-villa\">Plataforma digital \u00fanica del Estado Peruano<\/a> las especies de aves se dividen en residentes, con registros eventuales y migratorias. Estas \u00faltimas pueden proceder de Am\u00e9rica del Norte, Am\u00e9rica del Sur, los Andes y algunas locales. Entre las aves m\u00e1s conocidas est\u00e1 el potoyunco peruano (<em>Pelecanoides garnotii<\/em>), el pelicano peruano (<em>Pelecanus thagus<\/em>), el guanay (<em>Phalacrocorax bouganvilli<\/em>)<em>,<\/em> el zambullidor blanquillo (<em>Podiceps occidentalis), <\/em>la gallareta gigante (<em>Fulica gigantea<\/em>) y m\u00e1s. Por otro lado, la flora en los Pantanos de Villa registra 67 especies de plantas, siendo las m\u00e1s conocidas la totora (<em>Thypa dominguensis<\/em>) y la grama salada (<em>Distichlis spicata<\/em>).  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Camino.jpg\" alt=\"\" class=\"wp-image-11452\" width=\"342\" height=\"254\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Camino.jpg 999w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Camino-300x223.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Camino-768x571.jpg 768w\" sizes=\"(max-width: 342px) 100vw, 342px\" \/><figcaption>Foto: Maudy Chirito<\/figcaption><\/figure><\/div>\n\n\n\n<p>Adem\u00e1s de la flora y fauna, los Pantanos de Villa contienen tres lagunas donde los visitantes pueden encontrar determinadas especies. La laguna Grande, contiene una torre miradora por la cual se puede apreciar la magnitud del \u00e1rea, la laguna Genesis, cerca al Centro de Interpretaci\u00f3n, donde encontramos los totorales y la laguna Miramar, donde se encuentran la mayor\u00eda de las aves migratorias; seg\u00fan <a href=\"http:\/\/perubirds.org\/rutas_Pantanos_de_Villa.shtml#thumb\" class=\"ek-link\">Per\u00fa Birds<\/a>. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Pantanos de Villa, es un refugio de vida silvestre cuyo objetivo es el cuidado y la conservaci\u00f3n de todas las especies de vida silvestre que habitan en este lugar. Adem\u00e1s, el uso racional y sostenible de sus recursos. El 31 de agosto de 2006, se hizo oficial la creaci\u00f3n del \u00c1rea Natural Protegida mediante [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":11429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[448,325,327,326],"tags":[1717,541,1718],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11425"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=11425"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11425\/revisions"}],"predecessor-version":[{"id":11458,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11425\/revisions\/11458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/11429"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=11425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=11425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=11425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}