{"id":11577,"date":"2021-12-03T01:11:11","date_gmt":"2021-12-03T06:11:11","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=11577"},"modified":"2021-12-03T09:30:37","modified_gmt":"2021-12-03T14:30:37","slug":"thriller-un-videoclip-que-se-hizo-historia","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/thriller-un-videoclip-que-se-hizo-historia\/","title":{"rendered":"Thriller: un videoclip que se hizo historia"},"content":{"rendered":"\n<p>Un 2 de diciembre de hace 38 a\u00f1os, el mundo se dej\u00f3 conquistar por un video\nmusical de 14 minutos, del denominado Rey del Pop, Michael Jackson, quien entreg\u00f3\nal mundo a \u201cThriller\u201d una de las piezas m\u00e1s ic\u00f3nicas de la historia musical,\npieza que adem\u00e1s, afirmo su poder en la industria posicion\u00e1ndose como un\nartista de talla mundial con grandes aspiraci\u00f3n de convertirse en leyenda.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"340\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-1-la-prensa.jpg\" alt=\"\" class=\"wp-image-11578\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-1-la-prensa.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-1-la-prensa-300x150.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption><strong>FUENTE: <\/strong>La prensa<\/figcaption><\/figure><\/div>\n\n\n\n<p>&nbsp;\u201cThriller\u201d pertenece al \u00e1lbum del mismo nombre que fue lanzado el 30 de noviembre de 1982, un a\u00f1o antes que el videoclip. Este \u00e1lbum de por s\u00ed ya ten\u00eda una fuerte aceptaci\u00f3n de los fan\u00e1ticos, pues contaba con la participaci\u00f3n de Paul McCartney en su primer sencillo titulado <strong><a href=\"https:\/\/www.youtube.com\/watch?v=8GB9BULxZ8c\" class=\"ek-link\">\u201cThe girl is mine\u201d<\/a><\/strong><em> <\/em>la cual fue escrita por el mismo Michael y cantada a d\u00fao con este personaje. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-4-rtv.es_.jpg\" alt=\"\" class=\"wp-image-11583\" width=\"281\" height=\"158\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-4-rtv.es_.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-4-rtv.es_-300x169.jpg 300w\" sizes=\"(max-width: 281px) 100vw, 281px\" \/><figcaption><strong>FUENTE: <\/strong>RTV<\/figcaption><\/figure><\/div>\n\n\n\n<p>La producci\u00f3n del video fue rechaza por la <strong>Sonic Music,<\/strong><em> <\/em>debido al alto presupuesto que requer\u00eda su realizaci\u00f3n, por lo que, John Landis, fue quien tom\u00f3 el trabajo de la direcci\u00f3n de este proyecto que se trasform\u00f3 en un icono de la cultura pop de los 80\u2019, cambiando el concepto del video musical al que estaban acostumbrados la mayor\u00eda, pues buscaba contar una historia completa que le diera un sentido al tema musical en un formato de cortometraje y as\u00ed superar el impacto de su \u00e1lbum anterior lanzado en 1979 titulado <strong><a href=\"https:\/\/www.youtube.com\/watch?v=ZorRGrDiMsA&amp;list=PLiBDZv9jRpwP39yKAYUvSzhvj_6ditNwx\" class=\"ek-link\">\u201cOff the Wall\u201d<\/a><\/strong> al que llamar\u00f3n el \u00e1lbum mas vendido por un artista negro en 1981.<\/p>\n\n\n\n<p>Por otro lado, tambi\u00e9n hab\u00eda recibido una negativa por parte de la revista Rolling\nStone en 1980, cuando pregunto que si estar\u00edan interesados en realizar un\nreportaje sobre \u00e9l y su m\u00fasica, por lo que se propuso revolucionar la industria\nmusical con el fin de demostrar todo su talento y su poder musical. La producci\u00f3n\ndel video contemplo la importancia de la coreograf\u00eda, el vestuario, maquillaje\ny por supuesto la m\u00fasica para la creaci\u00f3n de una pieza que fuera comercial y que\nrompiera esquemas en cuanto sea lanzado, por lo que, no escatimo en gasto\nllegando a costar cerca de un mill\u00f3n de d\u00f3lares en total. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-3-la-tercera.jpg\" alt=\"\" class=\"wp-image-11581\" width=\"251\" height=\"169\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-3-la-tercera.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-3-la-tercera-300x203.jpg 300w\" sizes=\"(max-width: 251px) 100vw, 251px\" \/><figcaption><strong>FUENTE: <\/strong>La tercera<\/figcaption><\/figure><\/div>\n\n\n\n<p>EL video tambi\u00e9n cont\u00f3 con la primera interacci\u00f3n del cantante con una\nmujer dentro de uno de sus videos, pues hasta entonces no hab\u00eda demostrado inter\u00e9s\nen realizar algo parecido, as\u00ed mismo cont\u00f3 con la participaci\u00f3n especial de\nVincent Price como el narrador, quien fue invitado por Quincy Jones, la participaci\u00f3n\ndel actor fue tan r\u00e1pido que logro terminar sus grabaci\u00f3n en solo dos tomas. &nbsp;<\/p>\n\n\n\n<p>Uno de los factores que ayudo a la emisi\u00f3n masiva del video fue MTV que se hab\u00eda creado poco antes de tal hecho bajo el formato de emisi\u00f3n constante de videos musicales durante 24 horas diariamente, por lo que, se dice que hubo una ayuda mutua entre estos, MTV impulso a \u201cThriller\u201d y Michael impulso a la MTV pues se lleg\u00f3 a presentar el video dos veces al d\u00eda en este canal.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-2-peru-21.jpg\" alt=\"\" class=\"wp-image-11608\" width=\"254\" height=\"143\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-2-peru-21.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/michael-2-peru-21-300x170.jpg 300w\" sizes=\"(max-width: 254px) 100vw, 254px\" \/><figcaption><strong>FUENTE: <\/strong> Per\u00fa21<\/figcaption><\/figure><\/div>\n\n\n\n<p>En el a\u00f1o 2009 el congreso Nacional de los Estados Unidos proclam\u00f3 como\npatrimonio hist\u00f3rico el videoclip \u201cthriller\u201d , tambi\u00e9n fue considerado como un\nproducto cultural, hist\u00f3rico y est\u00e9ticamente significativo siendo incluido en\nel Registro Nacional del cine de Estados Unidos contribuyendo a su cultura\npopular.<\/p>\n\n\n\n<p><strong>Dato curioso:<\/strong> Existe una versi\u00f3n india de este famoso videoclip, titulado <strong><a href=\"https:\/\/www.youtube.com\/watch?v=A2tOlfLEHZI\" class=\"ek-link\">\u201cGolimar\u201d<\/a><\/strong>, donde tanto el vestuario, el maquillaje as\u00ed como la escenograf\u00eda son muy parecida a \u201cThriller\u201d y que los fans han tomado como un agasajo al Rey del pop. Esta pieza forma parte de la pel\u00edcula \u201cDonga\u201d de origen Hind\u00fa. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un 2 de diciembre de hace 38 a\u00f1os, el mundo se dej\u00f3 conquistar por un video musical de 14 minutos, del denominado Rey del Pop, Michael Jackson, quien entreg\u00f3 al mundo a \u201cThriller\u201d una de las piezas m\u00e1s ic\u00f3nicas de la historia musical, pieza que adem\u00e1s, afirmo su poder en la industria posicion\u00e1ndose como un [&hellip;]<\/p>\n","protected":false},"author":226,"featured_media":11588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,549,44,9],"tags":[572,1748,170,1747,1746],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11577"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/226"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=11577"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11577\/revisions"}],"predecessor-version":[{"id":11667,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11577\/revisions\/11667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/11588"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=11577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=11577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=11577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}