{"id":11894,"date":"2021-12-08T13:52:47","date_gmt":"2021-12-08T18:52:47","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=11894"},"modified":"2021-12-08T13:52:50","modified_gmt":"2021-12-08T18:52:50","slug":"chile-entra-la-lista-de-los-paises-que-aprueban-el-matrimonio-igualitario","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/chile-entra-la-lista-de-los-paises-que-aprueban-el-matrimonio-igualitario\/","title":{"rendered":"Chile entra la lista de los pa\u00edses que aprueban el matrimonio igualitario"},"content":{"rendered":"\n<p><strong>Chile se suma a los pa\u00edses a nivel mundial que han aprobado el matrimonio igualitario en su naci\u00f3n. Poco a poco, m\u00e1s pa\u00edses se van sumando a esta nueva disposici\u00f3n legal que otorga mayores derechos a las personas con orientaciones sexuales diferentes a las heterosexuales. Sin embargo, en pa\u00edses como Per\u00fa, a\u00fan no se tiene una iniciativa fuerte entre los parlamentarios para discutir una ley referente a este tema. \u00a0<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/activistas.png\" alt=\"\" class=\"wp-image-11896\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/activistas.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/activistas-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Activistas festejando la aprobaci\u00f3n en el congreso. Fotograf\u00eda: Rodrigo Garrido Reuters <\/figcaption><\/figure>\n\n\n\n<p>El d\u00eda 7 de diciembre del 2021, el congreso de Chile\naprob\u00f3 la legalizaci\u00f3n del matrimonio igualitario en el pa\u00eds, despu\u00e9s de m\u00e1s de\n3 a\u00f1os de haber sido presentado el proyecto por la entonces presidenta Michelle\nBachelet. El actual presidente, Sebasti\u00e1n Pi\u00f1era, mostr\u00f3 su apoyo ante esta\niniciativa e impuls\u00f3 su discusi\u00f3n y aprobaci\u00f3n desde junio de dicho a\u00f1o.\nAnteriormente, dicho pa\u00eds ya reconoc\u00eda la uni\u00f3n civil entre personas del mismo\nsexo; sin embargo, a partir de su aprobaci\u00f3n podr\u00e1n gozar de los mismos\nderechos de los matrimonios heterosexuales, como la adopci\u00f3n de ni\u00f1os. Sin\nduda, esto ha sido un gran avance para la comunidad LGBTIQ+ en el pa\u00eds chileno,\nya que se reconoce su derecho y capacidad para formar una familia sin importar\nsu sexo, a pesar de posturas conservadoras no logran aceptar dichas relaciones.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" loading=\"lazy\" width=\"318\" height=\"327\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Novias.png\" alt=\"\" class=\"wp-image-11897\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Novias.png 318w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Novias-292x300.png 292w\" sizes=\"(max-width: 318px) 100vw, 318px\" \/><figcaption>Fuente:  Ovejarosa<\/figcaption><\/figure><\/div>\n\n\n\n<p>Seg\u00fan un <a href=\"https:\/\/ilga.org\/downloads\/ILGA_Mundo_Homofobia_de_Estado_Actualizacion_Panorama_global_Legislacion_diciembre_2020.pdf\">reporte\ndel 2020<\/a> de la Asociaci\u00f3n Internacional de Lesbianas, Gays, Bisexuales,\nTrans e Intersex, el matrimonio igualitario est\u00e1 aprobado en 28 de 193 estados\nmiembros de la ONU, adem\u00e1s de 30 territorios no independientes y una naci\u00f3n no\nafiliada a la organizaci\u00f3n. Tambi\u00e9n, se observa en el reporte que el continente\ncon mayor cantidad de pa\u00edses donde se est\u00e1 legalizado el matrimonio entre el\nmismo sexo es Europa, con 16 de los4 8 pa\u00edses en total, entre ellos Alemania,\nB\u00e9lgica, Espa\u00f1a, Francia, Reino Unido, entre otros. Caso opuesto es el de Asia,\ndonde hasta el 2021 casi ning\u00fan pa\u00eds tiene una ley para oficiar y legalizar estos\nmatrimonios en el territorio, solo en Taiw\u00e1n. Caso similar es el de \u00c1frica, con\nsolo Sud\u00e1frica y 4 naciones anexadas a otras, como Francia o Reino Unido.<\/p>\n\n\n\n<p>En Am\u00e9rica, son 9 pa\u00edses en total con la aprobaci\u00f3n del\nmatrimonio igualitario. Reci\u00e9n en el 2020, Costa Rica se convirti\u00f3 en el primer\npa\u00eds independiente en Centroam\u00e9rica en legalizarlo, ya que otros pa\u00edses\nanexados a territorios como Estados Unidos o Francia tambi\u00e9n aprobaron la uni\u00f3n.\nEn Norteam\u00e9rica, Canad\u00e1 y Estados Unidos ya es legal en todos sus estados. En M\u00e9xico,\n19 de sus estados ya adoptaron esta ley, aunque no existe una generalizada para\ntoda la naci\u00f3n. En Sudam\u00e9rica, en el 2010, Argentina fue el primer pa\u00eds en esta\nregi\u00f3n en legalizaci\u00f3n del matrimonio igualitario en su territorio. Posteriormente,\nle sigui\u00f3 Uruguay, Brasil, Colombia y Ecuador. Actualmente, se lo suma a la\nlista a Chile, como un nuevo pa\u00eds en aprobar dicha ley en el a\u00f1o 2021.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Per\u00fa.png\" alt=\"\" class=\"wp-image-11899\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Per\u00fa.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Per\u00fa-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente:  Gesti\u00f3n.<\/figcaption><\/figure>\n\n\n\n<p>\u00bfPor qu\u00e9 hasta el momento no se aprueba el matrimonio\nigualitario en el Per\u00fa? Se puede iniciar recordando que quienes aprueban y\nrechazan las leyes en nuestro pa\u00eds es el congreso, por lo que si hasta ahora no\nse ha aprobado dicha iniciativa es por la negaci\u00f3n mayoritaria de los\nparlamentarios. Sin embargo, el congreso solo es la representaci\u00f3n de la\nrealidad peruana con respecto a la homosexualidad. Seg\u00fan <a href=\"https:\/\/www.ipsos.com\/sites\/default\/files\/ct\/news\/documents\/2021-06\/D\u00eda%20del%20orgullo-%20Junio%202021.pdf\">un\nreporte de IPSOS<\/a> por el \u201cD\u00eda del orgullo\u201d en el 2021, el 59% de peruanos\na\u00fan est\u00e1n en contra de la uni\u00f3n civil de las personas del mismo sexo y el 64%\nen que estos matrimonios puedan adoptar ni\u00f1os. Esto se refleja en los\nestereotipos existentes entre la poblaci\u00f3n, como el creer que \u201ces peligroso\ndejar a un\/una ni\u00f1o\/a con un homosexual\u201d, que \u201cel VIH &#8211; SIDA es una enfermedad\nde homosexuales y persona trans\u201d o que \u201cla homosexualidad es una enfermedad\u201d.\nHasta que estos pensamientos y creencias no desaparezcan de gran parte de la\npoblaci\u00f3n, estaremos lejos de tener leyes m\u00e1s igualitarias.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" loading=\"lazy\" width=\"355\" height=\"264\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/hombres.png\" alt=\"\" class=\"wp-image-11900\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/hombres.png 355w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/hombres-300x223.png 300w\" sizes=\"(max-width: 355px) 100vw, 355px\" \/><figcaption>Fuente: Alba<\/figcaption><\/figure><\/div>\n\n\n\n<p>Pero \u00bfpor qu\u00e9 es importante el matrimonio igualitario\ny su aprobaci\u00f3n a nivel mundial? El matrimonio como instrumento legal otorga\nderechos y prestaciones a la pareja y a la familia que no se otorgan en otro\ntipo de relaci\u00f3n jur\u00eddica, como el derecho a la reproducci\u00f3n asistida como\npareja, los derechos alimentarios sin condicionamientos, seguridad sobre los\nbienes familiares y derechos hereditarios directos. Es decisi\u00f3n de cada persona\npoder acceder a estos derechos por libre elecci\u00f3n; sin embargo, impedirlo por la\norientaci\u00f3n sexual es solo una forma de discriminaci\u00f3n y atentado a los derechos\nhumanos, m\u00e1s a\u00fan cuando solo se mantiene una postura contraria solo con bases\nculturales, religiosos o hist\u00f3ricos. Por ello, es necesario poner en discusi\u00f3n\nentre las autoridades sobre este tema y que m\u00e1s pa\u00edses se unan a esta medida. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chile se suma a los pa\u00edses a nivel mundial que han aprobado el matrimonio igualitario en su naci\u00f3n. Poco a poco, m\u00e1s pa\u00edses se van sumando a esta nueva disposici\u00f3n legal que otorga mayores derechos a las personas con orientaciones sexuales diferentes a las heterosexuales. Sin embargo, en pa\u00edses como Per\u00fa, a\u00fan no se tiene [&hellip;]<\/p>\n","protected":false},"author":205,"featured_media":11895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[331,33],"tags":[419,406,1779,66],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11894"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/205"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=11894"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11894\/revisions"}],"predecessor-version":[{"id":11901,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11894\/revisions\/11901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/11895"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=11894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=11894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=11894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}