{"id":11919,"date":"2021-12-08T19:31:24","date_gmt":"2021-12-09T00:31:24","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=11919"},"modified":"2021-12-08T19:35:32","modified_gmt":"2021-12-09T00:35:32","slug":"que-es-aew-y-porque-esta-revolucionando-la-industria-de-la-lucha-libre","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/que-es-aew-y-porque-esta-revolucionando-la-industria-de-la-lucha-libre\/","title":{"rendered":"\u00bfQu\u00e9 es AEW, y porque est\u00e1 revolucionando la industria de la lucha libre?"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"506\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/aew-especial.jpg\" alt=\"\" class=\"wp-image-11930\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/aew-especial.jpg 900w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/aew-especial-300x169.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/aew-especial-768x432.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption>Fuente: Milenio<\/figcaption><\/figure>\n\n\n\n<p>El wrestling (lucha libre), es un deporte de contacto predeterminado y armado de antemano, esto quiere decir que no es un deporte con una competencia real, y tampoco trata de serlo. El wrestling y sus participantes (los wrestler o los luchadores profesionales) tienen como fin en s\u00ed cautivar a la audiencia mediante el desarrollo de encuentros entre luchadores, sus rivalidades y las historias que pueden contar dentro del cuadril\u00e1tero.&nbsp;<\/p>\n\n\n\n<p>El fin de la lucha libre no es la deportividad y la competencia leal, sino que se trata de mera teatralidad que se puede ver como una forma de arte, puesto que su desarrollo puede inspirar el esp\u00edritu competitivo de querer motivar y despertar emociones en la audiencia. El wrestling es un tipo de espect\u00e1culo \u00fanico en su clase, puesto que aunque se sabe que estos wrestlers no \u201cluchan\u201d de verdad, lo que s\u00ed es real e innegable es que la audiencia y sus seguidores lo sienten real.&nbsp;<\/p>\n\n\n\n<p>Durante m\u00e1s de dos d\u00e9cadas, desde el fin de las tan famosas \u201cMonday Night Wars\u201d de la d\u00e9cada de los 90, con el cierre definitivo de la empresa WCW y su compra por parte de la entonces WWF all\u00e1 por el a\u00f1o 2001, el estigma de la lucha libre occidental recay\u00f3 en un monopolio de la \u00fanica empresa Mainstream en lo que a lucha libre se refiere. La WWF pas\u00f3 a ser la WWE, y con ello vino su posterior proyecto de globalizar la industria de la lucha libre, incluso en donde el wrestling es considerado un deporte tradicional.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/MNW.jpg\" alt=\"\" class=\"wp-image-11931\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/MNW.jpg 800w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/MNW-300x169.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/MNW-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Fuente: Sportskeeda<\/figcaption><\/figure>\n\n\n\n<p>Por alrededor de 20 a\u00f1os se consumi\u00f3 a nivel global, mayoritariamente en occidente, un producto de lucha libre con una visi\u00f3n \u00fanica del c\u00f3mo deb\u00eda hacerse. Se implant\u00f3 la idea de que solo exist\u00eda una forma de ver este deporte espect\u00e1culo y que todo lo dem\u00e1s simplemente era errado, se cre\u00f3 una burbuja de entretenimiento donde nada aparte de WWE existiera.<\/p>\n\n\n\n<p>A medida que los a\u00f1os pasaban, era mucho m\u00e1s notorio que la empresa l\u00edder de la industria abandonaba el estigma que durante mucho tiempo era parte de su esencia, abandonaron los c\u00e1nones del wrestling para simplemente llamarse entretenimiento deportivo. Trataron de alejarse lo m\u00e1s que pudieran de la industria para diferenciarse, a pesar de que es la esencia de este deporte.&nbsp;<\/p>\n\n\n\n<p>El entretenimiento deportivo disfrazado de wrestling gobern\u00f3 durante dos d\u00e9cadas y educando a una audiencia y la vista general que se ten\u00eda del wrestling. Ya no se lo conoc\u00eda como un deporte espect\u00e1culo, sino como mero entretenimiento que cada vez volv\u00eda mon\u00f3tono la lucha libre. Sin embargo, todo eso cambi\u00f3 el 1 de enero del a\u00f1o 2019 con el anuncio de una nueva empresa que cambiar\u00eda el estigma del wrestling norteamericano y la visi\u00f3n occidental que se ten\u00eda de la lucha libre.&nbsp;<\/p>\n\n\n\n<p>ALL ELITE WRESTLING (AEW) fue fundada por el empresario Tony Khan con una importante inversi\u00f3n de su padre, Shahid Khan, su sede de operaciones se encuentra en Jacksonville -Florida . Para comenzar su proyecto, Khan decidi\u00f3 contratar a las ex estrellas de la compa\u00f1\u00eda WWE como Chris Jericho y Cody Rhodes en 2018, solo necesitaba decenas de millones de d\u00f3lares.<\/p>\n\n\n\n<p>Con talentos bien reconocidos a nivel mundial por los fan\u00e1ticos de la lucha libre, incluido el legendario ex comentarista de la WWE Jim Ross, AEW comenz\u00f3 con su primer \u00abpago por visi\u00f3n\u00bb, Double or Nothing. agotando todas las entradas. El espect\u00e1culo tuvo lugar en Las Vegas en mayo de 2019. Y el 2 de octubre de 2019, TNT le dio el visto bueno al programa semanal AEW Dynamite y tambi\u00e9n a su m\u00e1s reciente show, AEW Rampage.&nbsp;<\/p>\n\n\n\n<p>El nacimiento de esta empresa les dio a los fan\u00e1ticos de la&nbsp; lucha libre una alternativa de la ya saturada WWE. Por primera vez existe una segunda empresa Mainstream de lucha libre que rompe los esquemas establecidos por los tantos a\u00f1os del monopolio de WWE.<br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"855\" height=\"570\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Moxley-vs.-Omega-Full-Gear.jpeg\" alt=\"\" class=\"wp-image-11932\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Moxley-vs.-Omega-Full-Gear.jpeg 855w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Moxley-vs.-Omega-Full-Gear-300x200.jpeg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Moxley-vs.-Omega-Full-Gear-768x512.jpeg 768w\" sizes=\"(max-width: 855px) 100vw, 855px\" \/><figcaption>Fuente: Turn Heel Wrestling<\/figcaption><\/figure>\n\n\n\n<p> AEW no solo cuenta con un sustento econ\u00f3mico estable, sino que se permite el poder contratar algunos de los m\u00e1s grandes nombres y leyendas de la industria y tenerlos en sus filas. Algunos como CM Punk, Kenny Omega, Bryan Danielson, Adam Cole, Sting, etc. No solo ello, sino que tambi\u00e9n son formadores de sus propios talentos y los desarrollan para ser futuras estrellas de la compa\u00f1\u00eda y de la industria en general, tales como: Darby Allin, MJF, Sammy Guevara, Adam Page,&nbsp; Jungle Boy, Britt Baker, Tay Conti, entre otras estrellas. <\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"CM Punk Speaks for the First Time Ever in AEW | AEW Rampage: The First Dance, 8\/20\/21\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/KrZXDqREmaU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>Fuente: All Elite Wrestling<\/figcaption><\/figure>\n\n\n\n<p>No solo se le puede considerar alternativa a AEW a lo que convencionalmente presenta WWE por sus luchadores que tienen, sino que tambi\u00e9n ofrecen productos muy distintos para sus fans, por no decir que son opuestos. AEW se diferencia de WWE en producto y en filosof\u00eda, mientras que WWE rechaza todo lo que est\u00e1 fuera de ellos, AEW abraza la historia, y realiza colaboraciones con otras compa\u00f1\u00edas&nbsp; de lucha libre en territorio estadounidense y fuera de ella. Algunos ejemplos de estas alianzas son con GCW, Impact Wrestling, NWA, Triple A, NJPW, TJPW, etc.&nbsp;<\/p>\n\n\n\n<p>Esta nueva perspectiva result\u00f3 ser atractiva para los fan\u00e1ticos, adicionando no solo los grandes nombres o las alianzas que AEW ha formado, sus luchas hablan por s\u00ed solas tambi\u00e9n, poseen una calidad de luchas est\u00e1ndar de nivel muy alto, por lo que sus shows casi nunca decepcionan. Esto cambi\u00f3 las reglas del juego, cambi\u00f3 la perspectiva de los fan\u00e1ticos, as\u00ed como tambi\u00e9n rompi\u00f3 la burbuja dibujada por el l\u00edder de la industria. Sigue estando muy lejos de WWE econ\u00f3micamente as\u00ed como a nivel de popularidad, sin embargo, AEW no ha hecho m\u00e1s que crecer y perfeccionar su producto cada vez m\u00e1s, el futuro de esta empresa es brillante.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Kenny-Omega-vs-Bryan-Danielson_2021-09-22-AEW-Dynamite-460-1024x683.jpg\" alt=\"\" class=\"wp-image-11934\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Kenny-Omega-vs-Bryan-Danielson_2021-09-22-AEW-Dynamite-460-1024x683.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Kenny-Omega-vs-Bryan-Danielson_2021-09-22-AEW-Dynamite-460-300x200.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Kenny-Omega-vs-Bryan-Danielson_2021-09-22-AEW-Dynamite-460-768x512.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Kenny-Omega-vs-Bryan-Danielson_2021-09-22-AEW-Dynamite-460.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Fuente: Fanbyte.com<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El wrestling (lucha libre), es un deporte de contacto predeterminado y armado de antemano, esto quiere decir que no es un deporte con una competencia real, y tampoco trata de serlo. El wrestling y sus participantes (los wrestler o los luchadores profesionales) tienen como fin en s\u00ed cautivar a la audiencia mediante el desarrollo de [&hellip;]<\/p>\n","protected":false},"author":251,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[44,1],"tags":[],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11919"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/251"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=11919"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11919\/revisions"}],"predecessor-version":[{"id":11937,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/11919\/revisions\/11937"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=11919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=11919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=11919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}