{"id":12065,"date":"2021-12-09T19:25:41","date_gmt":"2021-12-10T00:25:41","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=12065"},"modified":"2021-12-09T19:25:44","modified_gmt":"2021-12-10T00:25:44","slug":"pelicula-navidena-el-chico-que-salvo-la-navidad","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/pelicula-navidena-el-chico-que-salvo-la-navidad\/","title":{"rendered":"Pel\u00edcula navide\u00f1a: \u201cEl chico que salv\u00f3 la Navidad\u201d"},"content":{"rendered":"\n<p>El 24 de noviembre, la plataforma de streaming Netflix estren\u00f3 la pel\u00edcula navide\u00f1a \u201cEl chico que salv\u00f3 la Navidad\u201d para consumo en estas \u00e9pocas de estar en casa y con la familia. Esta pel\u00edcula cuenta con las actuaciones de Henry Lawfull, Toby Jones, Sally Hawkins, Kristen Wiig, Michiel Huisman, Zoe Colletti, Stephen Merchant, Jim Broadbent y Maggie Smith.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"630\" height=\"354\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/cast.jpg\" alt=\"\" class=\"wp-image-12073\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/cast.jpg 630w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/cast-300x169.jpg 300w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><figcaption>Fuente: Sky.com<\/figcaption><\/figure>\n\n\n\n<p>Esta pel\u00edcula comienza con la llegada de la t\u00eda Ruth en la v\u00edspera de Navidad. Ella fue a cuidar a los ni\u00f1os mientras el padre no estaba. Poco a poco se revela que la madre de estos hab\u00eda fallecido y los peque\u00f1os a\u00fan no lo superaban. Mientras esperan al padre, la t\u00eda Ruth decide contarles un cuento para distraerlos.<\/p>\n\n\n\n<p>El cuento trata sobre un ni\u00f1o com\u00fan y corriente llamado Nikolas, que emprende una extraordinaria aventura para encontrar a su padre, quien est\u00e1 en una b\u00fasqueda para descubrir el legendario pueblo de los elfos, Elfhelm. Nikolas es acompa\u00f1ado por su fiel rat\u00f3n mascota y un reno que encontr\u00f3 en el camino, pronto llega a su destino en esta historia m\u00e1gica, c\u00f3mica y entra\u00f1able que demuestra que nada es imposible.&nbsp;<\/p>\n\n\n\n<p>Nikolas segu\u00eda el mapa pero solo encontraba cada vez m\u00e1s nieve, por lo que perdi\u00f3 la esperanza y se dej\u00f3 conquistar por el fr\u00edo. Sin embargo, un elfo y su tataranieta lo encontraron a tiempo, lo rescataron y ayudaron a ver que hab\u00eda llegado Elfhelm. Lo llevaron a una fiesta secreta de Navidad y le mostraron lo que lo que alguna vez le cont\u00f3 su madre. Sin embargo, la fiesta no dur\u00f3 mucho ya que apareci\u00f3 la madre Vodar y les record\u00f3 la prohibici\u00f3n de estas celebraciones debido a que ten\u00edan que proteger la aldea de los humanos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"630\" height=\"262\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/elfos-1.jpg\" alt=\"\" class=\"wp-image-12072\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/elfos-1.jpg 630w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/elfos-1-300x125.jpg 300w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><figcaption>Fuente: Netflix<\/figcaption><\/figure>\n\n\n\n<p>\u00c9l trat\u00f3 de explicar que los humanos son amables, pero la Madre Vodal revel\u00f3 que su padre y el resto de humanos secuestraron al peque\u00f1o elfo llamado Kip. Por ello orden\u00f3 su captura y ya en su celda, el ni\u00f1o conoci\u00f3 a un hada de la verdad que lo ayud\u00f3 a escapar. Despu\u00e9s de prometer rescatar a Kip, Nikolas r\u00e1pidamente lo encontr\u00f3 secuestrado, pero no pudo liberarlo porque su padre y compa\u00f1eros lo impidieron. Joel, el padre, orden\u00f3 que lo aten, pero esto era un enga\u00f1o para as\u00ed huir en medio de la noche y ayudar a su hijo. Joel, su hijo, Kip, el rat\u00f3n y el reno, lograron escapar, pero fueron perseguidos por cazadores. Gracias a la magia de Nikolas,el reno Bitzen comenz\u00f3 a volar, pero el peso del trineo le impidi\u00f3 volar por completo, por lo que Joel decidi\u00f3 sacrificarse.<\/p>\n\n\n\n<p>Al regresar a Elfhelm, Nikolas rescat\u00f3 a los elfos que los ayudaron a escapar de la Madre Vodal, y los miembros de la aldea hicieron juguetes y chocolates para llevarlos al rey como s\u00edmbolo de esperanza. Madre Vodar intent\u00f3 detenerlo, pero cuando descubri\u00f3 que Nikolas era el hijo de su amiga humana, lo dej\u00f3 ir.<\/p>\n\n\n\n<p>Aunque el rey le conmovi\u00f3 su acci\u00f3n, no cre\u00eda que fuera realmente m\u00e1gica, por lo que Nikolas lo llev\u00f3 a repartir los obsequios y chocolates a los aldeanos en medio de la noche. Cuando vio la reacci\u00f3n, el rey supo que era una alegr\u00eda para ellos y les brindaba esperanza. Para continuar con esta, el rey le pidi\u00f3 a Nicol\u00e1s que todos los a\u00f1os repartiera regalos, y llamaron a esta celebraci\u00f3n Navidad.&nbsp;<\/p>\n\n\n\n<p>Es as\u00ed como la t\u00eda Ruth termina el cuento, para despu\u00e9s despedirse de los ni\u00f1os. Ante la incredulidad de estos ella, solo se fue y dijo: \u00abYo nunca miento\u00bb como siempre dec\u00eda el hada de la verdad, adem\u00e1s, arroj\u00f3 algo explosivo, demostrando ser ella.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"699\" height=\"299\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/maggie.jpg\" alt=\"\" class=\"wp-image-12069\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/maggie.jpg 699w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/maggie-300x128.jpg 300w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><figcaption>Fuente: Netflix<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El 24 de noviembre, la plataforma de streaming Netflix estren\u00f3 la pel\u00edcula navide\u00f1a \u201cEl chico que salv\u00f3 la Navidad\u201d para consumo en estas \u00e9pocas de estar en casa y con la familia. Esta pel\u00edcula cuenta con las actuaciones de Henry Lawfull, Toby Jones, Sally Hawkins, Kristen Wiig, Michiel Huisman, Zoe Colletti, Stephen Merchant, Jim Broadbent [&hellip;]<\/p>\n","protected":false},"author":236,"featured_media":12070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[549,35,44],"tags":[618,665,845],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12065"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/236"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=12065"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12065\/revisions"}],"predecessor-version":[{"id":12074,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12065\/revisions\/12074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/12070"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=12065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=12065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=12065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}