{"id":12077,"date":"2021-12-09T19:47:36","date_gmt":"2021-12-10T00:47:36","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=12077"},"modified":"2021-12-09T19:48:01","modified_gmt":"2021-12-10T00:48:01","slug":"navidad-2021-2-campanas-solidarias-que-puedes-apoyar","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/navidad-2021-2-campanas-solidarias-que-puedes-apoyar\/","title":{"rendered":"Navidad 2021: 2 campa\u00f1as solidarias que puedes apoyar"},"content":{"rendered":"\n<p>Ya es diciembre y con ello llega la \u00e9poca de fiestas, entre\nellas: Navidad. Esta tradicional celebraci\u00f3n a\u00f1o a a\u00f1o junta a miles de\nfamilias alrededor del mundo y es conocida por representar la uni\u00f3n familiar. No\nobstante, no todos tienen las mismas posibilidades de celebrarla de la misma\nmanera que muchos de nosotros. <\/p>\n\n\n\n<p>Por ello, a tan solo d\u00edas de esta fecha especial, distintas\norganizaciones han buscado la manera de apoyar a quienes lo necesitan. A raz\u00f3n\nde ello, se han organizado campa\u00f1as navide\u00f1as que buscan voluntarios que se\nsumen a intentar llevar alegr\u00eda a trav\u00e9s de donaciones.<\/p>\n\n\n\n<p>A continuaci\u00f3n, te muestro dos de ellas:<\/p>\n\n\n\n<p><strong>Wawayay Per\u00fa: Navidad con nuestros Wawalectores<\/strong><\/p>\n\n\n\n<p>Wawayay Per\u00fa es una Asociaci\u00f3n Civil de derecho privado, de\ncar\u00e1cter social, sin fines de lucro, que brinda asistencia social de manera\ngratuita a ni\u00f1os, ni\u00f1as y adolescentes en situaci\u00f3n de vulnerabilidad a nivel\nnacional.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n2-1024x1024.jpg\" alt=\"\" class=\"wp-image-12080\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n2-1024x1024.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n2-150x150.jpg 150w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n2-300x300.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n2-768x768.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n2-540x540.jpg 540w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n2.jpg 1034w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> Fuente: Facebook Wawayay Per\u00fa <\/figcaption><\/figure>\n\n\n\n<p>En esta oportunidad, su objetivo es reunir juguetes,\ncuentos, \u00fatiles escolares, v\u00edveres para chocolatada, etc. Los beneficiarios\nser\u00e1n 25 ni\u00f1os de Oyot\u00fan \u2013 Chiclayo y 43 ni\u00f1os de Sa\u00f1o &#8211; Huancayo, integrantes\nde su programa Wawalectores. Asimismo, otra forma de ayudar es donando 25 soles,\nprecio de un pack que incluir\u00e1 un regalo, una chocolatada, un cuento, un\nminipanet\u00f3n y una sorpresa.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"379\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n1-1-1024x379.jpg\" alt=\"\" class=\"wp-image-12079\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n1-1-1024x379.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n1-1-300x111.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n1-1-768x284.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> Fuente: Facebook Wawayay Per\u00fa <\/figcaption><\/figure>\n\n\n\n<p>Todos aquellos que quieran apoyar podr\u00e1n hacerlo a trav\u00e9s de Yape (987016951) y Plin (931361626), de la misma forma para m\u00e1s informaci\u00f3n pueden contactar a esos n\u00fameros o seguirlos en Instagram como <a href=\"https:\/\/www.instagram.com\/wawayay_peru\/\" class=\"ek-link\">@wawayay_peru<\/a>.<\/p>\n\n\n\n<p><strong>Pura Voluntad Per\u00fa: 500 Sue\u00f1os de Navidad<\/strong><\/p>\n\n\n\n<p>Pura Voluntad es un movimiento de ayuda social y apoyo voluntario\ncuya misi\u00f3n es conectar a personas en situaciones vulnerables con personas y\nentidades que deseen brindarles ayuda. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n3-1024x1024.jpg\" alt=\"\" class=\"wp-image-12081\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n3-1024x1024.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n3-150x150.jpg 150w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n3-300x300.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n3-768x768.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n3-540x540.jpg 540w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n3.jpg 1726w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> Fuente: Facebook Pura Voluntad <\/figcaption><\/figure>\n\n\n\n<p>En esta oportunidad buscan beneficiar a 500 ni\u00f1os y ancianos\nde 13 lugares distintos: <\/p>\n\n\n\n<ul><li>Casa Ronald McDonald en Surco. <\/li><li>Albergue Frieda Heller <\/li><li>Albergue Aldimi <\/li><li>Albergue Inspira<\/li><li>Casa Hogar San Luis Chorrillos <\/li><li>PRONOEI Estrellita de Dios en Cieneguilla<\/li><li>La Escuelita de Ca\u00f1ete en el AAHH Ar\u00edstide\nMerloni <\/li><li>Proyecto Quijote para la Vida en AAHH Santa\nRosa en Puente Piedra<\/li><li>Casa Hogar Talita Kum <\/li><li>Centro de Madres adolescentes Villa Vida <\/li><li>Casa Hogar Virgen del Carmen Chorrillos <\/li><li>Casa Hogar para adultos mayores Villa Marina <\/li><li>Casa Hogar para ni\u00f1os con VIH \u201cUn d\u00eda de\nesperanza\u201d<\/li><\/ul>\n\n\n\n<p>A trav\u00e9s de la donaci\u00f3n de 50 soles se armar\u00e1n packs que\nconstar\u00e1n de un regalo, un compartir y un pack de aseo personal (cepillo dental,\npasta dental, jab\u00f3n de tocador, shampoo, desodorante y mascarilla). A su vez,\nse puede ayudar participando en los compartires, haci\u00e9ndoles llegar los\nproductos o insumos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n4-1024x576.jpg\" alt=\"\" class=\"wp-image-12082\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n4-1024x576.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n4-300x169.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n4-768x432.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n4.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> Fuente: Facebook Pura Voluntad <\/figcaption><\/figure>\n\n\n\n<p>Las donaciones se har\u00e1n a trav\u00e9s de los siguientes canales:\n<\/p>\n\n\n\n<p>Yape\/ Plin: 989140528 o BBVA: 001108140219144070 CCI:\n01181400021914407016<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n pueden contactar con el n\u00famero 989140528 o en redes sociales como <a href=\"https:\/\/www.instagram.com\/puravoluntadperu\/\" class=\"ek-link\">@puravoluntadperu<\/a>. <\/p>\n\n\n\n<p><strong>\u00bfOtras opciones?<\/strong><\/p>\n\n\n\n<p>Si deseas buscar otras alternativas puedes entrar a la p\u00e1gina web de <a href=\"https:\/\/proa.pe\/\" class=\"ek-link\">PROA<\/a>, plataforma peruana que conecta donadores o voluntarios con organizaciones solidarias que necesitan de su ayuda.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/N6-1024x1024.jpg\" alt=\"\" class=\"wp-image-12084\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/N6-1024x1024.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/N6-150x150.jpg 150w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/N6-300x300.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/N6-768x768.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/N6-540x540.jpg 540w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/N6.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> Fuente: Facebook PROA <\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"502\" height=\"264\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n5.jpg\" alt=\"\" class=\"wp-image-12083\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n5.jpg 502w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/n5-300x158.jpg 300w\" sizes=\"(max-width: 502px) 100vw, 502px\" \/><figcaption>Fuente: Facebook PROA<\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ya es diciembre y con ello llega la \u00e9poca de fiestas, entre ellas: Navidad. Esta tradicional celebraci\u00f3n a\u00f1o a a\u00f1o junta a miles de familias alrededor del mundo y es conocida por representar la uni\u00f3n familiar. No obstante, no todos tienen las mismas posibilidades de celebrarla de la misma manera que muchos de nosotros. Por [&hellip;]<\/p>\n","protected":false},"author":216,"featured_media":12085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[359],"tags":[1421,618,1800],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12077"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/216"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=12077"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12077\/revisions"}],"predecessor-version":[{"id":12086,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12077\/revisions\/12086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/12085"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=12077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=12077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=12077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}