{"id":12325,"date":"2021-12-15T19:01:50","date_gmt":"2021-12-16T00:01:50","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=12325"},"modified":"2021-12-15T19:01:54","modified_gmt":"2021-12-16T00:01:54","slug":"yma-sumac-la-princesa-inca-de-los-50-s","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/yma-sumac-la-princesa-inca-de-los-50-s\/","title":{"rendered":"Yma Sumac: La princesa Inca de los 50\u2019 s"},"content":{"rendered":"\n<p>Una de las figuras m\u00e1s representativas que tuvo el Per\u00fa durante la d\u00e9cada de los a\u00f1os 50 fue Zoila Augusta Emperatriz Ch\u00e1varri del Castillo, mejor conocida como <em>Yma Sumac<\/em>. Fue una soprano excepcional e inusual que el mundo presenci\u00f3, ya que era la \u00fanica que pod\u00eda realizar la triple coloratura, es decir, dominaba la t\u00e9cnica que replicaba el trino de las aves. Considerada como una diva, estuvo presente en diversos musicales de Broadway y tuvo presencia en el cine junto a Charlton Heston. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-revista-life-ok.png\" alt=\"\" class=\"wp-image-12327\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-revista-life-ok.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-revista-life-ok-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: Revista Life.<\/figcaption><\/figure>\n\n\n\n<p>Nacida en Ichocan, Cajamarca, desde peque\u00f1a demostr\u00f3 dotes para el canto y aprendi\u00f3 de los mejores maestros: las aves. Conforme creci\u00f3 se mud\u00f3 con sus padres a la regi\u00f3n del Callao, donde comenzar\u00eda su vida art\u00edstica. Mois\u00e9s Vivanco, su ex-esposo, la reclut\u00f3 y la hizo parte de la Compa\u00f1\u00eda de Artes de Mois\u00e9s Vivanco, como voz principal. Tuvo tanto \u00e9xito que su internacionalizaci\u00f3n comenz\u00f3 al participar en una radio argentina. Este paso para <em>Yma Sumac<\/em> solo fue el inicio de su estrellato y el camino para ser considerada como una diva, que estuvo presente como la primera mujer latinoamericana en formar parte del elenco musical de Broadway. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-pinterest-ok.jpg\" alt=\"\" class=\"wp-image-12328\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-pinterest-ok.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-pinterest-ok-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: Gettyimages.<\/figcaption><\/figure>\n\n\n\n<p>El ser la \u00fanica peruana que tiene una estrella en el Paseo de la Fama de Hollywood, ha hecho que se la reconozca por su trayectoria y su contribuci\u00f3n a la industria musical. <em>Yma Sumac<\/em> no solo cautiv\u00f3 con su voz, sino tambi\u00e9n lo hizo con la fusi\u00f3n musical. Mezcl\u00f3 m\u00fasica folkl\u00f3rica con ritmos como el jazz, mambo y rock, ya que no deseaba que las canciones sean mon\u00f3tonas. El realizar esta mezcla era una forma de \u201censalzar la canci\u00f3n\u201d, sin embargo, las cr\u00edticas de puristas musicales no eran ajenas a ello. Pero, ello no la detuvo para seguir con su carrera. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-gettyimages-961815658-612x612-ok.png\" alt=\"\" class=\"wp-image-12331\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-gettyimages-961815658-612x612-ok.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-gettyimages-961815658-612x612-ok-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: Gettyimages.<\/figcaption><\/figure>\n\n\n\n<p><em>Yma Sumac<\/em> no solo dej\u00f3 un legado art\u00edstico, sino tambi\u00e9n dej\u00f3 un legado cultural. Ello se presencia a trav\u00e9s de sus canciones e interpretaciones en los escenarios. El uso de vestimentas y el lenguaje quechua hizo que se revalorara a nivel mundial la cultura incaica durante los a\u00f1os 50 &#8216;s. Es as\u00ed que gracias a su talento, recorri\u00f3 diversos pa\u00edses del mundo bajo el apelativo de \u201cLa \u00faltima princesa Inca\u201d. Lleg\u00f3 al Medio y Lejano Oriente, inclusive recibi\u00f3 una invitaci\u00f3n a la ex &#8211; Uni\u00f3n Sovi\u00e9tica por dos semanas, del propio presidente del Consejo de Ministros de la URSS, Nikita Jrushchov. Pero fue tanto el recibimiento que permaneci\u00f3 en la URSS durante seis meses, dando conciertos en toda la naci\u00f3n sovi\u00e9tica. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-sumac-Russia-Beyond-ES-ok.png\" alt=\"\" class=\"wp-image-12329\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-sumac-Russia-Beyond-ES-ok.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-sumac-Russia-Beyond-ES-ok-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: Russia Beyond ES.<\/figcaption><\/figure>\n\n\n\n<p>Al ser una persona famosa durante la \u00e9poca de los 50 &#8216;s, no todo fue perfecto. Esc\u00e1ndalos y problemas sobre su nacionalidad la colocaron en el ojo de la tormenta, y ello afect\u00f3 su carrera art\u00edstica, de la cual pudo recuperarse tiempo despu\u00e9s. Medios y personajes del entretenimiento de aquel entonces, la reconoc\u00edan, entrevistaron y elaboraron documentales sobre aquel talento que es inusual ver y que cada cien a\u00f1os aparece. <\/p>\n\n\n\n<p>Cabe se\u00f1alar, que no solo hizo un gran aporte a la industria musical, sino tambi\u00e9n revaloriz\u00f3 la cultura y dio mayor visibilidad a la lengua quechua, ya que en aquella \u00e9poca, el pa\u00eds era desconocido y merec\u00eda ser visto. Gracias a su talento \u201csobrehumano\u201d, como la catalogan muchos expertos, hizo que el Per\u00fa sea mundialmente conocido colocando al pa\u00eds en los ojos del mundo, especialmente a Machu Picchu. Por lo que hasta la actualidad se la considera una leyenda e inspiraci\u00f3n para diversos artistas. Sin duda una importante embajadora cultural del Per\u00fa e iniciadora de la fusi\u00f3n musical durante los a\u00f1os 50\u2019 s.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-Radi\u00f3nica-ok.png\" alt=\"\" class=\"wp-image-12330\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-Radi\u00f3nica-ok.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Yma-Sumac-Radi\u00f3nica-ok-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: Radi\u00f3nica.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Una de las figuras m\u00e1s representativas que tuvo el Per\u00fa durante la d\u00e9cada de los a\u00f1os 50 fue Zoila Augusta Emperatriz Ch\u00e1varri del Castillo, mejor conocida como Yma Sumac. Fue una soprano excepcional e inusual que el mundo presenci\u00f3, ya que era la \u00fanica que pod\u00eda realizar la triple coloratura, es decir, dominaba la t\u00e9cnica [&hellip;]<\/p>\n","protected":false},"author":233,"featured_media":12332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,444,555],"tags":[1386,81,170,1834],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12325"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/233"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=12325"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12325\/revisions"}],"predecessor-version":[{"id":12337,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12325\/revisions\/12337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/12332"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=12325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=12325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=12325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}