{"id":12353,"date":"2021-12-15T23:30:39","date_gmt":"2021-12-16T04:30:39","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=12353"},"modified":"2021-12-15T23:31:55","modified_gmt":"2021-12-16T04:31:55","slug":"ceramica-del-pueblo-peruano-awajun-es-declarado-patrimonio-cultural-inmaterial-de-la-humanidad-por-la-unesco","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/ceramica-del-pueblo-peruano-awajun-es-declarado-patrimonio-cultural-inmaterial-de-la-humanidad-por-la-unesco\/","title":{"rendered":"Cer\u00e1mica del pueblo peruano Awaj\u00fan es declarado Patrimonio Cultural Inmaterial de la Humanidad por la Unesco"},"content":{"rendered":"\n<p> El <a href=\"https:\/\/bdpi.cultura.gob.pe\/pueblos\/awajun\">pueblo Awaj\u00fan<\/a>, tambi\u00e9n conocido como Aguaruna, es el segundo m\u00e1s numeroso de la Amazon\u00eda peruana. Esta comunidad amaz\u00f3nica, como muchas otras, se caracteriza por su compromiso con la defensa de su territorio ancestral, el cual es representado en sus actividades, por ejemplo la producci\u00f3n alfarera. Esta pr\u00e1ctica milenaria desempe\u00f1a una funci\u00f3n social importante, ya que representa parte de su relaci\u00f3n con la naturaleza a trav\u00e9s de dibujos geom\u00e9tricos inspirados en elementos naturales. Adem\u00e1s, ofrece la posibilidad de empoderamiento y progreso de su poblaci\u00f3n. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Gobierno-del-Per\u00fa-1.jpg\" alt=\"\" class=\"wp-image-12357\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Gobierno-del-Per\u00fa-1.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Gobierno-del-Per\u00fa-1-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Cer\u00e1mica Awj\u00fan declarada como Patrimonio Cultural Inmaterial de la Humanidad. | Fuente: Andina<\/figcaption><\/figure>\n\n\n\n<p> La <a href=\"https:\/\/es.unesco.org\/\">Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura (Unesco)<\/a> declar\u00f3 Patrimonio Cultural Inmaterial de la Humanidad a los valores, conocimientos, saberes y pr\u00e1cticas ancestrales del pueblo Awaj\u00fan asociados a la producci\u00f3n de la cer\u00e1mica, poniendo en valor esta expresi\u00f3n art\u00edstica que es transmitida de generaci\u00f3n en generaci\u00f3n en sus comunidades ubicadas en la selva amaz\u00f3nica peruana.  <\/p>\n\n\n\n<p>La declaratoria se dio en el contexto de la d\u00e9cimo sexta reuni\u00f3n del Comit\u00e9 Intergubernamental para\u00a0 la Salvaguardia del Patrimonio Cultural Inmaterial que se celebra del 13 al 18 de diciembre de 2021. Esta noticia fue celebrada por la actual ministra de cultura, Gisela Ortiz, quien destac\u00f3 el talento de las mujeres alfareras awaj\u00fan y su compromiso con el medio ambiente en la elaboraci\u00f3n de sus piezas de cer\u00e1mica.  <\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>\u201cEs un honor tener como representantes de la cultura del pa\u00eds ante el mundo a mujeres ind\u00edgenas que valoran y transmiten valiosos saberes ancestrales, destacando el uso de la lengua awaj\u00fan, veh\u00edculo important\u00edsimo de nuestra memoria y nuestra historia\u201d. <\/p><cite> Declar\u00f3 Ortiz durante su intervenci\u00f3n en la sesi\u00f3n del Comit\u00e9 Intergubernamental para la Salvaguardia del Patrimonio Cultural Inmaterial de la Unesco.  <\/cite><\/blockquote>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Ministerio-de-Cultura-1.jpg\" alt=\"\" class=\"wp-image-12362\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Ministerio-de-Cultura-1.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/12\/Ministerio-de-Cultura-1-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: Ministerio de Cultura<\/figcaption><\/figure>\n\n\n\n<p>Cabe destacar que, a comienzos de 2017 el Estado peruano declar\u00f3 <strong>Patrimonio Cultural de la Naci\u00f3n <\/strong>a la producci\u00f3n de la cer\u00e1mica Awaj\u00fan por su trascendencia art\u00edstica y cultural. M\u00e1s tarde, seg\u00fan informaci\u00f3n del <a href=\"https:\/\/www.gob.pe\/qu\/institucion\/cultura\/noticias\/569966-declaran-patrimonio-cultural-inmaterial-de-la-humanidad-a-la-ceramica-awajun\">Ministerio de Cultura<\/a>, se present\u00f3 un expediente t\u00e9cnico a la sede de Par\u00eds de la Unesco en abril de 2019 el cual ser\u00eda sometido a una rigurosa evaluaci\u00f3n para ser merecedor del reconocimiento como Patrimonio Cultural Inmaterial de la Humanidad en m\u00e9rito a su permanente salvaguardia de estos conocimientos y pr\u00e1cticas que expresan\u00a0 valores, e identidad cultural.<\/p>\n\n\n\n<p>La noticia fue anunciada a trav\u00e9s del Twitter oficial\u00a0 de la Unesco, donde se felicita al Per\u00fa por este nuevo registro y, m\u00e1s tarde, fue compartida por las cuentas oficiales del Ministerio de Cultura.  <\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter aligncenter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83d\udd34 \u00daLTIMA HORA<br>Nueva inscripci\u00f3n en la lista del <a href=\"https:\/\/twitter.com\/hashtag\/PatrimonioInmaterial?src=hash&amp;ref_src=twsrc%5Etfw\">#PatrimonioInmaterial<\/a>: Valores, conocimientos, saberes y pr\u00e1cticas del pueblo awaj\u00fan asociados a la producci\u00f3n de cer\u00e1mica.<br> <br>\ud83d\udc4f \u00a1Felicidades <a href=\"https:\/\/twitter.com\/hashtag\/Per%C3%BA?src=hash&amp;ref_src=twsrc%5Etfw\">#Per\u00fa<\/a> \ud83c\uddf5\ud83c\uddea! \ud83d\udc4f<br> <br>\u2139\ufe0f <a href=\"https:\/\/t.co\/koSUj3gwB6\">https:\/\/t.co\/koSUj3gwB6<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/PatrimonioVivo?src=hash&amp;ref_src=twsrc%5Etfw\">#PatrimonioVivo<\/a> <a href=\"https:\/\/t.co\/TSmFPzBTVv\">pic.twitter.com\/TSmFPzBTVv<\/a><\/p>&mdash; UNESCO en espa\u00f1ol \ud83c\udfdb\ufe0f#Educaci\u00f3n #Ciencia #Cultura (@UNESCO_es) <a href=\"https:\/\/twitter.com\/UNESCO_es\/status\/1470790999647690759?ref_src=twsrc%5Etfw\">December 14, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1Nuestra cer\u00e1mica Awaj\u00fan es declarada Patrimonio Cultural Inmaterial de la Humanidad!<br><br>UNESCO declar\u00f3 el d\u00eda de hoy a los valores, conocimientos, saberes y pr\u00e1cticas del pueblo Awaj\u00fan asociados a la cer\u00e1mica, como Patrimonio Cultural Inmaterial de la Humanidad. <a href=\"https:\/\/t.co\/yauKBF3PBD\">pic.twitter.com\/yauKBF3PBD<\/a><\/p>&mdash; Ministerio Cultura (@MinCulturaPe) <a href=\"https:\/\/twitter.com\/MinCulturaPe\/status\/1470790305305841669?ref_src=twsrc%5Etfw\">December 14, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El pueblo Awaj\u00fan, tambi\u00e9n conocido como Aguaruna, es el segundo m\u00e1s numeroso de la Amazon\u00eda peruana. Esta comunidad amaz\u00f3nica, como muchas otras, se caracteriza por su compromiso con la defensa de su territorio ancestral, el cual es representado en sus actividades, por ejemplo la producci\u00f3n alfarera. Esta pr\u00e1ctica milenaria desempe\u00f1a una funci\u00f3n social importante, ya [&hellip;]<\/p>\n","protected":false},"author":219,"featured_media":12366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,329,357],"tags":[1205,1838,1447,1839,1837],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12353"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/219"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=12353"}],"version-history":[{"count":4,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12353\/revisions"}],"predecessor-version":[{"id":12363,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12353\/revisions\/12363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/12366"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=12353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=12353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=12353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}