{"id":12750,"date":"2022-07-03T11:06:26","date_gmt":"2022-07-03T16:06:26","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=12750"},"modified":"2022-07-03T11:07:18","modified_gmt":"2022-07-03T16:07:18","slug":"tarjetas-fantasma-nueva-modalidad-de-robo","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/tarjetas-fantasma-nueva-modalidad-de-robo\/","title":{"rendered":"Tarjetas \u201cfantasma\u201d: nueva modalidad de robo"},"content":{"rendered":"\n<p>Los delincuentes encuentran cada vez m\u00e1s maneras de poder realizar delitos. En estos \u00faltimos a\u00f1os se han incrementado los actos vand\u00e1licos de tipo electr\u00f3nico. Seg\u00fan el Comercio, a trav\u00e9s de su investigaci\u00f3n respecto al tema, habr\u00eda un nuevo formato de robo de dinero, que es el hecho de usar datos personales de las personas para sacar pr\u00e9stamos financieros o comprar productos de gran valor. <\/p>\n\n\n\n<p>Esta nueva modalidad se est\u00e1 incrementando debido a que cada vez los bancos tienen menos filtros y seguridad debida para que las personas puedan sacar pr\u00e9stamos de gran cantidad. De esta manera, los delincuentes tienen la facilidad de cometer estos actos, sin problema alguno, adem\u00e1s, de que no es un inconveniente conseguir y acceder a los datos de muchos ciudadanos.<\/p>\n\n\n\n<p>Luego de que El Comercio publique un reportaje exclusivo de esta modalidad de robo y del caso de la periodista Delsy Loyola, salieron m\u00e1s casos. Por ejemplo, la periodista,  quien tiene una deuda de m\u00e1s de ocho mil soles por esta modalidad de robo, se enter\u00f3 de ello cuando se puso a investigar su historial crediticio. As\u00ed, hay m\u00e1s casos, como el de Paulo Iglesias, que reside en Estados Unidos y se enter\u00f3 hace poco que debe m\u00e1s de veinticinco mil soles en compras en internet.<\/p>\n\n\n\n<p>En efecto, es un tema que preocupa a muchos peruanos en el pa\u00eds y por su parte, los bancos involucrados en este problema, al haber otorgado tarjetas y pr\u00e9stamos con facilidad a muchos usuarios, comentan que a partir de ahora, todo tr\u00e1mite y entrega de tarjetas o pr\u00e9stamos ser\u00e1n exclusivamente de manera presencial, ya no virtual. Sin embargo, ello todav\u00eda no arregla el problema de los afectados, ni la devoluci\u00f3n de su dinero. Adem\u00e1s, aqu\u00ed tambi\u00e9n estar\u00eda involucrado la Reniec debido a que estar\u00edan filtrando los datos f\u00e1cilmente a cualquier persona. Los afectados esperan encontrar una soluci\u00f3n pronto en la respuesta de las entidades bancarias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los delincuentes encuentran cada vez m\u00e1s maneras de poder realizar delitos. En estos \u00faltimos a\u00f1os se han incrementado los actos vand\u00e1licos de tipo electr\u00f3nico. Seg\u00fan el Comercio, a trav\u00e9s de su investigaci\u00f3n respecto al tema, habr\u00eda un nuevo formato de robo de dinero, que es el hecho de usar datos personales de las personas para [&hellip;]<\/p>\n","protected":false},"author":265,"featured_media":12751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[334,42],"tags":[1849,1848,102],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12750"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=12750"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12750\/revisions"}],"predecessor-version":[{"id":12752,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12750\/revisions\/12752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/12751"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=12750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=12750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=12750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}