{"id":12776,"date":"2022-07-03T16:03:45","date_gmt":"2022-07-03T21:03:45","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=12776"},"modified":"2022-07-07T15:11:55","modified_gmt":"2022-07-07T20:11:55","slug":"la-feria-del-libro-ciudad-con-cultura-regresa-a-los-olivos","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/la-feria-del-libro-ciudad-con-cultura-regresa-a-los-olivos\/","title":{"rendered":"La Feria del Libro \u201cCiudad con Cultura\u201d regresa a Los Olivos"},"content":{"rendered":"\n<p><strong>\u201cCiudad con Cultura\u201d es una iniciativa que incentiva el h\u00e1bito de la lectura. Los vecinos olivenses disfrutaron de las diversas actividades durante los d\u00edas de la exhibici\u00f3n.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/img-feria-libro.jpg\" alt=\"\" class=\"wp-image-12778\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/img-feria-libro.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/img-feria-libro-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Foto: Eduardo Quispe Huaringa<\/figcaption><\/figure>\n\n\n\n<p>Recientemente, la Municipalidad de los Olivos en coordinaci\u00f3n con la librer\u00eda Ciudad Librera y el Fondo de Cultura Econ\u00f3mica presentaron la Feria del Libro \u201cCiudad con Cultura\u201d 2022.<\/p>\n\n\n\n<p> Este evento alberg\u00f3 una gran variedad de librer\u00edas, editoriales, distribuidoras, emprendimientos culturales y art\u00edsticos, etc. La exhibici\u00f3n cultural se instal\u00f3 por segundo a\u00f1o consecutivo en la explanada del palacio municipal (Av. Carlos Izaguirre 813).<\/p>\n\n\n\n<p> La Feria del Libro se realiz\u00f3 no solo para fomentar la lectura, sino tambi\u00e9n para brindar m\u00faltiples actividades culturales para los vecinos olivenses. Del mismo modo, ofreci\u00f3 promociones y descuentos en diversos t\u00edtulos al p\u00fablico en general. Para ingresar los asistentes debieron usar doble mascarilla y mantener el distanciamiento social correspondiente.<\/p>\n\n\n\n<p> En los puestos de venta se pudo encontrar libros desde 5 soles y de diversos g\u00e9neros. Del mismo modo, se presentaron historietas de Marvel Comics y Detective Comics, mangas de series populares como Dragon Ball y Naruto, entre otros t\u00edtulos.<\/p>\n\n\n\n<p>Durante los d\u00edas de la Feria se realizaron 4 actividades principales:<br> <\/p>\n\n\n\n<p> \u25cf Concurso de cosplay: a cargo de Ciudad Librera, el esperad\u00edsimo evento reuni\u00f3 a los j\u00f3venes fan\u00e1ticos de los c\u00f3mics y el manga.<br> <\/p>\n\n\n\n<p> \u25cf M\u00fasica en vivo: la banda de postpunk Rod Blur, la banda de rock alternativo Artib\u00fcs, entre otros m\u00fasicos brindaron un peque\u00f1o concierto para amenizar la feria.<\/p>\n\n\n\n<p> \u25cf  Cuentacuentos: Jos\u00e9 Luis Guardia de \u201cPapo cuentacuentos\u201dy Cristy La Barrera de  \u201cLa biblioteca de Cristy\u201ddirigieron esta presentaci\u00f3n para toda la familia.<\/p>\n\n\n\n<p> \u25cf Conversatorios: a cargo de los clubes de lectura \u201cLibros que muerden\u201d de Katherin  Nu\u00f1ez y \u201cRecomendaci\u00f3n de autores para empezar a leer literatura cl\u00e1sica\u201d de  Kenneth Villanueva y Carlos Zambrano.<\/p>\n\n\n\n<p> Asimismo, como cierre de la feria, se realiz\u00f3 un sorteo en el que participaron todas las personas que compraron libros durante los d\u00edas de la exhibici\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCiudad con Cultura\u201d es una iniciativa que incentiva el h\u00e1bito de la lectura. Los vecinos olivenses disfrutaron de las diversas actividades durante los d\u00edas de la exhibici\u00f3n. Recientemente, la Municipalidad de los Olivos en coordinaci\u00f3n con la librer\u00eda Ciudad Librera y el Fondo de Cultura Econ\u00f3mica presentaron la Feria del Libro \u201cCiudad con Cultura\u201d 2022. [&hellip;]<\/p>\n","protected":false},"author":168,"featured_media":12777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,43,1216],"tags":[81,1861,851],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12776"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/168"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=12776"}],"version-history":[{"count":4,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12776\/revisions"}],"predecessor-version":[{"id":12927,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12776\/revisions\/12927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/12777"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=12776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=12776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=12776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}