{"id":12936,"date":"2022-07-07T20:02:08","date_gmt":"2022-07-08T01:02:08","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=12936"},"modified":"2022-07-12T08:12:30","modified_gmt":"2022-07-12T13:12:30","slug":"efectivos-de-la-policia-nacional-frustran-asalto-de-grifo-en-san-martin-de-porres","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/efectivos-de-la-policia-nacional-frustran-asalto-de-grifo-en-san-martin-de-porres\/","title":{"rendered":"Efectivos de la Polic\u00eda Nacional frustran asalto de grifo en San Mart\u00edn de Porres"},"content":{"rendered":"\n<p>Agentes de la Divisi\u00f3n Policial (DIVPOL) Norte 1 capturaron el pasado 7 de julio a dos delincuentes completamente armados cuando se encontraban asaltando el grifo \u201cEstaci\u00f3n 715\u201d en el distrito de San Mart\u00edn de Porres. Esta intervenci\u00f3n se dio gracias a la alerta temprana de uno de los vecinos, acto que produjo un r\u00e1pido accionar de los agentes del orden. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p> \u201cEl d\u00eda de hoy hemos capturado a dos de estos sujetos integrantes de una banda delincuencial. Tambi\u00e9n se ha logrado la incautaci\u00f3n de un arma de fuego abastecida y de un arma blanca. Ya hab\u00edan agredido a uno de los trabajadores de este grifo\u201d, sostuvo el general PNP Manuel Lozada Morales, jefe de la Regi\u00f3n Policial Lima, a Canal N.<br><br> <\/p><\/blockquote>\n\n\n\n<p>Ambos sujetos, que pertenecer\u00edan a la banda delincuencial denominada \u201cLos malditos de Bela\u00fande\u201d, fueron intervenidos con los 25 mil soles que ya le hab\u00edan arrebatado a uno de los trabajadores de la estaci\u00f3n de servicios ubicada en el cruce de las avenidas Canta Callao y Sant\u00edsima Cruz, en la urbanizaci\u00f3n San Diego.<br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/SMP-II.png\" alt=\"\" class=\"wp-image-12939\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/SMP-II.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/SMP-II-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Los delincuentes no contaban con documento de identidad al momento de la intervenci\u00f3n. <\/figcaption><\/figure>\n\n\n\n<p>No obstante, un tercer delincuente se dio a la fuga a bordo de un autom\u00f3vil. \u201cEstamos con el Plan Cerco activado. Es cuesti\u00f3n de horas para atraparlo. Estamos en el proceso de identificaci\u00f3n\u201d, afirm\u00f3 el jefe de la Regi\u00f3n Policial Lima. Asimismo, se utilizaron aparatos tecnol\u00f3gicos para impedir el asalto. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p> \u201cHemos empleado drones para poder tener eficacia y no haya costo social\u201d, a\u00f1adi\u00f3 el general PNP Manuel Lozada.<br><br> <\/p><\/blockquote>\n\n\n\n<p>Fuentes consultadas: https:\/\/canaln.pe\/actualidad\/olivos-policia-nacional-frustro-asalto-grifo-n448053<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agentes de la Divisi\u00f3n Policial (DIVPOL) Norte 1 capturaron el pasado 7 de julio a dos delincuentes completamente armados cuando se encontraban asaltando el grifo \u201cEstaci\u00f3n 715\u201d en el distrito de San Mart\u00edn de Porres. Esta intervenci\u00f3n se dio gracias a la alerta temprana de uno de los vecinos, acto que produjo un r\u00e1pido accionar [&hellip;]<\/p>\n","protected":false},"author":258,"featured_media":12937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[314,322,42],"tags":[1057,960,1905,1906],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12936"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/258"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=12936"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12936\/revisions"}],"predecessor-version":[{"id":12955,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12936\/revisions\/12955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/12937"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=12936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=12936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=12936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}