{"id":12972,"date":"2022-07-12T09:34:06","date_gmt":"2022-07-12T14:34:06","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=12972"},"modified":"2022-07-26T09:35:57","modified_gmt":"2022-07-26T14:35:57","slug":"los-olivos-joven-muere-por-impacto-de-bala-en-avenida-carlos-izaguirre","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/los-olivos-joven-muere-por-impacto-de-bala-en-avenida-carlos-izaguirre\/","title":{"rendered":"Los Olivos: joven muere por impacto de bala en avenida Carlos Izaguirre"},"content":{"rendered":"\n<p><em><strong>El hombre identificado como Jhomer Castillo Palomo (29), fue acribillado mientras caminaba tranquilamente por la acera. Actualmente, la Polic\u00eda Nacional investiga el origen de los disparos.<\/strong><\/em><\/p>\n\n\n\n<p>Una vida m\u00e1s se vio apagada en manos de la inseguridad ciudadana. Jhomer Castillo Palomo, un joven ingeniero, fue v\u00edctima de un impacto de bala mientras caminaba por la avenida Carlos Izaguirre, en el distrito de Los Olivos.<\/p>\n\n\n\n<p>Desde la Policia Nacional se manejan diversas hip\u00f3tesis, tratando de investigar el origen de los disparos. Una de las supuestos m\u00e1s sonados, ser\u00eda que se trata de un enfrentamiento entre bandas criminales de la zona, siendo una bala perdida la que impact\u00f3 sobre el cuerpo de la v\u00edctima.<\/p>\n\n\n\n<p>En el lugar del crimen, cerca a una conocida tienda de venta de electrodom\u00e9sticos, los peritos de criminal\u00edstica llegaron a encontrar hasta cinco casquillos de bala.<\/p>\n\n\n\n<p>Por su parte, el coronel PNP <strong>Juan Mundaca<\/strong>, jefe de la Divisi\u00f3n Policial Norte 1, revel\u00f3 que la v\u00edctima no contaba con ning\u00fan antecedente. Por lo mismo, la hipotes\u00eds de un posible asesinato por encargo, perder\u00eda peso.<\/p>\n\n\n\n<p>\u201c<em>Las investigaciones se est\u00e1n dando, hay hasta dos o tres hip\u00f3tesis. (\u2026) Hay videos que pueden identificar a una persona que al parecer ha realizado los disparos. No puedo adelantar opiniones<\/em>\u201d, declar\u00f3 ante RPP.<\/p>\n\n\n\n<p><strong>Vecinos reclaman la presencia del serenazo y la Polic\u00eda Nacional<\/strong><\/p>\n\n\n\n<p>Recientemente, el distrito de Los Olivos se ha visto envuelto en numerosos casos de delincuencia e inseguridad cuidadana. Por ello, muchos vecinos reclaman a las autoridades la presencia c\u00e1maras y de un patrullaje constante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hombre identificado como Jhomer Castillo Palomo (29), fue acribillado mientras caminaba tranquilamente por la acera. Actualmente, la Polic\u00eda Nacional investiga el origen de los disparos. Una vida m\u00e1s se vio apagada en manos de la inseguridad ciudadana. Jhomer Castillo Palomo, un joven ingeniero, fue v\u00edctima de un impacto de bala mientras caminaba por la [&hellip;]<\/p>\n","protected":false},"author":264,"featured_media":12975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[314,1216],"tags":[1457,595,1907],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12972"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/264"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=12972"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12972\/revisions"}],"predecessor-version":[{"id":12976,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/12972\/revisions\/12976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/12975"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=12972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=12972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=12972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}