{"id":13156,"date":"2022-07-26T03:25:16","date_gmt":"2022-07-26T08:25:16","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=13156"},"modified":"2022-07-26T03:25:20","modified_gmt":"2022-07-26T08:25:20","slug":"expertos-opinan-de-famosos-largometrajes-basados-en-el-mundo-de-la-tecnologia","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/expertos-opinan-de-famosos-largometrajes-basados-en-el-mundo-de-la-tecnologia\/","title":{"rendered":"Expertos opinan de famosos largometrajes basados en el mundo de la tecnolog\u00eda"},"content":{"rendered":"\n<p><strong>La saga de Matrix, innovaci\u00f3n en efectos especiales, Origen; implantaci\u00f3n de recuerdos, Gattaca; los mejores embriones y La Red Social; historia del nacimiento de la red m\u00e1s famosa del planeta. Pel\u00edculas para cin\u00e9filos que aman la tecnolog\u00eda.<\/strong><\/p>\n\n\n\n<p><strong>Matrix<\/strong>&nbsp;<\/p>\n\n\n\n<p>Filmes de los hermanos Wachowski, estrenada la primera en 1999, cuenta la historia de Neo, un joven hacker que es convocado por el movimiento de resistencia liderado por Morfeo, que lucha contra la dominaci\u00f3n de los seres humanos por las m\u00e1quinas. Morfeo le ofrece dos pastillas de diferentes colores: con una continuar\u00e1 en la ilusi\u00f3n, con la otra descubrir\u00e1 la verdad. El primer filme de la saga <a rel=\"noreferrer noopener\" href=\"https:\/\/www.espinof.com\/listas\/todas-peliculas-matrix-ordenadas-peor-a-mejor\" target=\"_blank\">Matrix<\/a> habla del nacimiento, el segundo de la vida y el\u00a0tercero de la muerte. La m\u00e1s reciente pel\u00edcula, la cuarta, estrenada en 2021 trata de una nueva decisi\u00f3n. Saga\u00a0considerada una\u00a0obra de culto, un referente para el cine de acci\u00f3n y para la innovaci\u00f3n en efectos especiales.\u00a0<\/p>\n\n\n\n<p> Marcos Merino <a rel=\"noreferrer noopener\" href=\"https:\/\/www.xataka.com\/inteligencia-artificial\/inteligencia-artificial-matrix-problema-eleccion\" target=\"_blank\">escribe sobre tecnolog\u00eda<\/a> e imparte cursos de alfabetizaci\u00f3n digital. El experto opina que &#8216;Matrix&#8217;, es una saga\u00a0especulativa donde\u00a0la apariencia y congruencia de las descripciones tecnol\u00f3gicas no es lo importante y s\u00ed las reflexiones filos\u00f3ficas. Respecto a inteligencia artificial, dice, nada vemos sobre redes neuronales, deep learning o leyes de la rob\u00f3tica. Comenta que a los Wachowski les preocupa m\u00e1s los simbolismos religiosos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"512\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/1366_2000-1024x512.jpeg\" alt=\"\" class=\"wp-image-13159\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/1366_2000-1024x512.jpeg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/1366_2000-300x150.jpeg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/1366_2000-768x384.jpeg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/1366_2000.jpeg 1366w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> Innovaci\u00f3n en efectos especiales Foto:  <a rel=\"noreferrer noopener\" href=\"https:\/\/www.xataka.com\/cine-y-tv\/matrix-resurrections-secuela-a-altura-trilogia-original-gran-reflexion-estancamiento-actual-cine\" target=\"_blank\">Xataka<\/a> <\/figcaption><\/figure>\n\n\n\n<p><strong>Origen<\/strong>\u00a0<\/p>\n\n\n\n<p>Origen o Inception, estrenada en 2010 de g\u00e9nero fant\u00e1stico, una pel\u00edcula de\u00a0Christopher Nolan. Dom Cobb (Leonardo DiCaprio) es experto\u00a0robando secretos valiosos dentro del subconsciente humano durante el sue\u00f1o, cuando la mente est\u00e1 en su estado m\u00e1s vulnerable. Roba en el mundo de los negocios para luego venderlos con grandes ganancias econ\u00f3micas.\u00a0Esta cualidad de Cobb lo ha convertido en un atractivo en el mundo del espionaje corporativo\u00a0y en un fugitivo internacional,\u00a0tendr\u00e1 que pagar un alto precio; Perder a la gente que ama. \u00a0<\/p>\n\n\n\n<p>Origen gan\u00f3 cuatro\u00a0Oscar en 2010; Mejor fotograf\u00eda, Mejor Edici\u00f3n de Sonido, Mejor Sonido y Mejores Efectos Visuales<\/p>\n\n\n\n<p><a href=\"https:\/\/www.lahiguera.net\/cinemania\/pelicula\/4545\/comentario.php\" target=\"_blank\" rel=\"noreferrer noopener\">Origen<\/a> parte de la posibilidad de compartir los sue\u00f1os&#8230; sue\u00f1os que se han dise\u00f1ado con cierto aspecto y ofrecer sensaciones completamente reales cuando se est\u00e1 dentro de ellos en estado de subconsciencia.&nbsp;<\/p>\n\n\n\n<p>Ana Paula Rumualdo es abogada, especialista en tecnolog\u00eda y protecci\u00f3n de datos, relata\u00a0en <a rel=\"noreferrer noopener\" href=\"https:\/\/letraslibres.com\/ciencia-y-tecnologia\/project-inception\/\" target=\"_blank\">\u201cLetras libres\u201d<\/a> que: Para <a rel=\"noreferrer noopener\" href=\"https:\/\/www.bu.edu\/csn\/profile\/steve-ramirez\/\" target=\"_blank\">Steve Ramirez<\/a> la manipulaci\u00f3n de la memoria s\u00ed funciona y el siguiente paso es \u00abeditar\u00bb los recuerdos (Project Inception) y opina que editarlos mientras est\u00e1n siendo reactivados, se puede modificar su contenido, de modo que pueden ser recordados hechos introducidos artificialmente y entonces\u00a0ser\u00edan de\u00a0una experiencia que nunca pas\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"990\" height=\"742\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/32708.jpg\" alt=\"\" class=\"wp-image-13160\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/32708.jpg 990w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/32708-300x225.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/32708-768x576.jpg 768w\" sizes=\"(max-width: 990px) 100vw, 990px\" \/><figcaption>La posibilidad de compartir los sue\u00f1os Foto:  <a rel=\"noreferrer noopener\" href=\"https:\/\/www.20minutos.com\/noticia\/24479\/0\/director-christopher-nolan\/explica-final\/origen-inception-peonza\/\" target=\"_blank\">20minutos.com<\/a>\u00a0 <\/figcaption><\/figure>\n\n\n\n<p>\u00a0\u00a0<\/p>\n\n\n\n<p><strong>Gattaca<\/strong>&nbsp;<\/p>\n\n\n\n<p>Gattaca&nbsp;es un centro de estudios y de investigaci\u00f3n espacial para j\u00f3venes con un patrimonio gen\u00e9tico impecable. En el mundo perfecto de&nbsp;Gattaca Jerome Morrow, el candidato ideal, ve su vida destrozada por un terrible accidente, mientras que Vincent Freeman, concebido de manera natural, sue\u00f1a con ir al espacio.&nbsp;<\/p>\n\n\n\n<p>Se ponen de acuerdo para alcanzar cada uno sus sue\u00f1os,\u00a0desafiando toda norma\u00a0que gobiernan <a rel=\"noreferrer noopener\" href=\"https:\/\/computerhoy.com\/listas\/life\/7-mejores-peliculas-amantes-tecnologia-24695\" target=\"_blank\">Gattaca<\/a>. Cuando todo parec\u00eda realizarse seg\u00fan sus planes, un director de vuelo es\u00a0terriblemente asesinado y, en el escenario del crimen amenazan con deshacer los planes de Jerome y Vincent. Sobrevivir en este ambiente no les resultar\u00e1 f\u00e1cil. Esta cinta se estren\u00f3 en 1998, del director Andrew Niccol en idioma ingl\u00e9s.\u00a0Fue premiada al \u00d3scar\u00a0a Mejor Dise\u00f1o de Producci\u00f3n,\u00a0<\/p>\n\n\n\n<p>\u201cEl progreso de la ciencia depende de nuevas t\u00e9cnicas, nuevos descubrimientos y nuevas ideas, probablemente en ese orden\u201d <a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/antonioregalado?ref_src=twsrc%5Egoogle%7Ctwcamp%5Eserp%7Ctwgr%5Eauthor\" target=\"_blank\">Antonio Regalado<\/a> quien escribe sobre biotecnolog\u00eda. \u201cLa era Gattaca: as\u00ed funciona el test de ADN para elegir el mejor embri\u00f3n\u201d (t\u00edtulo del art\u00edculo que hace referencia a la cinta) apunta\u00a0que, en Estados Unidos, algunas parejas\u00a0deseosas de\u00a0tener hijos est\u00e1n acudiendo a expertos en fertilidad para solicitar una pol\u00e9mica prueba gen\u00e9tica llamada <a rel=\"noreferrer noopener\" href=\"https:\/\/www.technologyreview.es\/\/s\/11617\/la-era-gattaca-asi-funciona-el-test-de-adn-para-elegir-el-mejor-embrion\" target=\"_blank\">\u00ab23andMe<\/a>, la cual es\u00a0una prueba de selecci\u00f3n de embriones que tengan congelados y mediante mediciones de ADN puede\u00a0predecir qu\u00e9 embriones tienen\u00a0menos probabilidades de padecer alguna enfermedad como: diabetes, ataques card\u00edacos o c\u00e1ncer.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"840\" height=\"560\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/840_560-1.jpeg\" alt=\"\" class=\"wp-image-13161\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/840_560-1.jpeg 840w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/840_560-1-300x200.jpeg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/840_560-1-768x512.jpeg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><figcaption>La selecci\u00f3n de ADN en Gattaca es una realidad Foto:  <a rel=\"noreferrer noopener\" href=\"https:\/\/www.xataka.com\/cine-y-tv\/gattaca-intriga-ciencia-ficcion-genetica-actual-e-inquietante-que-nunca\" target=\"_blank\">Xataka<\/a>\u00a0 <\/figcaption><\/figure>\n\n\n\n<p><strong>La Red Social<\/strong>&nbsp;<\/p>\n\n\n\n<p>La pel\u00edcula cuenta la historia de&nbsp;Mark Zuckerberg&nbsp;y del origen de la red social m\u00e1s famosa del mundo; Facebook. La historia refleja las ambiciones, los sue\u00f1os y los retos de un reducido grupo de estudiantes que quieren hacer&nbsp;grandes cambios en el mundo de las redes.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Mark Zuckerberg, arrogante y ambicioso quiere hacer una red social interna para Harvard. En seis\u00a0a\u00f1os, el proyecto de Facebook unir\u00e1 a millones de usuarios\u00a0y har\u00e1 del fundador un joven con una gran fortuna. Pel\u00edcula estrenada en diciembre de 2010. Su leyenda: &#8216;No se hacen 500 millones de amigos sin hacer unos cuantos enemigos&#8217;. Director:\u00a0David Fincher. Multipremiada: \u00d3scar al Mejor Gui\u00f3n Adaptado, \u00d3scar a la Mejor Banda Sonora, Premio Globo de Oro al Mejor director, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.google.com\/search?rlz=1C1CHBF_esMX946MX946&amp;sxsrf=ALiCzsavdg7aFxGnd44L-Q4PlhUz1SLHJw:1658658973136&amp;q=Anexo:BAFTA+al+mejor+montaje&amp;stick=H4sIAAAAAAAAAONgFuLSz9U3MC-2MDHLUgKzjQor80qKtIQcyxOLUsIz8_JSi0LywZxFrDKOeakV-VZOjm4hjgqJOQq5qVn5RQq5-XkliVmpANYZtVRNAAAA&amp;sa=X&amp;ved=2ahUKEwihtpaXqpH5AhWckmoFHRUtDYsQri56BAglEBs\" target=\"_blank\">Premio BAFTA al Mejor Montaje,<\/a>  entre otros.\u00a0<\/p>\n\n\n\n<p>En el portal <a rel=\"noreferrer noopener\" href=\"https:\/\/www.eldiario.es\/hojaderouter\/tecnologia\/software\/asesor-informatico-peliculas-la-red-social_1_4678806.html\" target=\"_blank\">El diario es<\/a> opinan que para hacer veros\u00edmil una historia tan tecnol\u00f3gica como este filme, los conocimientos inform\u00e1ticos resultaban muy\u00a0necesarios. Todas las escenas en las que Zuckerberg se desenvuelve entre c\u00f3digo y servidores, estuvo\u00a0Paul McReynolds, el inform\u00e1tico que contrat\u00f3 Fincher como asesor\u00a0para salvaguardar el rigor de la pel\u00edcula.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"642\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/la-red-social-tarantino-1590737127-1024x642.jpg\" alt=\"\" class=\"wp-image-13162\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/la-red-social-tarantino-1590737127-1024x642.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/la-red-social-tarantino-1590737127-300x188.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/la-red-social-tarantino-1590737127-768x482.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2022\/07\/la-red-social-tarantino-1590737127.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Entre c\u00f3digos y servidores Foto:  <a rel=\"noreferrer noopener\" href=\"https:\/\/www.20minutos.com\/noticia\/24479\/0\/director-christopher-nolan\/explica-final\/origen-inception-peonza\/\" target=\"_blank\">20minutos.com<\/a>\u00a0 <\/figcaption><\/figure>\n\n\n\n<p>.\u00a0<\/p>\n\n\n\n<p>Seg\u00fan McReynolds,&nbsp;hace poco que los directores y productores de cine se preocupan&nbsp;por la precisi\u00f3n en los aspectos tecnol\u00f3gicos. Y dice&nbsp;no ser el \u00fanico que se ha dado cuenta. Opina que as\u00ed lo demuestran webs como&nbsp;<a href=\"https:\/\/moviecode.tumblr.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">c\u00f3digo fuente en Tv y pel\u00edculas.<\/a> entre otras.&nbsp;<\/p>\n\n\n\n<p>Por su parte <a rel=\"noreferrer noopener\" href=\"https:\/\/www.sage.com\/es-es\/blog\/la-red-social-pelicula-sobre-los-origenes-de-facebook-como-ejercicio-de-emprendimiento\/\" target=\"_blank\">Sage<\/a> asevera que quiz\u00e1 la pel\u00edcula lo que menos cuenta es\u00a0Facebook,\u00a0ya que nunca se menciona la utilidad, qu\u00e9 hace, qu\u00e9 es y\u00a0tampoco en lo que se puede convertir. Cree que esta pel\u00edcula es un esfuerzo para colocar a Facebook en otra dimensi\u00f3n m\u00e1s all\u00e1 de las computadoras, los tel\u00e9fonos y otros dispositivos.\u00a0<\/p>\n\n\n\n<p>\u00a0<\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La saga de Matrix, innovaci\u00f3n en efectos especiales, Origen; implantaci\u00f3n de recuerdos, Gattaca; los mejores embriones y La Red Social; historia del nacimiento de la red m\u00e1s famosa del planeta. Pel\u00edculas para cin\u00e9filos que aman la tecnolog\u00eda. Matrix&nbsp; Filmes de los hermanos Wachowski, estrenada la primera en 1999, cuenta la historia de Neo, un joven [&hellip;]<\/p>\n","protected":false},"author":257,"featured_media":13157,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,35,28],"tags":[1958,1956,1954],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13156"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/257"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=13156"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13156\/revisions"}],"predecessor-version":[{"id":13163,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13156\/revisions\/13163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/13157"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=13156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=13156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=13156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}