{"id":13218,"date":"2022-07-27T01:05:10","date_gmt":"2022-07-27T06:05:10","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=13218"},"modified":"2022-07-27T01:07:11","modified_gmt":"2022-07-27T06:07:11","slug":"salon-de-primaria-continuo-con-clases-presenciales-pese-a-un-caso-confirmado-de-coronavirus","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/salon-de-primaria-continuo-con-clases-presenciales-pese-a-un-caso-confirmado-de-coronavirus\/","title":{"rendered":"Sal\u00f3n de primaria continu\u00f3 con clases presenciales pese a un caso confirmado de coronavirus"},"content":{"rendered":"\n<p><strong>En el colegio Alfredo Bonifaz mostr\u00f3 poca importancia a un caso de Covid-19 de un alumno, suspendi\u00e9ndole un d\u00eda de clases presenciales pese a que el Minsa consigna que deben ser 7 d\u00edas de cuarentena para todo el sal\u00f3n.<\/strong><\/p>\n\n\n\n<p>En el jueves 14 de julio, un alumno de primaria de la instituci\u00f3n educativa <a href=\"https:\/\/alfredobonifaz.edu.pe\/\">Alfredo Bonifaz Fonseca<\/a> ya presentaba unos s\u00edntomas de COVID -19, pero Edwin C\u00f3rdova, el padre del ni\u00f1o, decidi\u00f3 descartar tal infecci\u00f3n. Horas m\u00e1s tarde, la profesora que labora en el colegio del ni\u00f1o le coment\u00f3 que hab\u00eda unos casos en primaria e incluso en el sal\u00f3n. Es por ello que el d\u00eda siguiente llev\u00f3 al menor al laboratorio cl\u00ednico <a href=\"https:\/\/labperu.com\/\">Lab Per\u00fa<\/a> para realizarle una prueba para ant\u00edgeno, a la cual sali\u00f3 positivo, confirmando que el ni\u00f1o contrajo coronavirus.<\/p>\n\n\n\n<p> Edwin C\u00f3rdova, quien tambi\u00e9n es representante del colectivo \u00ab<a href=\"https:\/\/www.facebook.com\/Peruanos-Unidos-por-una-Mejor-Educaci%C3%B3n-287628845072774\/\">Peruanos unidos por una mejor educaci\u00f3n<\/a>\u00ab, dice que al comunicarlo el colegio prefiri\u00f3 mantenerlo en silencio, no darlo a conocer a los padres, por lo que las clases del d\u00eda viernes 15 de julio se llevaron con normalidad a excepci\u00f3n del ni\u00f1o contagiado, a quien se le permiti\u00f3 no asistir. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>\u201cSolamente dijeron que el ni\u00f1o (su hijo) no vaya a clases y que los dem\u00e1s siguieran asistiendo (&#8230;) en primaria ha habido una pol\u00edtica de ocultamiento de los casos\u201c, indic\u00f3 el padre del menor.<\/p><\/blockquote>\n\n\n\n<p>Aunque en la<a href=\"https:\/\/www.gob.pe\/institucion\/minedu\/normas-legales\/2721750-048-2022-minedu\"> Resoluci\u00f3n Ministerial N\u00b0 048-2022-MINEDU<\/a> se establece lo que debi\u00f3 haber hecho la instituci\u00f3n militar Alfredo Bonifaz: suspender temporalmente la presencialidad durante 7 d\u00edas, como subraya el protocolo ante casos sospechosos o confirmados de contagio, pero el recinto educativo decidi\u00f3 incidir en una pol\u00edtica de ocultamiento de los casos. Reci\u00e9n el d\u00eda domingo 17 de julio a las 9:20 am la licenciada Carrillo, a cargo del grado, escribi\u00f3 en el grupo de WhatsApp del sal\u00f3n que \u201cpor orden del director Smith Herrera Iba\u00f1ez y la subdirectora de primaria Tania Chavarria Rodriguez, el aula de 3ro A pasar\u00e1 a virtual el d\u00eda de ma\u00f1ana, solo por ma\u00f1ana\u201d.<\/p>\n\n\n\n<p>El d\u00eda lunes el se\u00f1or C\u00f3rdova se comunica con el con el subprefecto de Lima, Edgar Trejo Cuentas, para informarle los hechos ocurridos en el colegio de su hijo, por lo que la autoridad comenz\u00f3 a buscar comunicaci\u00f3n con la direcci\u00f3n de la I.E. Alfredo Bonifaz Fonseca, a lo cual respondi\u00f3 la secretaria, pues el coronel y director del colegio hab\u00eda salido.  El prefecto cuenta haberle preguntado \u201cpor qu\u00e9 no se est\u00e1n siguiendo los protocolos\u201d a lo cual inmediatamente el centro educativo castrense dependiente del Ministerio de Defensa apel\u00f3 a los siete d\u00edas de descanso por caso de COVID-19.<\/p>\n\n\n\n<p> El colegio Alfredo Bonifaz es una instituci\u00f3n educativa que brinda clases de iniciar, primaria y secundaria, siendo esta \u00faltima la que muestra una situaci\u00f3n diferente en la aplicaci\u00f3n de protocolos respecto al registro de un caso de coronavirus. La comunicaci\u00f3n fue distinta en grados como el 2do A, 2do E, 3ro C y 5to E de secundaria, pues en las cuatro secciones, la subdirecci\u00f3n cumpli\u00f3 con aplicar los siete d\u00edas preventivos al registrarse casos de COVID-19.<\/p>\n\n\n\n<p>El Instituto Nacional de Defensa de la Competencia y de la Protecci\u00f3n de la Propiedad Intelectual (<a href=\"https:\/\/www.indecopi.gob.pe\/servicios-en-linea\">Indecopi<\/a>), autoridad que advierte a los colegios que incumplen con sus obligaciones en contexto de COVID-19, da un plazo para que pueda implementar las acciones correctivas. El colegio Alfredo Bonifaz tard\u00f3 un par de d\u00edas en cumplir la norma y por ello quedar\u00eda libre de un procedimiento administrativo sancionador que le hubiese cobrado hasta 450 unidades impositivas tributarias (m\u00e1s de 2 millones de soles).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el colegio Alfredo Bonifaz mostr\u00f3 poca importancia a un caso de Covid-19 de un alumno, suspendi\u00e9ndole un d\u00eda de clases presenciales pese a que el Minsa consigna que deben ser 7 d\u00edas de cuarentena para todo el sal\u00f3n. En el jueves 14 de julio, un alumno de primaria de la instituci\u00f3n educativa Alfredo Bonifaz [&hellip;]<\/p>\n","protected":false},"author":254,"featured_media":13219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[27,39,317,482],"tags":[1404,166,1471,1847,286],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13218"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/254"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=13218"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13218\/revisions"}],"predecessor-version":[{"id":13221,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13218\/revisions\/13221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/13219"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=13218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=13218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=13218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}