{"id":13536,"date":"2022-08-17T00:05:31","date_gmt":"2022-08-17T05:05:31","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=13536"},"modified":"2022-08-17T00:05:36","modified_gmt":"2022-08-17T05:05:36","slug":"elecciones-2022-conoce-cuales-son-las-labores-de-los-miembros-de-mesa","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/elecciones-2022-conoce-cuales-son-las-labores-de-los-miembros-de-mesa\/","title":{"rendered":"Elecciones 2022: conoce cu\u00e1les son las labores de los miembros de mesa"},"content":{"rendered":"\n<p>La Oficina Nacional de Procesos Electorales (ONPE) inform\u00f3 a la opini\u00f3n p\u00fablica sobre las labores de los miembros de mesa durante las elecciones regionales y municipales del pr\u00f3ximo 2 de octubre.<\/p>\n\n\n\n<p>La ONPE indic\u00f3 que <strong>de los miembros de mesa depender\u00e1 la instalaci\u00f3n temprana y funcionamiento de la misma<\/strong>.<\/p>\n\n\n\n<p>Adem\u00e1s, que una de sus principales labores es la correcta conducci\u00f3n del proceso de sufragio.<\/p>\n\n\n\n<p>Asimismo, <strong>los miembros de mesa realizar\u00e1n el escrutinio de votos concluida la etapa de votaci\u00f3n<\/strong>, ya que estos ciudadanos ser\u00e1n la m\u00e1xima autoridad electoral en cada mesa de sufragio.<\/p>\n\n\n\n<p><strong>Protocolos de bioseguridad<\/strong><\/p>\n\n\n\n<p>La ONPE dio a conocer a los miembros de mesa los protocolos a seguir para que puedan ejercer sus funciones con total seguridad durante las Elecciones Regionales y Municipales.<\/p>\n\n\n\n<p>El ente electoral inform\u00f3 que, seg\u00fan la Resoluci\u00f3n Jefatural N\u00b0 01845-2022-JN\/ONPE, <strong>es de uso obligatorio dos mascarillas quir\u00fargicas o una KN95<\/strong> durante el proceso electoral.<\/p>\n\n\n\n<p>Indic\u00f3 que el alcohol en gel estar\u00e1 disponible en todas las mesas de sufragio. Adem\u00e1s, precis\u00f3 que otro de los protocolos de bioseguridad es la ventilaci\u00f3n continua de los espacios de sufragio.<\/p>\n\n\n\n<p>Asimismo, se\u00f1al\u00f3 que el<strong> distanciamiento m\u00ednimo entre miembros de mesa ser\u00e1 de un metro en el interior del aula<\/strong>.\u00a0<\/p>\n\n\n\n<p>El viernes 22 de julio, un total de 505,938 ciudadanos fueron seleccionados como miembros de mesa, entre titulares y suplentes, para las elecciones regionales y municipales.<\/p>\n\n\n\n<p>La multa por no ejercer el cargo de miembro de mesa es de 230 soles. Asimismo, los miembros de mesa que ejerzan el cargo recibir\u00e1n una compensaci\u00f3n econ\u00f3mica de 120 soles por cada jornada electoral (primera y segunda elecci\u00f3n) durante las elecciones regionales y municipales.<\/p>\n\n\n\n<p>Como es de conocimiento p\u00fablico, a trav\u00e9s de un sorteo las 93 oficinas descentralizadas de procesos electorales seleccionaron a tres miembros de mesa titulares y tres suplentes para cada una de las 84,323 mesas de sufragio que deber\u00e1n instalarse en la jornada electoral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Oficina Nacional de Procesos Electorales (ONPE) inform\u00f3 a la opini\u00f3n p\u00fablica sobre las labores de los miembros de mesa durante las elecciones regionales y municipales del pr\u00f3ximo 2 de octubre.<\/p>\n","protected":false},"author":263,"featured_media":13538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[316,329,33],"tags":[2033,1232,836],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13536"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/263"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=13536"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13536\/revisions"}],"predecessor-version":[{"id":13539,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13536\/revisions\/13539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/13538"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=13536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=13536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=13536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}