{"id":13665,"date":"2023-05-08T16:51:33","date_gmt":"2023-05-08T21:51:33","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=13665"},"modified":"2023-05-08T16:51:38","modified_gmt":"2023-05-08T21:51:38","slug":"los-corridos-tumbados-estan-conquistando-la-industria-musical","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/los-corridos-tumbados-estan-conquistando-la-industria-musical\/","title":{"rendered":"Los \u201ccorridos tumbados\u201d est\u00e1n conquistando la industria musical"},"content":{"rendered":"\n<p><strong>En los \u00faltimos a\u00f1os, un subg\u00e9nero musical de origen mexicano conocido como los \u201ccorridos tumbados\u201d se ha convertido en uno de los m\u00e1s populares a nivel mundial.<\/strong><\/p>\n\n\n\n<p>Este\nsubg\u00e9nero surge de la fusi\u00f3n del corrido mexicano, que es un estilo musical\ntradicionalmente asociado con la m\u00fasica norte\u00f1a, y se a\u00f1ade con el trap y con\nel hip-hop, g\u00e9neros de m\u00fasica urbana que se originan en Estados Unidos. <\/p>\n\n\n\n<p><a href=\"https:\/\/la-lista.com\/entretenimiento\/2023\/04\/28\/peso-pluma-que-son-los-corridos-tumbados-gil-barrera\">Gilberto Barrera<\/a>, cr\u00edtico de espect\u00e1culos,\na\u00f1ade que \u201ces una variante del corrido tradicional que cuenta historias urbanas\npero actualizadas, ya no revolucionarias ni basadas en rancher\u00edas, que era lo\nque ten\u00edamos con el origen de los corridos\u201d<\/p>\n\n\n\n<p>Entre\nlas estrellas del subg\u00e9nero est\u00e1n <a href=\"https:\/\/www.youtube.com\/channel\/UCW2_ESwKrYgSjqQjrR09n0g\">Natanael Cano<\/a>, <a href=\"https:\/\/www.youtube.com\/channel\/UCtqOng3GVhQVu1Gl-3UlyAQ\">Christian Nodal<\/a>, <a href=\"https:\/\/www.youtube.com\/channel\/UCwA5HHGsAlpU1UlhwWD52uA\">Junior H<\/a>, <a href=\"https:\/\/www.youtube.com\/channel\/UCFLI6KAjrKRtydD7KqiYvAw\">Fuerza Regida<\/a>, entre otros; quienes han\nlogrado grandes \u00e9xitos durante su carrera musical. Inclusive los \u201ccorridos\ntumbados\u201d recientemente han logrado encabezar las listas de reproducci\u00f3n m\u00e1s\nescuchados, posicion\u00e1ndose en el <a href=\"https:\/\/www.billboard.com\/music\/chart-beat\/eslabon-armado-peso-pluma-ella-baila-sola-number-one-global-200-1235314209\/\">puesto n\u00famero 1 de la\nlista Billboard Global 200<\/a> con el famoso Peso Pluma a trav\u00e9s de su single <a href=\"https:\/\/www.youtube.com\/watch?v=lZiaYpD9ZrI\">\u00ab<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=lZiaYpD9ZrI\">Ella Baila Sola<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=lZiaYpD9ZrI\">\u00ab<\/a>, junto con otras 6 canciones que se\nencuentran en este reconocido ranking internacional. <\/p>\n\n\n\n<p>Este\npanorama muestra que aunque el origen del corrido tumbado se ubica en M\u00e9xico,\nsu popularidad ha trascendido fronteras y actualmente es un fen\u00f3meno musical en\ntoda Am\u00e9rica Latina y Estados Unidos.<\/p>\n\n\n\n<p><strong>La f\u00f3rmula del \u00e9xito<\/strong><\/p>\n\n\n\n<p>Los\ncorridos est\u00e1n de moda, y es un subg\u00e9nero que est\u00e1 logrando una gran acogida en\ndistintos pa\u00edses. En ese sentido, el \u00e9xito del corrido tumbado radica en su\ncapacidad de conectar con la juventud hispanohablante a trav\u00e9s de una propuesta\nmusical que mezcla elementos de la tradici\u00f3n con la modernidad. <\/p>\n\n\n\n<p>Hace\npoco, hubo una colaboraci\u00f3n para interpretar un corrido tumbado entre el famoso\nGrupo Frontera con el artista de reggaeton, <a href=\"https:\/\/www.youtube.com\/channel\/UCmBA_wu8xGg1OfOkfW13Q0Q\">Bad Bunny<\/a>. Y no s\u00f3lo ello, sino que la\ncolaboraci\u00f3n <a href=\"https:\/\/www.billboard.com\/espanol\/noticias\/grupo-frontera-bad-bunny-un-x100to-no-1-listas-mundiales-1235319303\/\">\u00abUn x100to\u00bb\nse ubic\u00f3 en el primer sitio de la lista de Billboard<\/a>.<\/p>\n\n\n\n<p>Adem\u00e1s,\nel g\u00e9nero ha sido utilizado como una forma de expresi\u00f3n para j\u00f3venes que viven\nen contextos de violencia y marginaci\u00f3n, y que encuentran en las letras del\ncorrido tumbado una forma de contar sus historias y denunciar las injusticias\nque viven en sus comunidades.<\/p>\n\n\n\n<p><strong>Cr\u00edticas hacia los corridos tumbados<\/strong><\/p>\n\n\n\n<p>Sin\nembargo, el corrido tumbado tambi\u00e9n ha generado controversia por su contenido\nexpl\u00edcito y violento, que ha sido criticado por algunos sectores de la sociedad\nque lo consideran una <a href=\"https:\/\/www.infobae.com\/america\/mexico\/2022\/10\/04\/apologia-del-delito-como-un-narcocorrido-en-honor-al-chapo-guzman-empano-celebracion-historica-en-sinaloa\/\">apolog\u00eda al\nnarcotr\u00e1fico y la violencia<\/a>. A pesar de ello, ha seguido creciendo en popularidad\ny ha encontrado un espacio en la m\u00fasica latina contempor\u00e1nea.<\/p>\n\n\n\n<p>En\nconclusi\u00f3n, el corrido tumbado es un subg\u00e9nero musical que ha logrado\nconquistar el coraz\u00f3n de los j\u00f3venes hispanohablantes en todo el mundo. Su\nfusi\u00f3n de elementos tradicionales y modernos, as\u00ed como sus letras que abordan\ntemas sociales relevantes, han convertido al corrido tumbado en una propuesta\nmusical \u00fanica y popular. Aunque ha generado controversia por su contenido\nviolento, el g\u00e9nero ha encontrado un espacio tanto en la m\u00fasica latina como a\nnivel mundial, por lo que sigue evolucionando y reinvent\u00e1ndose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os, un subg\u00e9nero musical de origen mexicano conocido como los \u201ccorridos tumbados\u201d se ha convertido en uno de los m\u00e1s populares a nivel mundial. Este subg\u00e9nero surge de la fusi\u00f3n del corrido mexicano, que es un estilo musical tradicionalmente asociado con la m\u00fasica norte\u00f1a, y se a\u00f1ade con el trap y con [&hellip;]<\/p>\n","protected":false},"author":131,"featured_media":13668,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[2060,2059,1099,170],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13665"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/131"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=13665"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13665\/revisions"}],"predecessor-version":[{"id":13667,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/13665\/revisions\/13667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/13668"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=13665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=13665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=13665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}