{"id":1541,"date":"2020-07-17T07:22:49","date_gmt":"2020-07-17T12:22:49","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=1541"},"modified":"2020-07-17T07:22:52","modified_gmt":"2020-07-17T12:22:52","slug":"la-new-media-ecology-y-la-evolucion-del-periodismo-y-de-su-formacion","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/la-new-media-ecology-y-la-evolucion-del-periodismo-y-de-su-formacion\/","title":{"rendered":"La New Media Ecology y la evoluci\u00f3n del periodismo&#8230;y de su formaci\u00f3n"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/07\/newmediaecology680x374.jpg\" alt=\"\" class=\"wp-image-1543\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/07\/newmediaecology680x374.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/07\/newmediaecology680x374-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Image  of Journalism That Matters. Fuente: The Waving Cat <\/figcaption><\/figure>\n\n\n\n<p>Se aprecia que en la&nbsp;<strong>nueva ecolog\u00eda de medios<\/strong>, las organizaciones de noticias incorporan, adaptan y usan las tecnolog\u00edas emergentes y disruptivas de la informaci\u00f3n en&nbsp; los diversos sitios web y forman parte de estrategias narrativas e informativas, por lo que la anal\u00edtica web, la narrativa multimedia y transmedia o el modelo period\u00edstico conocido como Slow Journalism, juegan un papel determinante en la evoluci\u00f3n del periodismo en internet.<\/p>\n\n\n\n<p>En paralelo, las tecnolog\u00edas emergentes y la nueva ecolog\u00eda de medios tambi\u00e9n est\u00e1n transformando profundamente las universidades que tienen facultades de Periodismo o Comunicaci\u00f3n, oblig\u00e1ndolas a cambiar sus m\u00e9todos de ense\u00f1anza que han acompa\u00f1ado a dichos estudios durante d\u00e9cadas pasadas.<\/p>\n\n\n\n<p>Estos aspectos forman parte del capitulo&nbsp;<strong>\u201cEcolog\u00eda de medios, tecnolog\u00edas y periodismo\u201d<\/strong>&nbsp;del libro&nbsp;<a href=\"http:\/\/www.comunicacionsocial.es\/catalogo\/publicaciones-autor\/Jes%C3%BAs%20Miguel%20Flores%20Vivar\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Tecnolog\u00edas del Ecosistema Period\u00edstico<\/strong><\/a>, publicado en noviembre de 2019 por la editorial Comunicaci\u00f3n Social.&nbsp;En dicho cap\u00edtulo, se analiza la evoluci\u00f3n de la ecolog\u00eda de los medios, el surgimiento de tecnolog\u00edas que consolidan el concepto como extensiones del ser humano lo que genera una innovaci\u00f3n disruptiva en muchos aspectos sociales, pol\u00edticos y econ\u00f3micos.<\/p>\n\n\n\n<p>Concretamente, el capitulo aborda temas acerca de&nbsp;McLuhan y Postman sobre Ecolog\u00eda de los medios; las tecnolog\u00edas y medios l\u00edquidos; hacia una contextualizaci\u00f3n de las tecnolog\u00edas e innovaciones disruptivas; la confluencia de las tecnolog\u00edas disruptivas con los medios l\u00edquidos de Bauman; el impacto de las tecnolog\u00edas disruptivas en las organizaciones de noticias; estudio de caso KPMG; el significado de la interrupci\u00f3n para los peri\u00f3dicos; como las tecnolog\u00edas disruptivas est\u00e1n mejorando el modelo operativo; como los medios deben aprovechar el potencial de innovaci\u00f3n disruptiva; los nuevos, nuevos medios y el periodismo en red; los nuevos medios como extensiones amplificadoras del conocimiento: software y aplicaciones; temas que tienen como bases las correspondientes referencias bibliogr\u00e1ficas publicadas por investigadores que vienen trabajando sobre los temas en cuesti\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ecolog\u00eda de medios, propuesta por McLuhan y Postman, requiere de una revisi\u00f3n, consenso, adaptaci\u00f3n y contextualizaci\u00f3n en una era marcada de profundas transformaciones tecnol\u00f3gicas que cambian las formas de producir, distribuir y consumir la informaci\u00f3n y el conocimiento.<\/p>\n","protected":false},"author":1,"featured_media":1543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[29,37,28],"tags":[60,53,61,58,55,56,57],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1541"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=1541"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1541\/revisions"}],"predecessor-version":[{"id":1544,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1541\/revisions\/1544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/1543"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=1541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=1541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=1541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}