{"id":1608,"date":"2020-07-19T12:05:26","date_gmt":"2020-07-19T17:05:26","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=1608"},"modified":"2020-07-19T12:05:30","modified_gmt":"2020-07-19T17:05:30","slug":"el-iv-seminario-red-itc-en-el-marco-del-iii-congreso-internacional-de-ecologia-de-los-medios-en-brasil","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/el-iv-seminario-red-itc-en-el-marco-del-iii-congreso-internacional-de-ecologia-de-los-medios-en-brasil\/","title":{"rendered":"El IV Seminario Red ITC en el marco del III Congreso Internacional de Ecolog\u00eda de los Medios en Brasil"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/07\/3congresomeistudiesSeminarioRedITC.jpg\" alt=\"\" class=\"wp-image-1610\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/07\/3congresomeistudiesSeminarioRedITC.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/07\/3congresomeistudiesSeminarioRedITC-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p> Ahora m\u00e1s\u00a0que nunca debido a la pandemia de la Covid 19, los investigadores de todas las disciplinas acad\u00e9micas participan y promueven la realizaci\u00f3n de eventos globales como es el caso de del\u00a0<strong>3er Congreso Internacional de Ecolog\u00eda de los Medios y Estudios de Imagen<\/strong>\u00a0con el tema\u00a0<em>\u00abDemocracia, medios y pandemia\u00bb<\/em>, que se llevar\u00e1\u00a0cabo entre el\u00a0<strong>1 de diciembre de 2020 &#8211; 31 de diciembre de 2020<\/strong>.<\/p>\n\n\n\n<p><br>Los resultados de la pandemia, muchos de los cuales a\u00fan son desconocidos para nosotros, han sido lo suficientemente intensos como para transformar conceptos, valores e importancia en diferentes sectores, incluidos los medios de comunicaci\u00f3n. las diversas disciplinas como la educaci\u00f3n, la publicidad, el periodismo, la comunicaci\u00f3n, etc.\u00a0<\/p>\n\n\n\n<p><br>El 3er. congreso, incluye adem\u00e1s, la realizaci\u00f3n del\u00a0<strong>IV Seminario Internacional Red ITC<\/strong>\u00a0con el tema\u00a0<em>\u00abEstrategias, iniciativas y desaf\u00edos de la ense\u00f1anza virtual en un momento de incertidumbre glocal\u00bb<\/em>, un seminario itinerante por la propia caracter\u00edstica\u00a0de los miembros de la Red ITC conformada por grupos de investigaci\u00f3n de cuatro pa\u00edses\u00a0iberoamericanos (Brasil, Espa\u00f1a, M\u00e9xico\u00a0y Per\u00fa).<\/p>\n\n\n\n<p><br>El 3er. congreso, que se viene celebrando en\u00a0un formato totalmente virtual desde sus inicios, en la edici\u00f3n 2020 contar\u00e1 con 18 \u00a0videoconferencistas magistrales de 12 pa\u00edses, que presentar\u00e1n sus contribuciones a trav\u00e9s de videos compartidos en la plataforma del evento durante todo el mes de diciembre,\u00a0conjuntamente con videoconferencias presentadas en tiempo real por los acad\u00e9micos invitados. Consta de 13 \u00a0mesas de trabajo con diversos temas relacionados en estudios sobre democracia y medios en tiempos de pandemia.<\/p>\n\n\n\n<p>Las inscripciones y la presentaci\u00f3n de comunicaciones est\u00e1n abiertas&nbsp;<a href=\"http:\/\/meistudies.org\/index.php\/cmei\/3cime\/index\" target=\"_blank\" rel=\"noreferrer noopener\">AQU\u00cd<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La realizaci\u00f3n del IV Seminario Internacional Red ITC con el tema \u00abEstrategias, iniciativas y desaf\u00edos de la ense\u00f1anza virtual en un momento de incertidumbre glocal\u00bb, un seminario itinerante por la propia caracter\u00edstica de los miembros de la Red ITC conformada por grupos de investigaci\u00f3n de cuatro pa\u00edses iberoamericanos (Brasil, Espa\u00f1a, M\u00e9xico y Per\u00fa).<\/p>\n","protected":false},"author":1,"featured_media":1610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[27,31],"tags":[73,77,50,76,75,74],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1608"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=1608"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1608\/revisions"}],"predecessor-version":[{"id":1611,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1608\/revisions\/1611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/1610"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=1608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=1608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=1608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}