{"id":1639,"date":"2020-07-20T09:57:16","date_gmt":"2020-07-20T14:57:16","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=1639"},"modified":"2020-07-20T09:59:49","modified_gmt":"2020-07-20T14:59:49","slug":"exponen-relatos-de-mi-piel-y-tacora-muestras-ganadoras-del-concurso-proyectos-artisticos","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/exponen-relatos-de-mi-piel-y-tacora-muestras-ganadoras-del-concurso-proyectos-artisticos\/","title":{"rendered":"Exponen \u201cRelatos de mi piel\u201d y \u201cTacora\u201d, muestras ganadoras del concurso \u201cProyectos Art\u00edsticos\u201d"},"content":{"rendered":"\n<p>Bellasartinas\nAngie Cienfuegos y Mara Palac\u00edn retratan sus reflexiones sobre el endoracismo y\nla resistencia urbana <\/p>\n\n\n\n<p><strong>Angie\nCienfuegos y Mara Palac\u00edn, ganadoras de la convocatoria \u201cProyectos Art\u00edsticos\u201d,\npresentaron sus exposiciones individuales en el Centro Cultural de Bellas\nArtes. En el estilo narrativo de sus propuestas utilizan desde t\u00e9cnicas de\ncostura o el empleo de materiales org\u00e1nicos hasta la ambientaci\u00f3n simulada.<\/strong><\/p>\n\n\n\n<p>En la ceremonia de inauguraci\u00f3n estuvieron\npresentes, adem\u00e1s de las artistas en menci\u00f3n, los curadores de la muestra,\nGeorge Clarke y Alejandra de la Cruz &#8211; respectivamente &#8211; , y la Directora de\nPromoci\u00f3n Cultural del centro educativo, Lizeth D\u00edaz Machuca, quien manifest\u00f3\nque \u201cambas exposiciones son el resultado de un trabajo comprometido y\nprofesional del equipo del Centro Cultural de Bellas Artes, desde la producci\u00f3n\nart\u00edstica as\u00ed como la propuesta museogr\u00e1fica\u201d <\/p>\n\n\n\n<p>\u201cRelatos de mi piel. Genealog\u00eda del vac\u00edo\u201d\nparte de una reflexi\u00f3n personal de Angie Cienfuegos, quien en un momento de su\nvida se cuestiona sobre sus ra\u00edces familiares, su procedencia geogr\u00e1fica y el\nproblema racial entre sus parientes. A partir de su pasi\u00f3n por la costura, una\npr\u00e1ctica heredada por las mujeres de su familia, y el inter\u00e9s por utilizar un\nproducto org\u00e1nico como la chancaca, representaci\u00f3n de la esclavitud de sus\nantepasados, une siluetas de personajes con fotograf\u00edas, recuerdos recortados,\npara construir y darle un sentido emocional a su narrativa art\u00edstica. <\/p>\n\n\n\n<p>Entre otros elementos que caracterizan el\nestilo de su proyecto es el empleo del collage, las quemaduras sobre tela y, de\nmanera anecd\u00f3tica, unas d\u00e9cimas de su creaci\u00f3n. Estas \u00faltimas narran casos de\nendoracismo (familiar), desde una manera racionalizadora; es decir,\nlegitimadora de sus emociones y pensamientos. \u201cAl igual que mis antepasados,\ntuve esa curiosidad por saber c\u00f3mo todo mi linaje africano llega a m\u00ed. Este mes,\nen donde se celebra el orgullo afroperuano, era muy importante para ense\u00f1ar mi\ntrabajo\u201d, expuso Cienfuegos.<\/p>\n\n\n\n<p>Por otro lado, en \u201cTacora: residuos como\nresistencia para sobrevivir\u201d, Mar\u00eda Claudia Ramos &#8211; o Mara Palac\u00edn, su nombre\nart\u00edstico &#8211; documenta a trav\u00e9s de im\u00e1genes y videos el mercado de segunda mano\nm\u00e1s grande Lima: Tacora, un punto de encuentro de personajes marginados en El\nAgustino. Con sus vivencias personales, c\u00e1mara en mano y valor, Palac\u00edn se\nsumerge en los almacenes olvidados y las historias de los personajes que lo\nfrecuentan. <\/p>\n\n\n\n<p>Todo esto lo logra gracias a la recreaci\u00f3n de\nsu proyecto, con m\u00fasica vernacular, p\u00f3sters chichas, objetos de segunda mano y\nfotograf\u00edas de grandes dimensiones que adentran al espectador en una\nexperiencia similar al de estar en aquel lugar. <\/p>\n\n\n\n<p>Ambas artistas, junto a Ricardo Puga &#8211; cuya\nexposici\u00f3n tendr\u00e1 lugar el 8 de junio en la Fundaci\u00f3n Euroidiomas -, conforman\nlos primeros estudiantes de dicha escuela en presentar sus trabajos despu\u00e9s de\nhaber ganado en \u201cProyectos Art\u00edsticos\u201d, un evento realizado por el centro de\nestudios en el marco de su centenario. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angie Cienfuegos y Mara Palac\u00edn, ganadoras de la convocatoria \u201cProyectos Art\u00edsticos\u201d, presentaron sus exposiciones individuales en el Centro Cultural de Bellas Artes. En el estilo narrativo de sus propuestas utilizan desde t\u00e9cnicas de costura o el empleo de materiales org\u00e1nicos hasta la ambientaci\u00f3n simulada.<\/p>\n","protected":false},"author":7,"featured_media":1641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,34],"tags":[67,83,82,81],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1639"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=1639"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1639\/revisions"}],"predecessor-version":[{"id":1643,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1639\/revisions\/1643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/1641"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=1639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=1639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=1639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}