{"id":1714,"date":"2020-07-20T12:40:26","date_gmt":"2020-07-20T17:40:26","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=1714"},"modified":"2020-07-20T12:53:38","modified_gmt":"2020-07-20T17:53:38","slug":"asciende-el-futbol-en-la-premier-league-con-el-leeds-de-bielsa","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/asciende-el-futbol-en-la-premier-league-con-el-leeds-de-bielsa\/","title":{"rendered":"Asciende el f\u00fatbol en la Premier League con el Leeds de Bielsa"},"content":{"rendered":"\n<p><em>Los dirigidos por Marcelo Bielsa subieron de categor\u00eda\nsin haber disputado el enfrentamiento por la fecha 45<\/em><\/p>\n\n\n\n<p>El Leeds United asciende a la Premier\nLeague, la liga m\u00e1s importante de Inglaterra, despu\u00e9s de 12 a\u00f1os. Tras la\nderrota del escolta West Bromwich por 1 a 2 frente al Huddersfield, el equipo\nde Marcelo Bielsa asegura su ascenso a la primera divisi\u00f3n del pa\u00eds brit\u00e1nico.\nLa ca\u00edda del segundo puesto de la tabla posiciona al equipo del \u201cloco\u201d en la\nm\u00e1s alta posici\u00f3n de la Championship (segunda divisi\u00f3n) con 87 puntos, y lo coloca\nde cara a ser campe\u00f3n de esta liga a dos fechas de culminar el torneo.<\/p>\n\n\n\n<p>En la temporada 2018 \u2013 2019,\ntras la llegada del \u201cloco\u201d Bielsa al club de segunda divisi\u00f3n, el Leeds United logr\u00f3\nconseguir 83 puntos y el tercer puesto en la tabla de posiciones de la\nChampionship al terminar la liga; por lo que no le alcanz\u00f3 para obtener el\nansiado ascenso. Con la llegada de Marcelo Bielsa, el Leeds logr\u00f3 escalar las\nposiciones principales; despu\u00e9s de que en la temporada 2016 \u2013 2017 quedara en\nel puesto 7 y en la temporada 2017 \u2013 2018 quedara en el puesto 13.<\/p>\n\n\n\n<p>Para que el Leeds se convierta\nen el campe\u00f3n absoluto de la segunda liga de Inglaterra tendr\u00e1 que asegurar una\nvictoria o un empate en el pr\u00f3ximo partido que le toque disputar. <\/p>\n\n\n\n<p>El leeds tiene dos partidos por\njugar antes de cerrar la temporada 2019 \u2013 2020: <\/p>\n\n\n\n<ul><li>Derby\nCounty vs Leeds (Dom., 19\/07)<\/li><li>Leeds vs Charlton (Mie., 22\/07 \u2013 13:30) <\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En la temporada 2018 \u2013 2019, tras la llegada del \u201cloco\u201d Bielsa al club de segunda divisi\u00f3n, el Leeds United logr\u00f3 conseguir 83 puntos y el tercer puesto en la tabla de posiciones de la Championship al terminar la liga; por lo que no le alcanz\u00f3 para obtener el ansiado ascenso. Con la llegada de Marcelo Bielsa, el Leeds logr\u00f3 escalar las posiciones <\/p>\n","protected":false},"author":26,"featured_media":1715,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[78,79],"tags":[94,96,69,112,111],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1714"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=1714"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1714\/revisions"}],"predecessor-version":[{"id":1717,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/1714\/revisions\/1717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/1715"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=1714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=1714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=1714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}