{"id":2231,"date":"2020-08-21T22:09:27","date_gmt":"2020-08-22T03:09:27","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=2231"},"modified":"2020-09-15T22:23:03","modified_gmt":"2020-09-16T03:23:03","slug":"%f0%9d%90%8d%f0%9d%90%9e%f0%9d%90%b2%f0%9d%90%a6%f0%9d%90%9a%f0%9d%90%ab-%f0%9d%90%89%f0%9d%90%ab-%f0%9d%90%9d%f0%9d%90%9e%f0%9d%90%ac%f0%9d%90%ad%f0%9d%90%a2%f0%9d%90%a7%f0%9d%90%9a%f0%9d%90%9d","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/%f0%9d%90%8d%f0%9d%90%9e%f0%9d%90%b2%f0%9d%90%a6%f0%9d%90%9a%f0%9d%90%ab-%f0%9d%90%89%f0%9d%90%ab-%f0%9d%90%9d%f0%9d%90%9e%f0%9d%90%ac%f0%9d%90%ad%f0%9d%90%a2%f0%9d%90%a7%f0%9d%90%9a%f0%9d%90%9d\/","title":{"rendered":"Neymar JR.: destinado a hacer historia"},"content":{"rendered":"\n<p>A la selecci\u00f3n de f\u00fatbol m\u00e1s exitosa de la historia le faltaba un t\u00edtulo. Muchos cracks comandaron esa selecci\u00f3n ol\u00edmpica en busca de la medalla dorada, pero todos fracasaron en el intento. Parec\u00eda que el destino lo ten\u00eda todo planeado: el 20 de agosto del 2016, con la atenta mirada de 75 mil espectadores que reventaban el Maracan\u00e1, Neymar Jr. ser\u00eda el encargado de ba\u00f1ar en oro los sue\u00f1os del pueblo brasile\u00f1o.<\/p>\n\n\n\n<p>Exactamente un a\u00f1o despu\u00e9s, el h\u00e9roe de la verdeamerelha har\u00eda su debut en el Parque de los Pr\u00edncipes. <a href=\"https:\/\/www.pasionfutbol.com\/noticias\/Neymar-el-mas-caro-por-mucho-tiempo-20200511-0016.html\" class=\"ek-link\">El PSG hab\u00eda desembolsado 222 millones de euros por Neymar Jr. convirti\u00e9ndolo en el jugador m\u00e1s caro de la historia<\/a> y en el nuevo conductor del equipo m\u00e1s ganador de Francia hacia el trofeo que tanto le hab\u00eda sido esquivo: la Champions League.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"755\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Before-the-game_-_We-are-not-afraid-of-Neymar_-In-the-game_-Triple-marking-on-Neymar-\ud83e\udd23-1024x755.jpg\" alt=\"\" class=\"wp-image-3984\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Before-the-game_-_We-are-not-afraid-of-Neymar_-In-the-game_-Triple-marking-on-Neymar-\ud83e\udd23-1024x755.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Before-the-game_-_We-are-not-afraid-of-Neymar_-In-the-game_-Triple-marking-on-Neymar-\ud83e\udd23-300x221.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Before-the-game_-_We-are-not-afraid-of-Neymar_-In-the-game_-Triple-marking-on-Neymar-\ud83e\udd23-768x566.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Neymar en el partido de semifinales de la UEFA Champions League (Foto: Marca)<\/figcaption><\/figure>\n\n\n\n<p>\ud835\udc04\ud835\udc25 \ud835\udc29\ud835\udc2b\ud835\udc22\ud835\udc26\ud835\udc1e\ud835\udc2b \ud835\udc28\ud835\udc2b\ud835\udc28 \ud835\udc28\ud835\udc25\ud835\udc22\u0301\ud835\udc26\ud835\udc29\ud835\udc22\ud835\udc1c\ud835\udc28<br>Los Juegos Ol\u00edmpicos de Londres 2012 hab\u00edan sido el primer intento de Neymar Jr. por conseguir la preciada medalla de oro. La canarinha llegaba armada hasta los dientes a tierras brit\u00e1nicas. Jugadores de la talla de Alex Sandro, Danilo, Marcelo, Thiago Silva, Ganso, Lucas Moura, \u00d3scar, Pato, Hulk y Leandro Dami\u00e3o integraban esa selecci\u00f3n que era dirigida por Mano Menezes.<\/p>\n\n\n\n<p>Brasil arrasaba con el rival que se le pusiera enfrente. En todos los partidos que jug\u00f3 hasta llegar a la final, los brasile\u00f1os lograron convertir 3 goles. Nada parec\u00eda frenar este tren que se dirig\u00eda a los m\u00e1s alto del podio. Sin embargo, <a href=\"https:\/\/www.mediotiempo.com\/futbol\/juegos-olimpicos-londres-2012-brasil-vs-mexico-alineaciones-goles-datos-estadisticos\" class=\"ek-link\">un doblete de Oribe Peralta ahogar\u00eda los sue\u00f1os del Scratch<\/a> y le dar\u00eda a M\u00e9xico su primera medalla de oro en f\u00fatbol masculino.<\/p>\n\n\n\n<p>Cuatro a\u00f1os m\u00e1s tarde la cita ser\u00eda en R\u00edo de Janeiro. Solo Neymar Jr. repetir\u00eda en el plantel pero, esta vez, como capit\u00e1n. <a href=\"https:\/\/elcomercio.pe\/deporte-total\/neymar-lista-brasil-juegos-olimpicos-rio-2016-431669-noticia\/#:~:text=La%20lista%20de%20convocados%20es,Luan%20(Vasco%20da%20Gama).\" class=\"ek-link\">Nombres nuevos aparecer\u00edan en la convocatoria<\/a>: experimentados como el arquero Weverton, Renato Augusto, Rafinha y Marquinhos respaldar\u00edan a nuestro protagonista. Mientras que j\u00f3venes promesas como Gabriel Jes\u00fas y \u2018Gabigol\u2019 refrescar\u00edan el ataque.<\/p>\n\n\n\n<p>La fase de grupos no se les hizo tan simple. Dos empates a cero y una victoria contundente los colocar\u00edan en el primer lugar. Luego, dos sencillos tr\u00e1mites, ante Colombia en cuartos y frente a Honduras en semifinales, los llevar\u00eda hacia la final. \u00bfEl rival? La siempre poderosa Alemania llegaba a esta instancia con 21 goles a favor en los 5 partidos previos \u201210 de ellos ante la d\u00f3cil representante de Ocean\u00eda: Fiyi\u2012 y el m\u00e1ximo artillero del torneo: Serge Gnabry.<\/p>\n\n\n\n<p>Dos potencias chocaban. En tierras cariocas, el escudo alem\u00e1n a\u00fan recordaba <a href=\"https:\/\/www.goal.com\/es-ar\/noticias\/el-7-1-de-alemania-a-brasil-en-el-mineirao-como-fue-el\/1dn8cc3lasl3d177xef9uhqijp\" class=\"ek-link\">el vergonzoso 7 a 1 del Mundial pasado<\/a>. El miedo presente ser\u00eda disipado por un tiro libre perfecto de Neymar Jr. quien, a diferencia del 2014, ahora s\u00ed estaba presente. El capit\u00e1n germano logr\u00f3 igualarlo: 1 a 1. Desde ese momento hasta el minuto 120 del tiempo suplementario nada cambi\u00f3. El ganador se definir\u00eda desde los 12 pasos.<\/p>\n\n\n\n<p>Todos convierten hasta llegar al quinto penal. Weverton logra atajar el disparo de Petersen y la definici\u00f3n para alcanzar la gloria queda en manos de nuestro protagonista. Neymar Jr. se deshace del abrazo de sus compa\u00f1eros y camina hacia el \u00e1rea para ejecutar su penal. Coge el bal\u00f3n, le da un c\u00e1lido beso y lo coloca en el punto que corresponde. Nueve pasos hacia atr\u00e1s. Manos en la cintura. El \u00e1rbitro pita. Pasos hacia la izquierda y la corrida m\u00e1s corta e importante de su vida. Golpea el bal\u00f3n y lo ajusta en el \u00e1ngulo superior izquierdo. Es un golazo. Neymar cae de rodillas al suelo, abre los brazos y mira al cielo. <a href=\"https:\/\/www.eluniverso.com\/deportes\/2016\/08\/20\/nota\/5753193\/brasil-alemania-final-juegos-olimpicos-rio-2016#:~:text=El%20pentacampe%C3%B3n%20mundial%20gan%C3%B3%20la,R%C3%ADo%20en%20el%20estadio%20Maracan%C3%A1.\" class=\"ek-link\">No puede contener el llanto: sabe que acaba de hacer historia.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Every Brazil men&#039;s football goal at Rio 2016 | Top Moments\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/_FFIGnqisJo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>Mejores momentos de Brasil en los Juegos Ol\u00edmpicos Rio 2016<\/figcaption><\/figure>\n\n\n\n<p>\ud835\udc03\ud835\udc1e\ud835\udc1b\ud835\udc2e\ud835\udc2d \ud835\udc2c\ud835\udc28\ud835\udc27\u0303\ud835\udc1a\ud835\udc1d\ud835\udc28 \ud835\udc32 \ud835\udc1d\ud835\udc1e\ud835\udc2e\ud835\udc1d\ud835\udc1a \ud835\udc1c\ud835\udc28\ud835\udc27 \ud835\udc0f\ud835\udc1a\ud835\udc2b\ud835\udc22\u0301\ud835\udc2c<br>Al a\u00f1o siguiente, luego de ganarlo todo con el Barcelona, el Par\u00eds Saint Germain se har\u00eda con sus servicios. En <a href=\"https:\/\/elpais.com\/deportes\/2017\/08\/13\/actualidad\/1502649217_137824.html\" class=\"ek-link\">su primer partido<\/a>, de visita frente al Guingamp, \u2018Ney\u2019 ya dio un destello \u20121 gol y dos asistencias\u2012 de lo que vendr\u00eda m\u00e1s adelante.<\/p>\n\n\n\n<p>Los parisinos esperaban ansiosos verlo desplegar su magia por primera vez, en vivo y en directo, con la camiseta del PSG. El 20 de agosto del 2017 el Parque de los Pr\u00edncipes desborda de hinchas y Neymar Jr. hace lo que mejor sabe: jugar al f\u00fatbol.<\/p>\n\n\n\n<p>Con cada jugada, el astro brasile\u00f1o har\u00eda vibrar a todos los aficionados. Marc\u00f3 dos goles: uno con el oportunismo de un goleador y el otro luego de regatear a tres rivales dentro del \u00e1rea. Dio dos asistencias: una de taco para el gol de Rabiot y otra en un tiro de esquina con el borde externo para la tijera de Kurzawa. El heredero del \u2018jogo bonito\u2019 se hab\u00eda metido en el coraz\u00f3n de todos en Par\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Neymar vs Toulouse Home HD 1080i (20\/08\/2017)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/N3yfSKpQ8ZA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>Mejores jugadas de Neymar en su partido de debut en el Parque de los Pr\u00edncipes<\/figcaption><\/figure>\n\n\n\n<p>A partir de ese momento, Neymar Jr. y el PSG hicieron lo que se les antoj\u00f3 en canchas galas. 3 Ligue 1, 2 Copas de Francia, 2 Copas de la Liga y 2 Supercopas demuestran la amplia superioridad que ha marcado el club a nivel nacional. Nadie, dentro de su territorio, logra hacerle frente. Sin embargo, la historia no ha sido la misma a nivel europeo.<\/p>\n\n\n\n<p>Dos ediciones consecutivas con \u2018Ney\u2019 a la cabeza en la fase de grupos, pero <a href=\"https:\/\/somosinvictos.com\/2020\/08\/18\/de-las-lesiones-a-la-final-el-emotivo-mensaje-de-neymar-tras-clasificarse-a-la-final-de-la-champions-league-con-psg\/\" class=\"ek-link\">lesionado para las fases finales<\/a>, el PSG no hab\u00eda podido superar los octavos de final. Los millones de inversi\u00f3n no daban frutos. Las cr\u00edticas a nuestro protagonista no se har\u00edan esperar.<\/p>\n\n\n\n<p>Sin embargo, este a\u00f1o, un a\u00f1o at\u00edpico para nuestro mundo y tambi\u00e9n para el planeta f\u00fatbol, ha dado el mejor resultado para el PSG. Por fin pudieron avanzar m\u00e1s all\u00e1 de los octavos de final y llegan, por primera vez en su historia, hasta el \u00faltimo partido. El domingo disputar\u00e1n la final frente al Bayern M\u00fanich y Neymar volver\u00e1 a encontrarse con viejos conocidos.<\/p>\n\n\n\n<p>Con Neymar Jr., siempre bien acompa\u00f1ado por Mbapp\u00e9, el Paris Saint Germain quiere levantar la Orejona. Para lograrlo, tendr\u00e1 que superar al poderoso equipo b\u00e1varo que viene arrollando, de manera contundente, a todo equipo que se le ponga enfrente. Un partidazo con protagonistas que ya se conocen, como \u2018Ney\u2019 y Gnabry, pero con la incertidumbre que siempre te deja el hecho de ver enfrentadas a dos potencias.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"990\" height=\"557\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/15977490355616.jpg\" alt=\"\" class=\"wp-image-3988\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/15977490355616.jpg 990w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/15977490355616-300x169.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/15977490355616-768x432.jpg 768w\" sizes=\"(max-width: 990px) 100vw, 990px\" \/><figcaption>Neymar nombrado mejor jugador de los cuartos de final de la Champions League 2019\/20 (Foto: Marca)<\/figcaption><\/figure>\n\n\n\n<p>Foto principal: Marca.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la selecci\u00f3n de f\u00fatbol m\u00e1s exitosa de la historia le faltaba un t\u00edtulo. Muchos cracks comandaron esa selecci\u00f3n ol\u00edmpica en busca de la medalla dorada, pero todos fracasaron en el intento. Parec\u00eda que el destino lo ten\u00eda todo planeado: el 20 de agosto del 2016, con la atenta mirada de 75 mil espectadores que [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":2236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[78,79],"tags":[208,163,207,209,210],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/2231"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=2231"}],"version-history":[{"count":10,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/2231\/revisions"}],"predecessor-version":[{"id":3995,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/2231\/revisions\/3995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/2236"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=2231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=2231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=2231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}