{"id":2544,"date":"2020-08-25T20:51:23","date_gmt":"2020-08-26T01:51:23","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=2544"},"modified":"2020-09-12T22:47:44","modified_gmt":"2020-09-13T03:47:44","slug":"futbol-peruano-vuelven-los-tripletes-en-el-estadio-nacional","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/futbol-peruano-vuelven-los-tripletes-en-el-estadio-nacional\/","title":{"rendered":"F\u00fatbol Peruano: Vuelven los &#8216;Tripletes&#8217; en el Estadio Nacional"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Vuelve la <a href=\"https:\/\/www.facebook.com\/LigaFutProf\/\" class=\"ek-link\">Liga 1<\/a> y, con ella, un formato que ha sido parte de la evoluci\u00f3n del f\u00fatbol.<\/h4>\n\n\n\n<p>En el mundo del Periodismo Deportivo se sol\u00eda hablar mucho del t\u00e9rmino &#8216;Triplete&#8217;. Sin embargo, hasta hace unas semanas, se hablaba de este, casi con nostalgia, como un recuerdo lejano de la \u00e9poca de los 90&#8217;s. <\/p>\n\n\n\n<p>Por esos a\u00f1os era com\u00fan que se jugaran varios partidos en un solo recinto deportivo, en un mismo d\u00eda. En su mayor\u00eda, los partidos del torneo peruano sol\u00edan jugarse en el Coloso de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Estadio_Nacional_del_Per%C3%BA#:~:text=%E2%80%8B%20Muchas%20personas%2C%20inclusive%20cronistas,al%20Ej%C3%A9rcito%20de%20los%20Andes.\" class=\"ek-link\">Jos\u00e9 D\u00edaz<\/a>, m\u00e1s conocido como Estadio Nacional<\/p>\n\n\n\n<p>Por eso la \u00faltima vez que se jug\u00f3 un triplete de partidos en el Estadio Nacional fue el 12 de septiembre de 1998. Por el Clausura, aquella vez, Municipal perdi\u00f3 2-1 ante&nbsp;Cienciano; Lawn Tennis&nbsp;venci\u00f3 2-0 Alianza Atl\u00e9tico; y Universitario gan\u00f3 1-0 a Juan Aurich.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La nueva normalidad de la <strong>Liga 1<\/strong><\/h2>\n\n\n\n<p>Nadie imaginaba que luego del Ayacucho FC vs Alianza Universidad, en el estadio Ciudad de Cuman\u00e1 del 9 de marzo, el mundo se detendr\u00eda debido a unas de las pandemias m\u00e1s devastadoras de los \u00faltimos a\u00f1os. <\/p>\n\n\n\n<p>Sin embargo, despu\u00e9s de cinco meses, la &#8216;nueva normalidad&#8217; trajo consigo algunos cambios para la vuelta del f\u00fatbol en nuestro pa\u00eds. El protocolo de seguridad implementado en nuestro pa\u00eds indica que uno de esos cambios ordena que los partidos en su totalidad se jueguen en Lima.<\/p>\n\n\n\n<p>Es por ello que hoy 25 de agosto, el pa\u00eds volvi\u00f3 a ser testigo de un &#8216;triplete&#8217; de f\u00fatbol en nuestro Estadio Nacional. Y vaya con qu\u00e9 partidos.<\/p>\n\n\n\n<p>La jornada inici\u00f3 temprano (11 a.m.) con el encuentro entre Deportivo Binacional vs Academia Cantolao. Victoria para este \u00faltimo por 2-3. Seguido del \u00abcl\u00e1sico moderno\u00bb Sporting Cristal vs Alianza Lima, que termin\u00f3 igualado a 1. Y finalizando la larga jornada, Deportivo Municipal vs Cienciano del Cusco que gan\u00f3 por la m\u00ednima diferencia. <\/p>\n\n\n\n<p>Sin duda a los periodistas de esta nueva generaci\u00f3n nos tocar\u00e1 vivir uno de los formatos que hasta hace poco cre\u00edamos no experimentar\u00edamos jam\u00e1s. Y seguramente en algunos a\u00f1os nos veamos como los actuales periodistas hablando de anta\u00f1o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conoce m\u00e1s de la historia del Estadio Nacional<\/h3>\n\n\n\n<figure class=\"wp-block-embed-youtube aligncenter wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La Historia del Estadio Nacional de Lima HD 2020\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/SQGhHvaPG5c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por eso la \u00faltima vez que se jug\u00f3 un triplete de partidos en el Estadio Nacional fue el 12 de septiembre de 1998. Por el Clausura, aquella vez, Municipal perdi\u00f3 2-1 ante Cienciano; Lawn Tennis venci\u00f3 2-0 Alianza Atl\u00e9tico; y Universitario gan\u00f3 1-0 a Juan Aurich.<\/p>\n","protected":false},"author":6,"featured_media":2559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[78,44,79],"tags":[273,181,180],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/2544"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=2544"}],"version-history":[{"count":9,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/2544\/revisions"}],"predecessor-version":[{"id":3305,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/2544\/revisions\/3305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/2559"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=2544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=2544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=2544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}