{"id":2581,"date":"2020-08-28T16:52:14","date_gmt":"2020-08-28T21:52:14","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=2581"},"modified":"2020-08-28T23:50:08","modified_gmt":"2020-08-29T04:50:08","slug":"peru-abrira-fronteras-internacionales-para-viajes-de-extrema-necesidad","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/peru-abrira-fronteras-internacionales-para-viajes-de-extrema-necesidad\/","title":{"rendered":"Per\u00fa abrir\u00e1 fronteras internacionales para viajes de extrema necesidad"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/08\/vuelos.jpg\" alt=\"\" class=\"wp-image-2583\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/08\/vuelos.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/08\/vuelos-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: El Comercio<\/figcaption><\/figure>\n\n\n\n<p><strong>El titular del MTC dio una luz de esperanza para quienes a\u00fan no han retornado a sus pa\u00edses originarios.<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">Carlos Estremadoyro, titular del <a href=\"https:\/\/www.gob.pe\/mtc\"> Ministerio de Transportes y Comunicaciones (MTC)<\/a>, asegur\u00f3 hace unos d\u00edas que no habr\u00e1 vuelos internacionales hasta julio del pr\u00f3ximo a\u00f1o. Sus declaraciones causaron zozobra para sus detractores, quienes abogaron por el turismo y el futuro incierto que le espera tras pasar tanto sin p\u00fablico extranjero; sin embargo, el d\u00eda de ayer anunci\u00f3 que existe la posibilidad de abrir las fronteras para quienes necesitaban viajar con urgencia.  <\/p>\n\n\n\n<p style=\"text-align:justify\">La entrada y salida de personas del pa\u00eds contar\u00e1 con un control estricto sanitario debido a la situaci\u00f3n que atravesamos, pero para que esa actividad inicie tendr\u00e1 que haber una reducci\u00f3n de la cantidad de infectados por <a href=\"https:\/\/www.who.int\/es\/emergencies\/diseases\/novel-coronavirus-2019\/advice-for-public\/q-a-coronaviruses\"> COVID 19 <\/a>. Hasta que no suceda eso, las restricciones seguir\u00e1n siendo las mismas y nadie podr\u00e1 ir contra las reglas. <\/p>\n\n\n\n<p style=\"text-align:justify\">Entre los requisitos estar\u00e1 el viajar por estudios, trabajo o salud.  Por otro lado, los vuelos tur\u00edsticos tendr\u00e1n que seguir a la espera de una fecha para activarse; ya que, como se dijo, priorizar\u00e1n a las personas con necesidades primarias y seg\u00fan mejore se implementar\u00e1n los viajes de descanso paulatinamente. <\/p>\n\n\n\n<p style=\"text-align:justify\">Asimismo, se\u00f1al\u00f3 que estos viajes ser\u00e1n organizados por la <a href=\"https:\/\/www.gob.pe\/rree\"> Canciller\u00eda peruana <\/a>.  El ministro asegur\u00f3 que \u201ctenemos que asegurarnos que las personas que suban a esos aviones sean sanas y cuando vengan ac\u00e1 vuelvan a pasar una prueba que les de la seguridad que son personas sanas antes que salgan a la calle\u201d.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El titular del MTC dio una luz de esperanza para quienes a\u00fan no han retornado a sus pa\u00edses originarios. Carlos Estremadoyro, titular del Ministerio de Transportes y Comunicaciones (MTC), asegur\u00f3 hace unos d\u00edas que no habr\u00e1 vuelos internacionales hasta julio del pr\u00f3ximo a\u00f1o. Sus declaraciones causaron zozobra para sus detractores, quienes abogaron por el turismo [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[45],"tags":[274,276,275],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/2581"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=2581"}],"version-history":[{"count":7,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/2581\/revisions"}],"predecessor-version":[{"id":2635,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/2581\/revisions\/2635"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=2581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=2581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=2581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}