{"id":3150,"date":"2020-09-09T02:42:50","date_gmt":"2020-09-09T07:42:50","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=3150"},"modified":"2020-09-09T02:42:53","modified_gmt":"2020-09-09T07:42:53","slug":"la-liga-de-las-naciones-2020-21-la-nueva-apuesta-europea","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/la-liga-de-las-naciones-2020-21-la-nueva-apuesta-europea\/","title":{"rendered":"La Liga de las Naciones 2020-21, la nueva apuesta europea"},"content":{"rendered":"\n<p>La UEFA Nations League, UEFA-Nationenliga, Ligue des nations de l&#8217;UEFA, Liga das Na\u00e7\u00f5es da UEFA o simplemente <a href=\"https:\/\/www.uefa.com\/uefanationsleague\/\" class=\"ek-link\">Liga de las Naciones de la UEFA<\/a>, est\u00e1 a punto de iniciar y, con ella, nos trae un simp\u00e1tico y algo complejo torneo europeo que busca terminar con los partidos amistosos en fecha FIFA que las selecciones de dicho continente sol\u00edan disputar cuando no se jugaba la Eurocopa o las Eliminatorias para el Mundial. Y no es para menos. Mientras el f\u00fatbol en sus distintas categor\u00edas se reinventa, el continente que ha ganado las \u00faltimas cuatro Copas del Mundo sabe que tiene que mantenerse a la vanguardia en el deporte rey. \u00bfQu\u00e9 nos trae este torneo en su segunda edici\u00f3n?<\/p>\n\n\n\n<p><strong>Europa a la vanguardia<\/strong><br>Tanto la UEFA como las 55 federaciones europeas que la conforman, caer\u00edan en cuenta que los amistosos que se juegan en fecha FIFA mientras no se compite por alg\u00fan torneo importante, como la Eurocopa o las eliminatorias al Mundial, no eran del todo productivos. Es as\u00ed que, bajo la premisa de mejorar la calidad y el prestigio del f\u00fatbol a nivel de selecciones, habr\u00eda que hacer algo por <a href=\"https:\/\/es.uefa.com\/uefanationsleague\/history\/2019\/\" class=\"ek-link\">cambiar el panorama europeo<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-1-1.jpg\" alt=\"\" class=\"wp-image-3153\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-1-1.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-1-1-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>La UEFA Nations League, en b\u00fasqueda de elevar la competencia europea \/ Fuente: Diario AS<\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/es.wikipedia.org\/wiki\/Liga_de_las_Naciones_de_la_UEFA\" class=\"ek-link\">La Liga de Naciones<\/a>, que viera sus primeras luces en la Reuni\u00f3n Estrat\u00e9gica de Chipre en 2011, termin\u00f3 por adaptarse de manera un\u00e1nime en el XXXVIII Congreso Ordinario de la UEFA en Astan\u00e1 el 27 de marzo de 2014. As\u00ed, este nuevo formato tendr\u00eda luz verde. \u00bfLa primera aventura? En la temporada 2018-19.<\/p>\n\n\n\n<p>En aquella ocasi\u00f3n, y donde radica su complejidad, el torneo constar\u00eda de cuatro ligas (A, B, C y D): la primera y segunda con 12 equipos, la tercera con 15 y una cuarta con 16. Todas tendr\u00edan cuatro grupos donde, naturalmente, las de las ligas A y B ser\u00edan de tres equipos por grupo, la liga C, de un grupo de tres y el resto de cuatro, para que finalmente la liga D est\u00e9 conformada por cuadro grupos de cuatro. \u00bfC\u00f3mo que s\u00f3lo el torneo peruano es complicado?<\/p>\n\n\n\n<p>\u00bfY qu\u00e9 pasaba luego de esta fase de grupos? Los primeros de cada grupo pasar\u00edan a jugar los ansiados \u2018play-off\u2019 y los \u00faltimos descender\u00edan. \u00bfC\u00f3mo en una liga com\u00fan y corriente? Tal cual.<\/p>\n\n\n\n<p>En estoy \u2018play-off\u2019, los equipos se emparejar\u00edan en llaves desde la estancia de semifinales. Los ganadores jugar\u00e1n la final y los perdedores se disputar\u00e1n el tercer puesto de su liga.<\/p>\n\n\n\n<p><a href=\"https:\/\/es.wikipedia.org\/wiki\/Liga_de_las_Naciones_de_la_UEFA_2018-19\" class=\"ek-link\">En su primera edici\u00f3n<\/a>, aquella del 2018-19, tuvo a su primer campe\u00f3n a un Portugal que ven\u00eda de ganar la Euro 2016 y de quedar eliminados en octavos en Rusia 2018, pero que supo sortear como primero el grupo A3, para luego ganarle a Suiza en la semifinal, a Pa\u00edses Bajos en la final y as\u00ed coronarse en la Liga de Naciones inaugural.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-3.jpg\" alt=\"\" class=\"wp-image-3154\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-3.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-3-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Portugal campe\u00f3n de la edici\u00f3n inaugural de la Nations League 2018-19 \/ Fuente: Eurosport<\/figcaption><\/figure>\n\n\n\n<p>\u00bfLa gran sorpresa? El descenso a la liga B de Alemania y la vigente subcampeona del mundo, Croacia.<\/p>\n\n\n\n<p><strong>Una chance mundial<\/strong><br>Adem\u00e1s de la constante competencia que producir\u00eda el aumento en el nivel futbol\u00edstico de las selecciones europeas, este torneo tambi\u00e9n le significar\u00eda una chance al campe\u00f3n, subcampe\u00f3n y tercer lugar y a los sucesivos puestos, de clasificar a la pr\u00f3xima Copa del Mundo, la cual contar\u00eda con 13 equipos europeos.<\/p>\n\n\n\n<p>Pues, as\u00ed como las eliminatorias europeas se juegan en diez grupos y de estos cada uno de los primeros obtiene una plaza directa para jugar el Mundial; los segundos (10 equipos en total) tendr\u00edan la oportunidad de una chance m\u00e1s. A ellos se sumar\u00edan dos equipos de la Liga de las Naciones que ser\u00edan el campe\u00f3n y subcampe\u00f3n del torneo siempre y cuando estos no hayan clasificado ya o hayan quedado segundos en los grupos de Eliminatorias. Naturalmente, los due\u00f1os de estos puestos al repechaje ser\u00edan los siguientes en la lista. Todo una mara\u00f1a que est\u00e1n dispuestos a entender y disputar por un lugar en el m\u00e1ximo torneo del f\u00fatbol mundial.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-2.jpg\" alt=\"\" class=\"wp-image-3155\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-2.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-2-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>La preciada copa, que les dar\u00eda una chance de jugar el Mundial \/ Fuente <\/figcaption><\/figure>\n\n\n\n<p><strong>Lo que se viene<\/strong><br><a href=\"https:\/\/es.uefa.com\/uefanationsleague\/news\/0253-0d81d5cbd33f-f43208e06088-1000--uefa-nations-league-todo-lo-que-necesitas-saber\/?referrer=%2Fuefaeuro%2Fnews%2Fnewsid%3D2079588\" class=\"ek-link\">Para la Liga de Naciones 2020-21<\/a>, las reglas cambiar\u00edan un poco, pues, bajo el concepto de reducir a\u00fan m\u00e1s los amistosos en fecha FIFA y de mejorar la equidad deportiva, el nuevo formato constar\u00eda a\u00fan de cuatro ligas (A, B, C y D); las tres primeras con diecis\u00e9is equipos (cuatro grupos de cuatro) y la \u00faltima con los restantes siete (un grupo de tres y el otro de cuatro). El superar esta fase como primeros en su grupo les permitir\u00e1 jugar los \u2018play-off\u2019 y los \u00faltimos de cada conjunto descender\u00e1n a la liga inferior. Lo mismo, pero diferente.<\/p>\n\n\n\n<p>En esta ocasi\u00f3n, los el grupo A1 estar\u00e1 conformado por Pa\u00edses Bajos, Italia, Bosnia Herzegovina y Polonia; el grupo A2 por Inglaterra, B\u00e9lgica, Dinamarca e Islandia; el grupo A3, y el que apunta a ser el de la muerte, conformado por Portugal, Francia, Suecia y Croacia; mientras que el grupo A4, por Suiza, Espa\u00f1a, Ucrania y Alemania.<\/p>\n\n\n\n<p>La fase de grupos se jugar\u00e1 durante lo que resta del 2020. Las jornadas 1 y 2 se jugar\u00e1n entre el 3 y 8 de septiembre, las jornadas 3 y 4, entre el 10 y 14 de octubre, las jornadas 5 y 6, entre el 14 y 18 de noviembre. Mientras que el Final Four \u00faltimo se disputar\u00e1, salvo sorpresas, entre septiembre u octubre del 2021.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-4.jpg\" alt=\"\" class=\"wp-image-3157\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-4.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/Nations-league-4-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Los grupos de la segunda edici\u00f3n de la UEFA Nations League \/ Fuente: Timejust<\/figcaption><\/figure>\n\n\n\n<p>Las bases est\u00e1n puestas, los equipos listos y, aunque por\nahora el p\u00fablico en las gradas no es a\u00fan permitida, no nos impedir\u00e1 disfrutar\nde f\u00fatbol internacional de calidad. A ponerse las pilas la Conmebol y, de alg\u00fan\nmodo, replicar un torneo como este y mejorar las \u00faltimas campa\u00f1as mundialistas.\nHasta entonces, a deleitarse con el deporte rey, esta vez, europeo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La UEFA Nations League, UEFA-Nationenliga, Ligue des nations de l&#8217;UEFA, Liga das Na\u00e7\u00f5es da UEFA o simplemente Liga de las Naciones de la UEFA, est\u00e1 a punto de iniciar y, con ella, nos trae un simp\u00e1tico y algo complejo torneo europeo que busca terminar con los partidos amistosos en fecha FIFA que las selecciones de dicho continente sol\u00edan disputar cuando no se jugaba la Eurocopa o las Eliminatorias para el Mundial. Y no es para menos. Mientras el f\u00fatbol en sus distintas categor\u00edas se reinventa, el continente que ha ganado las \u00faltimas cuatro Copas del Mundo sabe que tiene que mantenerse a la vanguardia en el deporte rey. \u00bfQu\u00e9 nos trae este torneo en su segunda edici\u00f3n?<\/p>\n","protected":false},"author":15,"featured_media":3159,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[78,79],"tags":[423,422,421],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3150"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=3150"}],"version-history":[{"count":5,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3150\/revisions"}],"predecessor-version":[{"id":3161,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3150\/revisions\/3161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/3159"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=3150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=3150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=3150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}