{"id":3310,"date":"2020-09-13T13:49:32","date_gmt":"2020-09-13T18:49:32","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=3310"},"modified":"2020-09-13T13:57:54","modified_gmt":"2020-09-13T18:57:54","slug":"james-rodriguez-el-hombre-de-confianza-de-carlo-ancelotti","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/james-rodriguez-el-hombre-de-confianza-de-carlo-ancelotti\/","title":{"rendered":"James Rodr\u00edguez, el hombre de confianza de Carlo Ancelotti"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"> \u00ab<em><strong>James Rodr\u00edguez merece jugar la Premier. Mostrar\u00e1 toda la calidad que tiene<\/strong><\/em>\u00ab, vaticin\u00f3 Carlo Ancelotti, el hombre que m\u00e1s fe le tiene al colombiano.<\/h4>\n\n\n\n<p>En la victoria del <a href=\"https:\/\/www.facebook.com\/EvertonOficial22\/\" class=\"ek-link\">Everton<\/a> ante <a href=\"https:\/\/www.facebook.com\/COYSFootball.London\/\" class=\"ek-link\">Tottenham<\/a> por la fecha 1 de la Premier League, James hizo su debut en la liga inglesa. Jug\u00f3 91 minutos y dej\u00f3 buenas impresiones. Al momento de ser reemplazado, la sonrisa de satisfacci\u00f3n era evidente en el abrazo eterno entre el colombiano y Ancelotti, quien confi\u00f3 en \u00e9l por tercera vez.<\/p>\n\n\n\n<p>James Rodr\u00edguez lleg\u00f3 a Inglaterra para unirse por tercera vez al entrenador italiano.<\/p>\n\n\n\n<p>La primera vez que estuvieron juntos fue en la temporada 2914-15 en el <a href=\"https:\/\/www.facebook.com\/RealMadrid\/\" class=\"ek-link\">Real Madrid<\/a>.  En el club merengue, James disput\u00f3 44 partidos, 3.524 minutos y 17 goles (un gol cada 207 minutos) en una temporada que los dej\u00f3 campeones de la Supercopa de Europa y el Mundial de Clubes. <\/p>\n\n\n\n<p>Tres a\u00f1os despu\u00e9s volvieron a juntarse en <a class=\"ek-link ek-link\" href=\"https:\/\/www.facebook.com\/fcbayern.es\/\">Bayern Munich. Al llegar al f\u00fatbol alem\u00e1n, James se lesion\u00f3 y se perdi\u00f3 los primeros cuatros partidos de la liga. Con camiseta &#8216;b\u00e1vara&#8217; debut\u00f3 el 9 de setiembre de 2017. Jug\u00f3 12 minutos y luego disput\u00f3 cuatro partidos seguidos antes de que Carlo Ancelotti fuera despedido tras perder 3-0 ante el PSG por Champions League. <\/a><\/p>\n\n\n\n<p>En total, James ha disputado 49 partidos bajo al direcci\u00f3n de Carlo Ancelotti, y ha anotado 18 goles. Sin embargo all\u00ed no termina todo, ya que la confianza del italiano radica tambi\u00e9n en las asistencias que dio James, 14 en total: 13 con Real Madrid y 1 con Bayern Munich.<\/p>\n\n\n\n<p>En el f\u00fatbol ingl\u00e9s, nuevamente bajo la direcci\u00f3n de Ancelotti, James ya disput\u00f3 91 minutos y la sensaci\u00f3n de que Everton est\u00e1 para grandes cosas esta temporada.<\/p>\n\n\n\n<p><strong>Mira aqu\u00ed el compacto de James Rodr\u00edguez en su debut con camiseta de Everton.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"James Rodr\u00edguez Everton Debut vs Tottenham (13\/09\/2020)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/DDlHTP-Ktps?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La primera vez que estuvieron juntos fue en la temporada 2914-15 en el Real Madrid.  En el club merengue, James disput\u00f3 44 partidos &#8230;<\/p>\n","protected":false},"author":6,"featured_media":3317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[78,79,331],"tags":[438,437,436],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3310"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=3310"}],"version-history":[{"count":8,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3310\/revisions"}],"predecessor-version":[{"id":3319,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3310\/revisions\/3319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/3317"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=3310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=3310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=3310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}