{"id":3866,"date":"2020-09-15T17:33:15","date_gmt":"2020-09-15T22:33:15","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=3866"},"modified":"2020-09-15T19:05:53","modified_gmt":"2020-09-16T00:05:53","slug":"un-solo-corazon-artistico","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/un-solo-corazon-artistico\/","title":{"rendered":"Un solo coraz\u00f3n art\u00edstico"},"content":{"rendered":"\n<p>La Escuela Nacional Superior Aut\u00f3noma de Bellas Artes del Per\u00fa ha sido y -contin\u00faa siendo- cuna de grandes artistas tales como <a href=\"http:\/\/bellasartesperu.tripod.com\/id24.html\" class=\"ek-link\">Jos\u00e9 Sabogal<\/a>, <a href=\"http:\/\/www.elperuano.pe\/noticia-artista-polifacetico-54199.aspx\" class=\"ek-link\">Juan Manuel Ugarte<\/a>, <a href=\"https:\/\/limagris.com\/miguel-baca-rossi-la-materia-cobra-vida-arte-e-historia-modeladas-retrospectiva-1917-2016\/\" class=\"ek-link\">Miguel Baca Rossi<\/a>, entre otros.<\/p>\n\n\n\n<p>Una de las cosas que estos pintores tienen en com\u00fan es el retratar la dicotom\u00eda de la sociedad peruana: la belleza de su cultura y las luchas sociales. Crear arte puede ser un proceso individual en primera instancia, pero al fin y al cabo se sostiene en base a la construcci\u00f3n de identidades sociales compartidas, as\u00ed como el intercambio cultural entre artistas; a\u00fan m\u00e1s en periodos tan inestables como los que se han vivido y contin\u00faan viviendo.<\/p>\n\n\n\n<p>Por ello, resulta necesario destacar la importancia de los colectivos art\u00edsticos. La propuesta de la exposici\u00f3n \u201cDel individuo al ser social: colectividades art\u00edsticas desde <a href=\"https:\/\/ensabap.edu.pe\/ensabap\/\" class=\"ek-link\">Bellas Artes<\/a>\u201d, compuesta por colectivos art\u00edsticos que se crearon en la escuela, representa la evoluci\u00f3n de la creaci\u00f3n individual al trabajo art\u00edstico colectivo en el Per\u00fa.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/colectivo-artistico-2.png\" alt=\"\" class=\"wp-image-3936\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/colectivo-artistico-2.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/colectivo-artistico-2-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fotograf\u00eda por Jazm\u00edn Flores.<\/figcaption><\/figure>\n\n\n\n<p>El arte individual ha estado presente a lo largo del tiempo; sin embargo, los colectivos art\u00edsticos en el Per\u00fa empezaron a configurarse como tal en la d\u00e9cada de los 60\u2019, impulsados por un cambio radical en la sociedad peruana en el cual el sujeto art\u00edstico empieza a difuminarse en funci\u00f3n a una colectividad art\u00edstica. En esta etapa, se dio pie a exponer las caracter\u00edsticas de la sociedad y la cultura popular de ese entonces a trav\u00e9s de recortes de peri\u00f3dicos y fotograf\u00edas de las calles de Lima.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/colectivos-artisticos-3.png\" alt=\"\" class=\"wp-image-3938\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/colectivos-artisticos-3.png 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/colectivos-artisticos-3-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fotograf\u00eda por Jazm\u00edn Flores.<\/figcaption><\/figure>\n\n\n\n<p>En la etapa de los 80\u2019 y 90\u2019, se aprecian ilustraciones, fotograf\u00edas y v\u00eddeos experimentales que documentan los inicios del trabajo colectivo art\u00edstico. En los 80\u2019, las agrupaciones escasearon, retra\u00eddas por las represiones pol\u00edticas de las sombras del terrorismo; sin embargo, a partir de los 90\u2019, surgieron nuevos colectivos que cuestionaban la crisis nacional y exploraban nuevas metodolog\u00edas de trabajo art\u00edstico.<\/p>\n\n\n\n<p>En la primera d\u00e9cada del siglo XXI, aparecieron colectivos comunitarios m\u00e1s ligados a la acci\u00f3n social y a la b\u00fasqueda de la identidad cultural; por ello, se aprecian impresiones y v\u00eddeos que documental aquel trabajo colectivo experimental.<\/p>\n\n\n\n<p>En los \u00faltimos a\u00f1os, lo colectivo ha sido conceptualizado como una exploraci\u00f3n natural a trav\u00e9s de experiencias transdisciplinarias; por ello, se aprecian instalaciones que contienen esculturas, fotograf\u00edas y otros objetos que en conjunto forman un peque\u00f1o sistema que representa la cultura popular y social de distintos espacios p\u00fablicos peruanos.<\/p>\n\n\n\n<p>Siguiendo la misma l\u00ednea de exploraci\u00f3n art\u00edstica, la calle toma protagonismo como el espacio p\u00fablico id\u00f3neo para la representaci\u00f3n de un mismo sentir, esto es, el espacio con la capacidad de albergar expresiones art\u00edsticas con los ideales colectivos como \u00fanica posible barrera. Muestra de ello son la instalaci\u00f3n de objetos propios de la calle: una bandera y un mural de grafiti, mu\u00f1ecos festivos, ilustraciones de una familia de animales, etc. Todos ellos llenos de color y movimiento, expresando la vitalidad y uni\u00f3n que caracteriza el sentir colectivo.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Escuela Nacional Superior Aut\u00f3noma de Bellas Artes del Per\u00fa ha sido y -contin\u00faa siendo- cuna de grandes artistas tales como Jos\u00e9 Sabogal, Juan Manuel Ugarte, Miguel Baca Rossi, entre otros. Una de las cosas que estos pintores tienen en com\u00fan es el retratar la dicotom\u00eda de la sociedad peruana: la belleza de su cultura [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":3888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,34],"tags":[522],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3866"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=3866"}],"version-history":[{"count":7,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3866\/revisions"}],"predecessor-version":[{"id":3942,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3866\/revisions\/3942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/3888"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=3866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=3866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=3866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}