{"id":3913,"date":"2020-09-15T18:11:33","date_gmt":"2020-09-15T23:11:33","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=3913"},"modified":"2020-09-15T18:11:38","modified_gmt":"2020-09-15T23:11:38","slug":"el-mausoleo-senderista-como-honrar-a-los-caidos","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/el-mausoleo-senderista-como-honrar-a-los-caidos\/","title":{"rendered":"El Mausoleo Senderista: \u00bfC\u00f3mo honrar a los ca\u00eddos?"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/s.jpg\" alt=\"\" class=\"wp-image-3920\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/s.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/s-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Foto: RPP<\/figcaption><\/figure>\n\n\n\n<p>Una ma\u00f1ana m\u00e1s de trabajo, una m\u00e1s en que los rezos, recuerdo que alimenta a los muertos, le dar\u00e1 unas monedas a Alfredo S\u00e1enz. Este, hombre de edad avanzada, natural de Cajamarca, avanza hacia la cima de la loma en que se encuentra el cementerio Pr\u00f3ceres 19 de julio. Es el 29 de diciembre del a\u00f1o 2018. <\/p>\n\n\n\n<p>-Polic\u00edas estaban en la puerta, a nadie dejaron pasar ese d\u00eda, joven.<br> -\u00bfY luego lo destruyeron [al Mausoleo Senderista]?<br> -S\u00ed, tempranito llegaron con el tractor y lo botaron todo.<br> <\/p>\n\n\n\n<p>Desde el mismo lugar de los hechos, el reportero de RPP Noticias, c\u00e1mara en mano apuntando a su rostro, relata los \u00faltimos acontecimientos, mientras se ve la maquinaria y la gran cantidad de efectivos policiales que lo rodean: \u00abNos encontramos en el distrito de Comas, para ser m\u00e1s espec\u00edficos, en lo m\u00e1s alto del cementerio Pr\u00f3ceres 19 de julio, donde precisamente hasta este momento se encontraba ubicado el Mausoleo Senderista. Este lugar en el cual rend\u00edan culto a sus muertos, a los cuerpos de terroristas fallecidos en la masacre de El Front\u00f3n. Como bien recordamos este Mausoleo hab\u00eda generado una gran indignaci\u00f3n y una gran pol\u00e9mica, debido a que se encontraba rindiendo homenaje y apolog\u00eda sobre todo con un tema tan sensible, como lo es el terrorismo en nuestro pa\u00eds\u00bb, sentenciaba el joven reportero, y posteriormente pasaba a explicar el tema a su manera.<\/p>\n\n\n\n<p><br>En ese momento, tal vez cruz\u00e1ndose con Alfredo S\u00e1enz, a la entrada del cementerio, Alicia Huaman\u00ed pugnaba por entrar. Les dec\u00eda a los polic\u00edas que era familiar de quien iba a ser retirado de la construcci\u00f3n que iban a destruir. <\/p>\n\n\n\n<p><br>Es posible imaginar alg\u00fan grito, quiz\u00e1s un empuj\u00f3n y esa pared de escudos que siempre repelen a las manifestaciones. Dentro, en un acto, r\u00e1pidamente, los ocho cuerpos fueron sacados del Mausoleo, reubicados en otros sitios y el lugar, las cincuenta tumbas, reducidas a pedazos de concreto, los mismos que el 1 de noviembre se adornan con aquella corona\u2026<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>Nery Ch\u00e1vez est\u00e1 por terminar, vienen a colaci\u00f3n los cuerpos prometidos por el Estado. Ella refiere que en las negociaciones con la Fiscal\u00eda, posterior a la entrega de los 7 cuerpos el 5 de agosto, aseguraban que luego les ser\u00edan entregados 35 restos mortales, pertenecientes a los demas deudos de El Front\u00f3n. Esa es la raz\u00f3n, nos dice, por la cual se mand\u00f3 a construir el Mausoleo con cincuenta tumbas. <\/p>\n\n\n\n<p><br>Posterior a ello, con la lucidez y facilidad de palabra que la caracterizan y haciendo el adem\u00e1n de estar contando un secreto, refiere que cada a\u00f1o, desde 1986, los familiares iban al muelle  del Callao que est\u00e1 al frente del Front\u00f3n a rendir tributo a su manera a sus muertos, que se sub\u00edan a balsas como anta\u00f1o, pero esta vez a lanzar flores y l\u00e1grimas al oc\u00e9ano. <\/p>\n\n\n\n<p>-\u201cEn el mar treinta a\u00f1os hemos ido. Todos los familiares cada a\u00f1o. Todos los 19 de junio hemos ido. Y d\u00edgame, \u00bfah\u00ed han dicho algo? \u00bfhan hecho alg\u00fan problema? [\u2026] \u00bfPor qu\u00e9 ayer 30 a\u00f1os lo han permitido y luego no lo han permitido cuando se ha hecho en tierra? \u00bfcu\u00e1l es la diferencia? Si lo que quieren los familiares es tener un lugar donde velar, donde rendir su tributo, donde expresar su dolor, d\u00f3nde ponerle una velita. \u00bfNo es as\u00ed lo que se acostumbra?\u201d<\/p>\n\n\n\n<p><br>Nery es una mujer que recuerda, que mira y a\u00fan posee esa ansia de responder, de ir m\u00e1s all\u00e1 del acto de la palabra, e intenta, con una oratoria clara, de explicarnos un drama del que a\u00fan estamos haci\u00e9ndonos una idea. Antes de despedirse, nos lee con su voz potente una carta incompleta que dej\u00f3 su hermana hoy difunta: <\/p>\n\n\n\n<p><br> -\u201cPido que se acuse y juzgue al expresidente Alan Garc\u00eda P\u00e9rez por haber participado del asesinato de mi hijo Peter Cruz Ch\u00e1vez en calidad de rendido y de 250 presos m\u00e1s en las masacres de Lurigancho, El Front\u00f3n y el Callao el 18 de junio de 1986\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>La plaza en que se encuentra la municipalidad de Comas tiene un monumento en medio: una especie de obelisco dedicado los \u201cm\u00e1rtires de Lucanamarca\u201d, en alusi\u00f3n a las 69 personas asesinadas por Sendero Luminoso en 1983. Al llegar a esta, en la puerta, una mujer se dirige al que cuida la puerta, extra\u00f1amente lo llama \u201ccompa\u00f1ero, camarada\u201d, y luego pasa riendo. Uno piensa en que estos rasgos, los gestos, los monumentos, llevan siempre a un tema del que no se habla mucho, pero que permanece presente en el aire: la \u00e9poca del terror. Uno busca algunas respuestas: \u00bfcu\u00e1l es la postura municipal?, \u00bffue genuino aquel af\u00e1n por cumplir las leyes?, \u00bfse justificaba la demolici\u00f3n del conjunto de tumbas?, \u00bfse actu\u00f3, de verdad, humanamente en este caso?<\/p>\n\n\n\n<p><br> Nadie quiere conversar, las respuestas van desde un \u201ceso ya pas\u00f3, ac\u00e1 no le van a decir nada\u201d, hasta un \u201cvaya a la biblioteca nacional, ah\u00ed est\u00e1n los peri\u00f3dicos, revise ah\u00ed, ya todo est\u00e1 publicado\u201d. Contestaciones que poco aportan a esta primera aproximaci\u00f3n. Sin embargo, alguien dice: \u201cmejor vaya al anexo N\u00b01, en el paradero 41, ah\u00ed est\u00e1 la oficina de cementerios, ah\u00ed que le expliquen\u201d. Una pista, al menos. En esa oficina me encuentro con una se\u00f1ora de lentes, cabellos canos y gesto serio, detr\u00e1s de un pupitre, frente a una computadora, quien me dice:<\/p>\n\n\n\n<p>-No le puedo atender as\u00ed nom\u00e1s. Si usted fuera familiar es otra cosa, pero como usted es estudiante debe pedir acceso a la informaci\u00f3n. Presenta una solicitud simple en mesa de partes, gerencia me autoriza a m\u00ed y ah\u00ed podemos conversar, si es posible hoy.<\/p>\n\n\n\n<p><br>Pierdo casi dos horas en ir de mesa de partes a la subgerencia de tal y cual asunto. Finalmente logr\u00f3 convencer a la se\u00f1ora, encargada de registrar los pagos y de agilizar los tr\u00e1mites de entierro no solo en el cementerio Pr\u00f3ceres 19 de Julio sino en los otros dos que existen en Comas. Me explica que en primer lugar, existe una ley de cementerios, que los entierros deben cumplir con lo que all\u00ed se dicta. Luego me dice que hay una ordenanza municipal, la 366. Disfraz\u00f3 las primeras preguntas de ingenuidad, y voy por las ramas. Consigo saber que algunos de los requisitos para ser enterrado en cualquiera de los tres cementerios son el acta de defunci\u00f3n certificada y el pago de 200 soles si el entierro es bajo tierra y de 200 m\u00e1s si es en nicho.<br> <\/p>\n\n\n\n<p>\u00bfY para tener un mausoleo?, le pregunt\u00f3. Me dice que se necesitan ciertas cosas. Primero, la solicitud al alcalde; segundo, los planos de la estructura y la distribuci\u00f3n de los nichos certificados por un profesional; tercero, el DNI del solicitante; cuarto, la relaci\u00f3n de los beneficiarios (los muertos); y quinto, el pago del derecho, que incluye una inspecci\u00f3n t\u00e9cnica y que es de tres mil soles. \u00bfY qu\u00e9 pas\u00f3 con el que destruyeron?, le digo, yendo al tema. Me dice que esos nichos fueron construidos por los familiares, que no cumplieron con las especificaciones y que, en todo caso, estuvieron ah\u00ed por orden de la Fiscal\u00eda. Luego me dice: \u201cpero ese no fue el problema de fondo, el problema de fondo era que ah\u00ed anualmente hac\u00edan sus reuniones y manifestaciones, ese fue el detonante, porque si hablamos de mausoleos que cumplen sus requisitos, casi la mayor\u00eda de los cementerios que tienen mausoleos no han cumplido con la formalizaci\u00f3n de su estructura, (\u2026) ni siquiera eso  que demolieron, ni siquiera los que hay en pie han cumplido con esa formalidad, por desconocimiento\u2026\u00bb. <br> <\/p>\n\n\n\n<p>\u201cEl problema de fondo era que (\u2026) hac\u00edan sus reuniones y manifestaciones\u201d, resuena en mi cabeza, y recuerdo las palabras del rezador, de don Alfredo, cuando me dijo pr\u00e1cticamente lo mismo: \u201ces que hicieron esc\u00e1ndalo, joven, si calladitos hubieran tra\u00eddo a sus muertos, nadie hubiera dicho nada, mucho esc\u00e1ndalo hac\u00edan\u201d. Hacia el final de la breve entrevista con la funcionaria, ella me explica que una cosa es la norma y otra la realidad. Que en cementerios como el Pr\u00f3ceres 19 de Julio, se est\u00e1 luchando por la formalizaci\u00f3n de las tumbas. Que no se sabe ni siquiera cu\u00e1ntos mausoleos hay en pie y finalmente me expresa que desde su punto de vista, esto ha sido por la presi\u00f3n medi\u00e1tica, que no se cumpli\u00f3 incluso con la constituci\u00f3n y que as\u00ed son las cosas. Nada m\u00e1s.<br> <\/p>\n\n\n\n<p>La legalidad. Ese tema, el que fue finalmente el motivo por el cual el Mausoleo fue derribado, se tambalea con lo que se ve en la realidad. \u00bfD\u00f3nde m\u00e1s se aplica la ley?, \u00bfcu\u00e1ntas de las miles de tumbas en los cementerios, de los mausoleos, requieren ser, si nos ponemos estrictos, formalizadas o derribados?, \u00bfc\u00f3mo es que hemos terminado aqu\u00ed, sobre los escombros?<br> <\/p>\n\n\n\n<p>Alberto de Belaunde, orgulloso de su autor\u00eda para la modificaci\u00f3n de la Ley de Cementerios, menciona en una entrevista con Wayka que \u201cesta no es una ley con nombre propio\u201d y que \u201cTenemos que acostumbrarnos a cumplir las normas\u201d. Asimismo, el excongresista dice que esta ley ayudar\u00e1 a la regulaci\u00f3n de otros mausoleos construidos ilegalmente. Sin embargo, cabe preguntarse, \u00bfera en realidad la finalidad de la modificaci\u00f3n de la ley?, \u00bfsolo se buscaba tener una mejor manera  en que la municipalidad administre sus cementerios?, \u00bfera necesario darle esa potestad de demoler una construcci\u00f3n para que haya una mejor regulaci\u00f3n? Si es as\u00ed, \u00bfpor qu\u00e9 solo se aplic\u00f3 en el mausoleo edificado por los familiares de las v\u00edctimas de la matanza de los penales?, \u00bfpor qu\u00e9 solo algunos \u201ctenemos que acostumbrarnos a cumplir las normas\u201d?, \u00bfpor qu\u00e9?<br> <\/p>\n\n\n\n<p>\u201c\u00bfPor qu\u00e9?\u201d es lo que debemos preguntarnos para seguir con este oficio, que, a veces llega a ser tan cruel como la vida misma, pues el precio de contar esta historia es llevar la carga para siempre. Cuestionarse muchas cosas: \u00bfqu\u00e9 es una v\u00edctima?, \u00bfqui\u00e9n tiene el poder de decidir?, \u00bfc\u00f3mo tratar con quienes exigen justicia, herederos de una cuota, cierta o falsa, justa o injustamente, de terror? Pienso en que el periodismo, si en algo vale, es para plantear las preguntas necesarias y nada m\u00e1s. Nada de respuestas, solo hechos, solo im\u00e1genes para quien quiera ver. <\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Comas: inician demolici\u00f3n de mausoleo senderista\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/GqjPMpb-DZo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>M\u00e1s sobre el mausoleo senderista.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una ma\u00f1ana m\u00e1s de trabajo, una m\u00e1s en que los rezos, recuerdo que alimenta a los muertos, le dar\u00e1 unas monedas a Alfredo S\u00e1enz. Este, hombre de edad avanzada, natural de Cajamarca, avanza hacia la cima de la loma en que se encuentra el cementerio Pr\u00f3ceres 19 de julio. Es el 29 de diciembre del [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":3920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[359],"tags":[455],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3913"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=3913"}],"version-history":[{"count":4,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3913\/revisions"}],"predecessor-version":[{"id":3921,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/3913\/revisions\/3921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/3920"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=3913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=3913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=3913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}