{"id":4063,"date":"2020-09-16T00:17:46","date_gmt":"2020-09-16T05:17:46","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=4063"},"modified":"2020-09-16T00:17:49","modified_gmt":"2020-09-16T05:17:49","slug":"las-herramientas-multimedia-como-recurso-para-visibilizar-las-problematicas-medioambientales-en-el-periodismo-digital","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/las-herramientas-multimedia-como-recurso-para-visibilizar-las-problematicas-medioambientales-en-el-periodismo-digital\/","title":{"rendered":"Las herramientas multimedia como recurso para visibilizar las problem\u00e1ticas medioambientales en el periodismo digital"},"content":{"rendered":"\n<p>En el paso del periodismo tradicional al periodismo digital, la mayor\u00eda de periodistas ambientales se ha visto en la necesidad de implementar herramientas multimedia digitales para darle mayor \u00e9nfasis a sus contenidos y que los lectores puedan tener una mejor experiencia. <\/p>\n\n\n\n<p>En entrevista para <a href=\"https:\/\/periodismoaet.wixsite.com\/ambientemultimedia\" class=\"ek-link\">Periodismo Aet<\/a>, conversamos con Jackeline C\u00e1rdenas Ipenza periodista ambiental para recoger sus experiencias al trabajar con herramientas multimedia y las ventajas que \u00a0les han otorgado estas en su proyecto period\u00edstico <a href=\"https:\/\/convoca.pe\/expedientetoxico\/nazareth\/\" class=\"ek-link\">Nazareth<\/a> .<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"614\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/ipenza-1024x614.jpg\" alt=\"\" class=\"wp-image-4068\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/ipenza-1024x614.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/ipenza-300x180.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/ipenza-768x461.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/ipenza-750x450.jpg 750w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/09\/ipenza.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption><em><a href=\"https:\/\/convoca.pe\/expedientetoxico\/nazareth\/#\" class=\"ek-link\">Nazareth olvidada dos veces<\/a><\/em>, proyecto period\u00edstico de Jackeline C\u00e1rdenas Ipenza<\/figcaption><\/figure>\n\n\n\n<p>\n\nJackeline C\u00e1rdenas Ipenza, periodista ambiental de medio digital <a href=\"https:\/\/convoca.pe\/\">Convoca<\/a> nos habl\u00f3 sobre las ventajas de usar herramientas multimedia digitales en el periodismo ambiental y de c\u00f3mo aportan a entender mejor el contexto de la historia presentada. Ella nos menciona que las herramientas multimedia ofrecen una gran ventaja para presentar una historia en la web a diferencia de un diario. \u201cEn el reportaje web es posible presentar im\u00e1genes en movimiento o audios que aportan en la experiencia de lector y causan una sensaci\u00f3n de realismo.\u201d, se\u00f1ala. \n\n<\/p>\n\n\n\n<p>\u00bf Qu\u00e9 ventajas le proporciona a trabajos como el de Nazaret, el empleo de herramientas multimedia?  <\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00bfQu\u00e9 ventajas le proporciona a trabajos como el de Nazaret, el empleo de herramientas multimedia?\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/6usVS1yoKPw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Por: marylin.alvis@unmsm.edu.pe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el paso del periodismo tradicional al periodismo digital, la mayor\u00eda de periodistas ambientales se ha visto en la necesidad de implementar herramientas multimedia digitales para darle mayor \u00e9nfasis a sus contenidos y que los lectores puedan tener una mejor experiencia. <\/p>\n","protected":false},"author":23,"featured_media":4068,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[326,359,28],"tags":[538,540,539,533],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4063"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=4063"}],"version-history":[{"count":4,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4063\/revisions"}],"predecessor-version":[{"id":4074,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4063\/revisions\/4074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/4068"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=4063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=4063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=4063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}