{"id":4343,"date":"2020-12-02T19:47:41","date_gmt":"2020-12-03T00:47:41","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=4343"},"modified":"2020-12-14T18:21:09","modified_gmt":"2020-12-14T23:21:09","slug":"el-caos-en-el-que-vivimos","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/el-caos-en-el-que-vivimos\/","title":{"rendered":"EL CAOS EN EL QUE VIVIMOS"},"content":{"rendered":"\n<p style=\"text-align:justify\">Este\n2020 ha sido realmente un a\u00f1o terrible para todo el mundo, pero a\u00fan m\u00e1s para el\nPer\u00fa. A pesar de la pandemia que nos aqueja, los congresistas elegidos por el\npueblo peruano decidieron cambiar de presidente como quien se cambia de medias.\nBas\u00e1ndose en especulaciones, sin hechos comprobados. Originando un panorama de\ncaos e incertidumbre en cuanto a la pol\u00edtica, que se sum\u00f3 a los problemas econ\u00f3micos\ny de salud que tenemos.<\/p>\n\n\n\n<p style=\"text-align:justify\">El\n9 de noviembre comenz\u00f3 todo, 105 congresistas votaron a favor de la vacancia en\ncontra Martin Vizcarra. En un af\u00e1n de hacerse del poder estos individuos\nacordaron en una reuni\u00f3n, minutos despu\u00e9s que el presidente diera su descargo y\nacusara a 68 de los 130 congresistas por tener problemas con la justicia. En\ndonde liderados por Manuel Arturo Merino de Lama en ese momento presidente del Congreso,\naceptaron votar a favor de la vacancia.<\/p>\n\n\n\n<p style=\"text-align:justify\">El\n10 de noviembre Merino de Lama jurament\u00f3 como el nuevo presidente del Per\u00fa sin\nimportarle el rechazo que se evidenci\u00f3 en las redes sociales. A pesar de\nmencionar que las elecciones del 11 de abril del 2021 no se iban a cambiar, el\npueblo no confi\u00f3 en \u00e9l y asumieron que era un golpe de estado.<\/p>\n\n\n\n<p style=\"text-align:justify\">Merino de Lama es un tumbesino de 59 a\u00f1os, el ingreso en 1979 a la Universidad de Piura a la carrera de agronom\u00eda la cual no lleg\u00f3 a concluir. Despu\u00e9s de esto ingres\u00f3 al partido de Acci\u00f3n Popular en el mismo a\u00f1o con el cual pudo llegar a ser congresista en tres oportunidades.<\/p>\n\n\n\n<p style=\"text-align:justify\">Este\npersonaje a pesar de no haber culminado sus estudios de agronom\u00eda estuvo muy\nmetido en esa industria, tuvo diversos puestos como presidente de\nComercializaci\u00f3n de la Asociaci\u00f3n de Productores de Pl\u00e1tano, presidente de la\nAsociaci\u00f3n de Comerciantes de Pl\u00e1tanos y Frutas en General, integrante del\nComit\u00e9 de Defensa del Agro Tumbesino, representante de los Productores Agrarios\nde Tumbes, presidente del Comit\u00e9 Electoral de la Comisi\u00f3n de Regantes de la Margen\nIzquierda del R\u00edo Tumbes y presidente de la Comisi\u00f3n Permanente de la Deuda\nAgraria de Tumbes.&nbsp; <\/p>\n\n\n\n<p style=\"text-align:justify\">\u00c9l\nlogr\u00f3 en el 2000 junto a diversas organizaciones agrarias de Tumbes la\ncondonaci\u00f3n de diversas deudas contra\u00eddas con el estado y refinanciar algunas.\nLas personas en la actualidad se preguntan \u00bfQui\u00e9nes votaron por \u00e9l para que sea\ncongresista? Ya sabemos qui\u00e9nes. <\/p>\n\n\n\n<p style=\"text-align:justify\">En\npocos d\u00edas el Congreso no se qued\u00f3 tranquilo y comenz\u00f3 a modificar el bachillerato\nautom\u00e1tico y la posible creaci\u00f3n de nuevas universidades que generar\u00edan el\nretroceso en el avance de una mejor educaci\u00f3n, lo cual increment\u00f3 a\u00fan m\u00e1s el\nrechazo hacia \u00e9l y el Congreso que lo escogi\u00f3.<\/p>\n\n\n\n<p style=\"text-align:justify\">Otro\npunto en contra que tuvo Merino para ganarse el rechazo del pueblo es que\neligiera como presidente del Consejo de Ministros a Antero Flores Araoz, quien\nha realizado comentarios discriminatorios en contra del pueblo peruano,\nllam\u00e1ndolos \u201cllamas\u201d y \u201cvicu\u00f1as\u201d, entre otros.<\/p>\n\n\n\n<p style=\"text-align:justify\">La\ngente no se qued\u00f3 tranquila, a pesar del COVID-19 salieron a protestar en\nmarchas pac\u00edficas, recibiendo del gobierno una respuesta violenta a trav\u00e9s de\nla polic\u00eda. Estos usaron armas que deber\u00edan servir para proteger al pueblo y no\npara lastimarlos. Originado la perdida de dos vida valiosas Inti Sotelo y Bryan\nPintado.<\/p>\n\n\n\n<p style=\"text-align:justify\">Debido\na estos hechos diversos ministros renunciaron a sus puestos, pero ya era muy\ntarde las muertes ya hab\u00edan sucedido. Merino al ver toda la situaci\u00f3n decidi\u00f3\npresentar su renuncia irrevocable de forma verbal al cargo de presidente.&nbsp; El Congreso en un af\u00e1n de quedar bien con la\npoblaci\u00f3n someti\u00f3 a votaci\u00f3n la renuncia, donde se obtuvo 120 votos a favor.<\/p>\n\n\n\n<p style=\"text-align:justify\">Despu\u00e9s de todo lo sucedido las preguntas son \u00bfC\u00f3mo podemos desterrar la corrupci\u00f3n de nuestro Per\u00fa?, \u00bfCu\u00e1ntas vidas m\u00e1s se deben dar para que la gente se dedique a la pol\u00edtica por amor al pueblo y no solo por el dinero? Estas y otras interrogantes son las que muchos peruanos se hacen d\u00eda a d\u00eda.<\/p>\n\n\n\n<p style=\"text-align:justify\">Algunos dicen que las protestas se deben a que las personas son de una nueva generaci\u00f3n. Pero lo que sucede en realidad es que la poblaci\u00f3n est\u00e1 harta de que los pol\u00edticos hagan lo que quieran, es por eso que debemos estar muy informados para estas nuevas elecciones. Depende de nosotros colocar a personas nuevas, con \u00e9tica y amor por servir a un pueblo que los necesita. Debemos evitar votar por personas que solo sirven a sus propios intereses. En nosotros esta que todo lo que pas\u00f3 este 14 de noviembre ya no se vuelva a repetir. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 2020 ha sido realmente un a\u00f1o terrible para todo el mundo, pero a\u00fan m\u00e1s para el Per\u00fa. A pesar de la pandemia que nos aqueja, los congresistas elegidos por el pueblo peruano decidieron cambiar de presidente como quien se cambia de medias. Bas\u00e1ndose en especulaciones, sin hechos comprobados. Originando un panorama de caos e [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":4346,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[553],"tags":[],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4343"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=4343"}],"version-history":[{"count":4,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4343\/revisions"}],"predecessor-version":[{"id":4351,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4343\/revisions\/4351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/4346"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=4343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=4343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=4343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}