{"id":4505,"date":"2020-12-09T22:00:09","date_gmt":"2020-12-10T03:00:09","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=4505"},"modified":"2020-12-09T22:00:12","modified_gmt":"2020-12-10T03:00:12","slug":"los-premios-grammy","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/los-premios-grammy\/","title":{"rendered":"Los premios Grammy"},"content":{"rendered":"\n<p style=\"text-align:justify\">El presente a\u00f1o, ha\nalbergado diversos sucesos que han trastornado la cotidianeidad de muchas\npersonas en el globo, desde los incendios en Australia, hasta el punto de\ninflexi\u00f3n que fue la pandemia y sus restricciones. En paralelo al confinamiento\n(sobre todo durante la carente expectaci\u00f3n a su prolongaci\u00f3n), se dio el\nlanzamiento del \u00e1lbum <em>The New Abnormal, <\/em>de la banda <em>The Strokes, <\/em>el\ncual ha sido nominado a los premios <em>Grammy <\/em>en la categor\u00eda de mejor\n\u00e1lbum de rock. A lo cual surge la interrogante \u00bfcu\u00e1l es la relevancia de esta\nnominaci\u00f3n?; siendo la primera nominaci\u00f3n de la banda a los <em>Grammys<\/em>, conseguir\ntal reconocimiento parecer\u00eda m\u00e1s que significante para la banda y sus\nseguidores; en contraste, las nominaciones de los Grammy, han generado\ncontroversias a lo largo de la vida de esta instituci\u00f3n.<\/p>\n\n\n\n<p style=\"text-align:justify\">En respuesta a la\npublicaci\u00f3n de los nominados y sus categor\u00edas, el cantante <em>The Weeknd<\/em> se\nmanifest\u00f3 en Twiter, refiri\u00e9ndose a esta celebraci\u00f3n como corrupta, lo cu\u00e1l\nretom\u00f3 la discusi\u00f3n respecto del c\u00f3mo se maneja esta celebraci\u00f3n, los criterios\nque se emplean para nominar o galardonar a los artistas. En principio, la\nrespuesta del artista aparenta ser una rabieta ante su nula presencia en las\nnominaciones; no obstante, se vuelve extra\u00f1a esta condici\u00f3n, considerando que\nsu \u00faltimo \u00e1lbum <em>After Hours<\/em>, goza de una buena cr\u00edtica e incluso siendo <em>Blinding\nLights,<\/em> una de las canciones del \u00e1lbum, parte del top de canciones m\u00e1s\nescuchadas seg\u00fan la lista <em>Billboard Hot 100<\/em>. <\/p>\n\n\n\n<p style=\"text-align:justify\">Los premios Grammy, est\u00e1n\nrodeados de controversias referentes a la posible naturaleza discriminatoria de\nestos galardones, desde el despido en condiciones poco esclarecidas, de la\nprimera mujer presidenta de la instituci\u00f3n, las acusaciones por infrarrepresentar\na diversos artistas \u201cno blancos\u201d y a las mujeres. La instituci\u00f3n aparenta\nentrar en decadencia, a lo cu\u00e1l debe de resaltarse que se mantiene siendo uno\nde los eventos m\u00e1s esperados en la escena musical y que mueve m\u00e1s dinero en la\nindustria.<\/p>\n\n\n\n<p style=\"text-align:justify\">En\ntodo caso, diversos artistas como <em>The Weeknd<\/em> o <em>Nicky Minaj<\/em>,\nmanifiestan su inconformidad con los premios, muchos otros artistas se muestran\nindiferentes ante este tipo de reconocimientos, por considerarlos meramente\nherramientas para impulsar el <em>mainstream<\/em>, siendo la banda <em>The Strokes\n<\/em>parte de estos, lo cual se vio bien evidenciado al ganar el premio a mejor\nbanda internacional en los NME awards.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presente a\u00f1o, ha albergado diversos sucesos que han trastornado la cotidianeidad de muchas personas en el globo, desde los incendios en Australia, hasta el punto de inflexi\u00f3n que fue la pandemia y sus restricciones. En paralelo al confinamiento (sobre todo durante la carente expectaci\u00f3n a su prolongaci\u00f3n), se dio el lanzamiento del \u00e1lbum The [&hellip;]<\/p>\n","protected":false},"author":85,"featured_media":4506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4505"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=4505"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4505\/revisions"}],"predecessor-version":[{"id":4507,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4505\/revisions\/4507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/4506"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=4505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=4505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=4505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}