{"id":4591,"date":"2020-12-10T21:41:50","date_gmt":"2020-12-11T02:41:50","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=4591"},"modified":"2021-01-14T08:41:02","modified_gmt":"2021-01-14T13:41:02","slug":"francisco-lombardi-cineasta-peruano-recibe-premio-en-festival-de-mexico","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/francisco-lombardi-cineasta-peruano-recibe-premio-en-festival-de-mexico\/","title":{"rendered":"Francisco Lombardi, cineasta peruano, recibe premio en festival de M\u00e9xico"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/IMAGEN-NOTA-PERIODISTICA-MONJE-SAMAME-1.jpg\" alt=\"\" class=\"wp-image-4592\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/IMAGEN-NOTA-PERIODISTICA-MONJE-SAMAME-1.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/IMAGEN-NOTA-PERIODISTICA-MONJE-SAMAME-1-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Ceremonia de Inauguraci\u00f3n del 35\u00b0 Festival Internacional de Cine de Guadalajara. 20\/11\/2020. Foto: \u00a9 FICG \/ Ana Cristina Rodr\u00edguez Mart\u00ednez<\/figcaption><\/figure>\n\n\n\n<p style=\"text-align:justify\"><strong>Este \u00faltimo 20 de noviembre, el reconocido director de\ncine, Francisco Lombardi, recibi\u00f3 el premio \u201cMayahuel Iberoamericano\u201d en la\nceremonia inicial del 35\u00b0 Festival Internacional de cine de Guadalajara (FICG)\npor su gran aporte al cine latinoamericano y mundial.<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">El <a href=\"https:\/\/ficg.mx\/35\/public\/es\/home\">Festival de cine de Guadalajara<\/a>\nes uno de los festivales con m\u00e1s prestigio de toda Latinoam\u00e9rica, es un\nacontecimiento cultural que permite difundir, promocionar, apreciar y\ndistribuir el cine mexicano e iberoamericano por toda la industria.<\/p>\n\n\n\n<p style=\"text-align:justify\">El pasado 20 de noviembre se realiz\u00f3 la inauguraci\u00f3n de\nsu trig\u00e9sima quinta edici\u00f3n y tuvo como pa\u00eds invitado de honor al Per\u00fa, y con\nello al grandioso cineasta \u201cPancho\u201d Lombardi, qui\u00e9n adem\u00e1s de recibir el\n\u201cMayahuel Iberoamericano\u201d, tambi\u00e9n dict\u00f3 una Clase Magistral el domingo 22 de\nnoviembre, titulado \u201c<a href=\"https:\/\/ficg.mx\/35\/public\/es\/noticia\/40\">Di\u00e1logos de Industria<\/a>\u201d,\ndonde comparti\u00f3 sus mejores an\u00e9cdotas como director, su visi\u00f3n y algunos logros\nque ha alcanzado a lo largo de su carrera art\u00edstica.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"645\" height=\"363\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/standard_Cineasta-peruano-Francisco-Lombardi-recibe-el-\u201cMayahuel-Iberoamericano\u201d-en-el-35\u00b0-Festival-Internacional-de-Cine-de-Guadalajara.jpg\" alt=\"\" class=\"wp-image-7975\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/standard_Cineasta-peruano-Francisco-Lombardi-recibe-el-\u201cMayahuel-Iberoamericano\u201d-en-el-35\u00b0-Festival-Internacional-de-Cine-de-Guadalajara.jpg 645w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/standard_Cineasta-peruano-Francisco-Lombardi-recibe-el-\u201cMayahuel-Iberoamericano\u201d-en-el-35\u00b0-Festival-Internacional-de-Cine-de-Guadalajara-300x169.jpg 300w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/><figcaption>Conferencia \u00abUna vida de hacer cine con Francisco Lombardi\u00bb, modera \u00d3scar S\u00e1nchez; en el marco de actividades del trig\u00e9simo quinto Festival Internacional de Cine en Guadalajara. Guadalajara, Jalisco, M\u00e9xico. Domingo 22 de noviembre de 2020. Foto: \u00a9 FICG \/ Gonzalo Garc\u00eda<\/figcaption><\/figure>\n\n\n\n<p style=\"text-align:justify\">Francisco Lombardi naci\u00f3 el 3 de agosto de 1949 en la\nciudad de Tacna, lugar donde pas\u00f3 sus primeros a\u00f1os, hasta mudarse a Lima y\ndesarrollar el gusto por el cine hollywoodense, posteriormente pudo concretizar\nel inicio de su carrera como cineasta a los 25 a\u00f1os. Desde ese momento ha\ndirigido grandes largometrajes como \u201cLa boca del lobo\u201d, \u201cLa ciudad y los\nperros\u201d, \u201cPantale\u00f3n y las visitadoras\u201d, \u201cTinta roja\u201d, entre otros. Supo crear\ngrandes obras art\u00edsticas a pesar de la dificultad que representaba la\nproducci\u00f3n. \u201cFui muy afortunado. Hacer cine en El Per\u00fa era algo muy\ndif\u00edcil, casi no hab\u00eda\u201d, comenta el experimentado director.<\/p>\n\n\n\n<p style=\"text-align:justify\">En el marco del festival, que durar\u00e1 desde el 20 hasta el\n27 de noviembre, se podr\u00e1n ver cinco pel\u00edculas restauradas de Lombardi: \u201cLa\nboca del lobo\u201d, \u201cCa\u00eddos del cielo\u201d, Bajo la piel\u201d, \u201cLa ciudad y los perros\u201d y\n\u201cOjos que no ven\u201d, cuya restauraci\u00f3n estuvo a cargo del Ministerio de Cultura\ndel Per\u00fa, con ayuda del Concurso Nacional de Proyectos de Preservaci\u00f3n\nAudiovisual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este \u00faltimo 20 de noviembre, el reconocido director de cine, Francisco Lombardi, recibi\u00f3 el premio \u201cMayahuel Iberoamericano\u201d en la ceremonia inicial del 35\u00b0 Festival Internacional de cine de Guadalajara (FICG) por su gran aporte al cine latinoamericano y mundial. El Festival de cine de Guadalajara es uno de los festivales con m\u00e1s prestigio de toda [&hellip;]<\/p>\n","protected":false},"author":118,"featured_media":4592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,35,34,444],"tags":[220,1099,1100],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4591"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/118"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=4591"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4591\/revisions"}],"predecessor-version":[{"id":7976,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4591\/revisions\/7976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/4592"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=4591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=4591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=4591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}