{"id":4594,"date":"2020-12-10T21:48:22","date_gmt":"2020-12-11T02:48:22","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=4594"},"modified":"2021-01-14T19:41:37","modified_gmt":"2021-01-15T00:41:37","slug":"congreso-de-la-republica-debate-ley-de-presupuesto-del-sector-publico-para-el-ano-fiscal-2021-que-asciende-a-183-029-millones-de-soles","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/congreso-de-la-republica-debate-ley-de-presupuesto-del-sector-publico-para-el-ano-fiscal-2021-que-asciende-a-183-029-millones-de-soles\/","title":{"rendered":"Congreso de la Rep\u00fablica debate Ley de Presupuesto del Sector P\u00fablico para el a\u00f1o fiscal 2021 que asciende a 183 029 millones de soles."},"content":{"rendered":"\n<p style=\"text-align:justify\">En sesi\u00f3n del pleno del Congreso los parlamentarios de las diferentes bancadas expusieron sus puntos de vista en referencia al presupuesto p\u00fablico que regir\u00e1 el a\u00f1o fiscal 2021. <strong>El mencionado debate tambi\u00e9n cont\u00f3 con la exposici\u00f3n de la Ley de Equilibrio Financiero y la Ley de Endeudamiento<\/strong>, las cuales fueron expuestas por el Ministro de Econom\u00eda Waldo Mendoza y la premier Violeta Berm\u00fadez.<\/p>\n\n\n\n<p style=\"text-align:justify\">Con un 3,19 % mayor al del 2020, aumento de casi 10% al sector salud, 17,9% para educaci\u00f3n el dictamen de la Ley de Presupuesto P\u00fablico 2021 aprobado en la Comisi\u00f3n de Presupuesto fue ampliamente observada por los congresistas por su car\u00e1cter centralista, ya que tan solo el 30% de los recursos del Estado llegar\u00e1n a los gobiernos regionales y locales. En ese sentido varios parlamentarios exigieron se contemple en los apartados de dicha Ley las necesidades m\u00e1s urgentes de la poblaci\u00f3n vulnerable, as\u00ed como la priorizaci\u00f3n en el cierre de brechas y la reactivaci\u00f3n econ\u00f3mica al interior del pa\u00eds.\u00a0\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/debate-parlamentario-26-11-20.jpeg\" alt=\"\" class=\"wp-image-8157\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/debate-parlamentario-26-11-20.jpeg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/debate-parlamentario-26-11-20-300x165.jpeg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption> Fuente: Centro de Noticias del Congreso  <\/figcaption><\/figure>\n\n\n\n<p> <a href=\"https:\/\/rpp.pe\/economia\/economia\/ley-de-presupuesto-2021-hoy-continua-debate-en-el-pleno-del-congreso-mef-endeudamiento-noticia-1306347\">https:\/\/rpp.pe\/economia\/economia\/ley-de-presupuesto-2021-hoy-continua-debate-en-el-pleno-del-congreso-mef-endeudamiento-noticia-1306347<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/comunicaciones.congreso.gob.pe\/noticias\/demandan-mas-presupuesto-para-obras-publicas-en-las-regiones\/\">https:\/\/comunicaciones.congreso.gob.pe\/noticias\/demandan-mas-presupuesto-para-obras-publicas-en-las-regiones\/<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/comunicaciones.congreso.gob.pe\/noticias\/inicio-debate-parlamentario-sobre-leyes-de-presupuesto\/\">https:\/\/comunicaciones.congreso.gob.pe\/noticias\/inicio-debate-parlamentario-sobre-leyes-de-presupuesto\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En sesi\u00f3n del pleno del Congreso los parlamentarios de las diferentes bancadas expusieron sus puntos de vista en referencia al presupuesto p\u00fablico que regir\u00e1 el a\u00f1o fiscal 2021. El mencionado debate tambi\u00e9n cont\u00f3 con la exposici\u00f3n de la Ley de Equilibrio Financiero y la Ley de Endeudamiento, las cuales fueron expuestas por el Ministro de [&hellip;]<\/p>\n","protected":false},"author":142,"featured_media":4595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4594"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/142"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=4594"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4594\/revisions"}],"predecessor-version":[{"id":8158,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4594\/revisions\/8158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/4595"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=4594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=4594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=4594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}