{"id":4615,"date":"2020-12-10T22:25:42","date_gmt":"2020-12-11T03:25:42","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=4615"},"modified":"2021-01-07T15:20:54","modified_gmt":"2021-01-07T20:20:54","slug":"jovenes-heridos-en-las-marchas-reciben-apoyo-economico-mediante-las-redes-sociales","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/jovenes-heridos-en-las-marchas-reciben-apoyo-economico-mediante-las-redes-sociales\/","title":{"rendered":"J\u00f3venes heridos en las marchas reciben apoyo econ\u00f3mico mediante las redes sociales"},"content":{"rendered":"\n<p style=\"text-align:justify\"><strong>El\npasado 12,14 y 15 de noviembre en Per\u00fa, se llev\u00f3 a cabo una serie de marchas\nnacionales donde asistieron personas de diversas edades a protestar de una\nmanera pac\u00edfica en contra del gobierno de Manuel Merino, registrando finalmente\nuna gran cantidad de heridos.<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">La vacancia del presidente Vizcarra gener\u00f3 una fuerte ola\nde ciudadanos que salieron a las calles alzando la voz en contra de la\npresidencia de Manuel Merino, exigiendo su renuncia inmediata a trav\u00e9s de\ncarteles, bailes, m\u00fasica y arengas.<\/p>\n\n\n\n<p style=\"text-align:justify\">Tras estas marchas pac\u00edficas se origin\u00f3 una fuerte represi\u00f3n policial hacia los protestantes, ocasionando la muerte de dos j\u00f3venes y decenas de heridos que fueron trasladados a los diferentes hospitales de Lima.<\/p>\n\n\n\n<p style=\"text-align:justify\">Muchos de estos j\u00f3venes quedaron con heridas sumamente\ngraves. La mayor\u00eda de ellos no contaban con los recursos suficientes por lo que\n<a href=\"https:\/\/larepublica.pe\/sociedad\/2020\/11\/13\/joven-pide-apoyo-tras-ser-herido-por-pnp-en-marchas-contra-merino\/\">comenzaron\na salir por los diferentes medios a pedir ayuda econ\u00f3mica<\/a>. Como\nconsecuencia se inici\u00f3 una campa\u00f1a de apoyo en redes sociales utilizando\nprincipalmente Instagram, Facebook, WhatsApp y Twitter, donde las personas con\nayuda de <em>flyers<\/em>, compart\u00edan y difund\u00edan informaci\u00f3n del proceso en el\nque se encontraban sus compa\u00f1eros y como se les pod\u00eda ayudar de manera\necon\u00f3mica.<\/p>\n\n\n\n<p style=\"text-align:justify\">Famosos e <em>influencers<\/em> tambi\u00e9n se sumaron a este\nllamado <a href=\"https:\/\/larepublica.pe\/espectaculos\/2020\/11\/18\/yidda-eslava-y-julian-zucchi-hacen-colecta-para-jovenes-heridos-en-la-marcha\/\">haciendo\ncolectas como el \u201cCyberton\u201d<\/a> y <a href=\"https:\/\/rpp.pe\/musica\/conciertos\/marcha-nacional-susana-baca-daniel-f-bareto-y-mas-artistas-ofrecen-hoy-sabado-21-un-concierto-solidario-para-los-heridos-en-protestas-noticia-1305464\">ofreciendo\nconciertos ben\u00e9ficos<\/a> por distintos artistas, logrando as\u00ed una mayor\ndifusi\u00f3n y alcance apoyando a los familiares de las v\u00edctimas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 12,14 y 15 de noviembre en Per\u00fa, se llev\u00f3 a cabo una serie de marchas nacionales donde asistieron personas de diversas edades a protestar de una manera pac\u00edfica en contra del gobierno de Manuel Merino, registrando finalmente una gran cantidad de heridos. La vacancia del presidente Vizcarra gener\u00f3 una fuerte ola de ciudadanos [&hellip;]<\/p>\n","protected":false},"author":137,"featured_media":4616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[330,329,1],"tags":[526],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4615"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/137"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=4615"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4615\/revisions"}],"predecessor-version":[{"id":4617,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4615\/revisions\/4617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/4616"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=4615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=4615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=4615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}