{"id":4657,"date":"2020-12-13T23:21:38","date_gmt":"2020-12-14T04:21:38","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=4657"},"modified":"2021-01-06T01:30:53","modified_gmt":"2021-01-06T06:30:53","slug":"portafolios-digitales","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/portafolios-digitales\/","title":{"rendered":"Portafolios Digitales"},"content":{"rendered":"\n<p>Debido al gran avance digital y al gran aumento de\nvisibilidad en las redes sociales, los fot\u00f3grafos, videografos, artistas en\ngeneral, han optado por mostrar su trabajo a trav\u00e9s de una pagina web.<\/p>\n\n\n\n<p>En estas p\u00e1ginas web, los fot\u00f3grafos podr\u00e1n publicar sus\nfotograf\u00edas m\u00e1s resaltantes agrup\u00e1ndolas en diferentes categor\u00edas de acuerdo al\nestilo del fot\u00f3grafo construyendo as\u00ed su portafolio digital, facilitando el\nalcance de su p\u00fablico objetivo con mayor rapidez y facilidad. Por lo que, ya no\nnecesitaran imprimir portafolios f\u00edsicos para entregar a sus clientes\npotenciales al momento de querer concretar un trabajo, sino solo se enviar\u00e1 el enlace\nde la pagina web para que el cliente observe los trabajos realizados.<\/p>\n\n\n\n<p>Asimismo, tener una pagina web genera un \u201cpunto extra\u201d,\nhaciendo que nuestro trabajo se vea m\u00e1s serio y profesional. Adem\u00e1s, no solo\npodemos publicar fotos en una p\u00e1gina web, sino tambi\u00e9n podremos publicar videos\n(si nos encargamos a realizar trabajos audiovisuales), publicar los clientes\nque han confiado en nuestro trabajo, paquetes de precios que ofrecemos, talleres\npara ense\u00f1ar, etc. En realidad, se puede publicar cualquier cosa relacionado a\nnuestro trabajo, pero manteniendo una esencia y un orden en conjunto. Incluso,\nalgunos fot\u00f3grafos han hecho de su pagina web no solo un portafolio digital\nsino un e-commerce, vendiendo sus fotograf\u00edas en cuadros listas para colgar en alguna\nhabitaci\u00f3n del hogar.<\/p>\n\n\n\n<p>Sin embargo, muchos fot\u00f3grafos optan simplemente por\npublicar sus fotograf\u00edas y poner su informaci\u00f3n de contacto. Es un detalle\nminimalista que tambi\u00e9n le da calidad y hace que el espectador, cliente,\nvisitante, etc., solo se enfoque en el trabajo fotogr\u00e1fico y lo vea en todo el\nespacio otorgado por la p\u00e1gina web. <\/p>\n\n\n\n<p>A continuaci\u00f3n, se dejar\u00e1 algunos enlaces de fot\u00f3grafos y\nsu portafolio digital:<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/ivanferrerophoto.com\/\">https:\/\/ivanferrerophoto.com\/<\/a> <\/li><li><a href=\"https:\/\/www.lidiavives.com\/\">https:\/\/www.lidiavives.com\/<\/a><\/li><li><a href=\"https:\/\/www.kikearnaiz.com\/\">https:\/\/www.kikearnaiz.com\/<\/a> <\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Debido al gran avance digital y al gran aumento de visibilidad en las redes sociales, los fot\u00f3grafos, videografos, artistas en general, han optado por mostrar su trabajo a trav\u00e9s de una pagina web. En estas p\u00e1ginas web, los fot\u00f3grafos podr\u00e1n publicar sus fotograf\u00edas m\u00e1s resaltantes agrup\u00e1ndolas en diferentes categor\u00edas de acuerdo al estilo del fot\u00f3grafo [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":4659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[358,360,362],"tags":[221,565],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4657"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=4657"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4657\/revisions"}],"predecessor-version":[{"id":4658,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4657\/revisions\/4658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/4659"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=4657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=4657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=4657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}