{"id":4823,"date":"2020-12-22T18:22:16","date_gmt":"2020-12-22T23:22:16","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=4823"},"modified":"2020-12-22T18:22:18","modified_gmt":"2020-12-22T23:22:18","slug":"las-3-mas-grandes-corporaciones-de-radio-en-el-peru","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/las-3-mas-grandes-corporaciones-de-radio-en-el-peru\/","title":{"rendered":"Las 3 m\u00e1s grandes corporaciones de radio en el Per\u00fa."},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img decoding=\"async\" loading=\"lazy\" width=\"265\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/PSX_20201203_190752.jpg\" alt=\"\" class=\"wp-image-4828\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/PSX_20201203_190752.jpg 265w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/PSX_20201203_190752-213x300.jpg 213w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><figcaption>Fuente: google<\/figcaption><\/figure><\/div>\n\n\n\n<p style=\"text-align:justify\">Seg\u00fan el Ministerio de Transportes y Comunicaciones (MTC) m\u00e1s del 80% de los peruanos consumen radio en el Per\u00fa. Seg\u00fan el estudio del Consejo Consultivo de Radio y Televisi\u00f3n (CONCORTV) <a href=\"http:\/\/www.concortv.gob.pe\/investigacion\/estudios-cuantitativos\/2017-estudio-sobre-consumo-televisivo-y-radial\/\">\u201cConsumo Televisivo y Radial 2017\u201d<\/a>, el 86% de adultos escucha radio durante 02:35 horas en promedio diario (de lunes a viernes). En cuanto a la poblaci\u00f3n joven, seg\u00fan &nbsp;el estudio <a class=\"ek-link ek-link\" href=\"http:\/\/www.concortv.gob.pe\/investigacion\/estudios-cuantitativos\/2018-estudio-cuantitativo-sobre-consumo-televisivo-y-radial-en-ninos-ninas-y-adolescentes\/\">\u201cConsumo Televisivo y Radial en Ni\u00f1os, Ni\u00f1as y Adolescentes, 2018\u201d<\/a>, el 81% de ni\u00f1os y ni\u00f1as de 7 a 11 a\u00f1os y adolescentes de 12 a 16 a\u00f1os, escucha radio de lunes a viernes, y prefieren los programas musicales (91%) y de entretenimiento (67%).<\/p>\n\n\n\n<p style=\"text-align:justify\">Por otro lado, seg\u00fan\ncifras del MTC, existen 5.667 estaciones de radio autorizadas a nivel nacional.\nLas regiones con m\u00e1s estaciones de radio son Cusco (509), Cajamarca (466),\n\u00c1ncash (412) y Lima (396). La mayor\u00eda de estaciones son de tipo comercial\n(4.435), le siguen las educativas (1.169) y comunitarias (63).<\/p>\n\n\n\n<p style=\"text-align:justify\">En este escenario,\nse hace, pues, relevante se\u00f1alar las cadenas de radio m\u00e1s grandes del Per\u00fa.\nEstas tienen gran alcance dentro de la capital y en casi todo el territorio\nperuano: Corporaci\u00f3n Universal, Corporaci\u00f3n RPP y Corporaci\u00f3n CRP. <\/p>\n\n\n\n<p style=\"text-align:justify\">La corporaci\u00f3n\nUniversal inicio con la creaci\u00f3n de la radio Universal en 1989 por Higinio\nCapu\u00f1ay Serpan. Con el tiempo se fue afiliando con otras radios regionales y\nas\u00ed se fue formando la corporaci\u00f3n Universal. Esta corporaci\u00f3n de radio tiene\nactualmente tres radios con cobertura en lima y provincias (radio Karibe\u00f1a,\nradio La Kalle y radio Sabor Mix). Est\u00e1n radios est\u00e1n enfocados en el rubro de\nla m\u00fasica y el entretenimiento. <\/p>\n\n\n\n<p style=\"text-align:justify\">La corporaci\u00f3n RPP inicio\ncon la creaci\u00f3n de Radio Programas del Per\u00fa (RPP) en 1963 por los hermanos\nGenaro y H\u00e9ctor Delgado Parker, asociados con Johnny E. Lindley. La corporaci\u00f3n\ntiene actualmente ocho emisoras de radio (radio RPP, radio Studio 92, radio\nFelicidad, radio Ox\u00edgeno, radio La Zona, radio Coraz\u00f3n, radio La Mega y radio\nFelicidad) que est\u00e1n orientadas a la m\u00fasica, entrenamiento y periodismo. <\/p>\n\n\n\n<p style=\"text-align:justify\">La corporaci\u00f3n CRP inici\u00f3\ncon la fundaci\u00f3n de Radiomar en 1969 por Abraham Zavala Falc\u00f3n. En el 98 se\nform\u00f3 la conglomeraci\u00f3n de radioemisoras en asociaci\u00f3n con Wilmer Salgado. La\ncorporaci\u00f3n tiene actualmente 10 frecuencias (radio Moda, radio Nueva Q, radio\nRitmo Rom\u00e1ntica, radio La Inolvidable, Radiomar, radio Oasis, radio Planeta,\nradio M\u00e1gica, radio Inca Sat AM y radio Bienestar) que est\u00e1n orientadas a la m\u00fasica\ny el entretenimiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan el Ministerio de Transportes y Comunicaciones (MTC) m\u00e1s del 80% de los peruanos consumen radio en el Per\u00fa. Seg\u00fan el estudio del Consejo Consultivo de Radio y Televisi\u00f3n (CONCORTV) \u201cConsumo Televisivo y Radial 2017\u201d, el 86% de adultos escucha radio durante 02:35 horas en promedio diario (de lunes a viernes). En cuanto a la [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":5681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[549,358],"tags":[582,581],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4823"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=4823"}],"version-history":[{"count":7,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4823\/revisions"}],"predecessor-version":[{"id":5682,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4823\/revisions\/5682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/5681"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=4823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=4823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=4823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}