{"id":4983,"date":"2020-12-22T19:29:59","date_gmt":"2020-12-23T00:29:59","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=4983"},"modified":"2020-12-22T19:30:02","modified_gmt":"2020-12-23T00:30:02","slug":"mitos-sobre-los-eclipses-solares-en-el-mundo","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/mitos-sobre-los-eclipses-solares-en-el-mundo\/","title":{"rendered":"Mitos sobre los eclipses solares en el mundo"},"content":{"rendered":"\n<p>En diversas partes del mundo explican estos fen\u00f3menos denomin\u00e1ndolos, como \u201clobos celestiales vikingos\u201d, \u201cperros de fuego coreanos\u201d as\u00ed como tienen diversas versiones en el \u00c1frica que es el de reconciliaci\u00f3n celestial. Muchas personas alrededor del mundo, al percibir tal situaci\u00f3n del eclipse, sienten que significa una ruptura del orden c\u00f3smico y por ende algunos lo denominan como algo malo, pero tambi\u00e9n existen aquellos que piensan que no es as\u00ed. Muchas personas creen que es una situaci\u00f3n terror\u00edfica y otros solo consideran que es momento de reflexi\u00f3n. <\/p>\n\n\n\n<p>El primer mito es la <strong>Degluci\u00f3n de fuego<\/strong>, muchas\nculturas consideran que cuando ocurre un eclipse, sea lunar o solar, es un\nmomento en el que los demonios y animales consumen al Sol y la Luna. Krupp, el director\ndel Observatorio Griffith en Los Angeles, menciona que en Vietnam una rana o\nsapo se come la Luna o el Sol mientras que los miembros de la tribu Kwakiutl,\nen Canad\u00e1, creen que la boca del cielo consume al Sol y la Luna en pleno eclipse.\n<\/p>\n\n\n\n<p>El segundo mito es <strong>El mago del eclipse<\/strong>, las\npersonas de muchas culturas hacen diversos ruidos para ahuyentar a lo que ellos\ncreen un demonio o animal, de acuerdo con lo mencionado por Nancy Maryboy, presidenta\ndel Instituto ind\u00edgena en San Juan. Es en ese momento que las personas golpean\nollas, sartenes y hasta tocan tambores para alejar a ese ser que se esta\ncomiendo al Sol o la Luna. <\/p>\n\n\n\n<p>El tercer mito es el <strong>Robo celestial<\/strong> y se\nrelaciona con la mitolog\u00eda coreana, en este mito se supone que unos perros de\nfuego se intentan robar el Sol y la Luna. Estos caninos m\u00edticos mediante ordenes\nde su rey hacen lo posible para capturar al Sol o la Luna, pero siempre fallan\ny es cuando muerden la \u00f3rbita y hace que sucedan los eclipses. <\/p>\n\n\n\n<p>El cuarto mito es el de <strong>Naturaleza y reconciliaci\u00f3n<\/strong>.\nJarita Holbrook, quien es astr\u00f3noma cultural de la universidad de the Western\nCape en Sud\u00e1frica, afirma que el pueblo de Batammaliba en Tongo cree que\ndurante eclipse la Luna y el Sol est\u00e1n peleando por lo que ellos animan a los\norbes a finalizar la pelea. La gente considera que es un momento en el que se re\u00fanen\ny solucionan viejas disputas. Por otro lado, Maryboy expresa que el pueblo\nNavajo observa al orden c\u00f3smico como en total equilibrio por lo que cuando\nsucede este acontecimiento, es momento de observar, reconocer y reflexionar\nsobre el orden c\u00f3smico. Asimismo, menciona que muchas familias respetan las\ntradiciones y se re\u00fanen en sus hogares para entonar canciones; estos no comen,\nni beben ni duermen. <\/p>\n\n\n\n<p>Finalmente se habla de algunas cuestiones modernas en\ncuanto a los eclipses, Krupp desmiente la idea que se tiene de que las mujeres\nembarazadas corren peligro. Otro concepto err\u00f3neo que desmiente tanto Krupp\ncomo Holbrook es que no se puede mirar directamente al eclipse. Ellos mencionan\nque no se deber\u00eda mirar al Sol directamente puesto que causa lesiones en los\nojos, pero s\u00ed se puede observar el eclipse cuando el Sol este totalmente\ncubierto. <\/p>\n\n\n\n<p>Krupp finaliza afirmando que es una experiencia sorprendente a pesar de que se sepa que solo es la Luna movi\u00e9ndose frente al Sol. \u00c9l expresa que es \u201cUna posibilidad de ver al universo funcionar\u201d y es \u201cun placer profundo y personal\u201d observa cuando sucede. <\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.nationalgeographicla.com\/espacio\/2019\/05\/mitos-sobre-eclipses-solares-de-todo-el-mundo\">National Geographic<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En diversas partes del mundo explican estos fen\u00f3menos denomin\u00e1ndolos, como \u201clobos celestiales vikingos\u201d, \u201cperros de fuego coreanos\u201d as\u00ed como tienen diversas versiones en el \u00c1frica que es el de reconciliaci\u00f3n celestial. Muchas personas alrededor del mundo, al percibir tal situaci\u00f3n del eclipse, sienten que significa una ruptura del orden c\u00f3smico y por ende algunos lo [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":4985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[40],"tags":[265],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4983"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=4983"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4983\/revisions"}],"predecessor-version":[{"id":5734,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/4983\/revisions\/5734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/4985"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=4983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=4983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=4983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}