{"id":5023,"date":"2020-12-29T18:54:03","date_gmt":"2020-12-29T23:54:03","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=5023"},"modified":"2020-12-29T18:54:05","modified_gmt":"2020-12-29T23:54:05","slug":"hans-zimmer-una-vida-llena-de-musica","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/hans-zimmer-una-vida-llena-de-musica\/","title":{"rendered":"Hans Zimmer, una vida llena de M\u00fasica"},"content":{"rendered":"\n<p>Hans Zimmer, nacido en Alemania, es un compositor de bandas sonoras de\npel\u00edculas y videojuegos. Es considerado como uno de los mejores compositores\ncinematogr\u00e1ficos de la actualidad, code\u00e1ndose con otros compositores reconocidos\ncomo John Williams, James Newton Howard o Marco Beltramy.<\/p>\n\n\n\n<p>Zimmer se interes\u00f3 por la m\u00fasica desde peque\u00f1o, empezando por que ser\u00eda\nsu instrumento favorito: el piano. M\u00e1s adelante, sigui\u00f3 cultivando su pasi\u00f3n y\ntalento para la m\u00fasica, llegando a formar parte de algunas bandas como The\ncamera club o Mecano, y siempre en el teclado. Poco a poco se empez\u00f3 a\ninteresar en la composici\u00f3n sinf\u00f3nica, apeg\u00e1ndose a sonidos electr\u00f3nicos, lo\nque hace que su m\u00fasica alcance un p\u00fablico m\u00e1s amplio.<\/p>\n\n\n\n<p>Producto de su trabajo, ha sido nominado once veces a los premios \u00d3scar\npor pel\u00edculas como <em>Interstellar,\nIncepti\u00f3n, Gladiador <\/em>y<em> Dunkerque<\/em>,\nresultando ganador con <em>El rey Le\u00f3n<\/em>.\nTambi\u00e9n fue nominado once veces a los Globos de Oro, resultando ganador con\nGladiador. Finalmente, fue nominado a trece premios Grammy, ganando en 4\nocasiones gracias a sus producciones en <em>The\nDark Knight, Marea Roja, El rey le\u00f3n <\/em>y<em>\nEl c\u00edrculo dela vida.<\/em><\/p>\n\n\n\n<p>El trabajo de Hans Zimmer est\u00e1 caracterizado por sumergirse en la\npel\u00edcula que va a musicalizar, un ejemplo de esto es al producir la banda\nsonora de <em>El \u00faltimo samur\u00e1i<\/em>, Zimmer\ntoma elementos de la cultura japonesa, tales como los instrumentos, dejando de\nlado los instrumentos occidentales, como las guitarras o bater\u00edas, sustituy\u00e9ndolos\npor el shakuhachi o el shamisen, de manera que se pueda ambientar de mejor\nmanera al espectador dentro de la pel\u00edcula. Del mismo modo, esto se puede\napreciar en pel\u00edculas como <em>\u00c1ngeles y\nDemonios, El c\u00f3digo Da Vinci<\/em> o <em>El\nGladiador<\/em>, donde Zimmer utiliza cantos gregorianos y en lat\u00edn para la letra\nde algunas de sus composiciones, haciendo que la banda sonora acompa\u00f1e y se\nacople perfectamente con el contexto mostrado.<\/p>\n\n\n\n<p>Finalmente, es imposible no haber escuchado algunas piezas de Hans Zimmer en el cine, para ello, un recuento de las pel\u00edculas m\u00e1s conocidas donde trabaj\u00f3: <em>El rey le\u00f3n I y II, Marea Roja, El pacificador, El pr\u00edncipe de Egipto, El camino hacia El Dorado, Pearl Harbor, Piratas del Caribe I, II y III, Kung fu panda, Madagascar, Sherlock Holmes, Doce a\u00f1os de esclavitud, Dunkerque, La mujer maravilla, Inferno, Interstellar, Divergente, El llanero solitario, El hombre de acero, El sorprendente Hombre ara\u00f1a I y II, e Inception.<\/em> <\/p>\n\n\n\n<p style=\"text-align:left\">Como se puede ver, Hans Zimmer ha trabajado en muchas pel\u00edculas reconocidas del cine mundial, dejando su huella personal en cada una de ellas, haciendo que la m\u00fasica, al igual que la imagen, sean parte del espect\u00e1culo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hans Zimmer, nacido en Alemania, es un compositor de bandas sonoras de pel\u00edculas y videojuegos. Es considerado como uno de los mejores compositores cinematogr\u00e1ficos de la actualidad, code\u00e1ndose con otros compositores reconocidos como John Williams, James Newton Howard o Marco Beltramy. Zimmer se interes\u00f3 por la m\u00fasica desde peque\u00f1o, empezando por que ser\u00eda su instrumento [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":6443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[35],"tags":[220,170],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5023"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=5023"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5023\/revisions"}],"predecessor-version":[{"id":5028,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5023\/revisions\/5028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6443"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=5023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=5023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=5023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}