{"id":5051,"date":"2020-12-22T19:40:01","date_gmt":"2020-12-23T00:40:01","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=5051"},"modified":"2020-12-22T19:40:45","modified_gmt":"2020-12-23T00:40:45","slug":"el-horrible-crimen-que-fascino-a-la-lima-del-siglo-xx","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/el-horrible-crimen-que-fascino-a-la-lima-del-siglo-xx\/","title":{"rendered":"El horrible crimen que fascin\u00f3 a la Lima del siglo XX"},"content":{"rendered":"\n<p><strong>El 1 de julio de 1930, hace 90 a\u00f1os, la capital se estremeci\u00f3 ante un horrendo crimen, los peri\u00f3dicos publicaron el hallazgo de un cad\u00e1ver descuartizado en dos maletas. El responsable del crimen: Genaro Ortiz. Por primera vez Lima ten\u00eda un crimen espantoso, un crimen que atrap\u00f3 a la ciudad entera.<\/strong><\/p>\n\n\n\n<p>Once d\u00edas antes, el 20 de junio, llegaron Genaro Ortiz y\nMarcelino Dom\u00ednguez a la ciudad de Lima, dos j\u00f3venes espa\u00f1oles que buscaban\nfama y fortuna a la par que escapaban de un pasado peligroso. Dom\u00ednguez llegaba\na Per\u00fa luego de haber asaltado una joyer\u00eda y en el camino se uni\u00f3 con Ortiz quien\nle ayudo a pasar el bot\u00edn. Buscaron hospedaje en el hotel Comercio, que quedaba\nentre el Jr.&nbsp; Carabaya y Jr. Ancash en el\ncentro de la ciudad, al lado de Palacio de Gobierno y al frente de la estaci\u00f3n\nde Los Desamparados. Se registraron en el cuarto 89, acto se guido, salieron a\nconocer la ciudad y a planificar sus siguientes movimientos. Los dos, acostumbrados\na mantener las apariencias pronto empezaron a tener problemas de dinero lo que\nir\u00eda fragmentando su interesada amistad.<\/p>\n\n\n\n<p>El 24 de junio, Genaro Ortiz y Marcelino Dom\u00ednguez volvieron\na discutir fuertemente por el bot\u00edn, pero Ortiz ya estaba decidido, esper\u00f3 a\nque Dom\u00ednguez cayera dormido en el catre que estaba al lado de la pared para\ndestruir su cabeza a martillazos. Usando sus conocimientos en medicina\ndescuartiz\u00f3 el cad\u00e1ver y coloc\u00f3 los pedazos en dos maletas, en una coloc\u00f3 el\ntorso y los brazos, en la otra las extremidades inferiores y la cabeza. Luego\nprocedi\u00f3 a limpiar la sangre derramada en el suelo con la misma ropa de su v\u00edctima.\nA la ma\u00f1ana siguiente, un 25 de junio, se dirigi\u00f3 a calle Conchan en donde\nconvers\u00f3 con Esther Buen d\u00eda y usando su carisma logr\u00f3 que ella le alquile el\ncuarto. Inmediata mente regres\u00f3 al hotel Comercio, extrajo las maletas y las\ndejo en casa de los Buend\u00eda, cerr\u00f3 el cuarto con candado y se despidi\u00f3 de su\ncasera. Genaro Ortiz ya no se sent\u00eda seguro as\u00ed que en cuesti\u00f3n de d\u00edas obtuvo\nun pasa porte falso y tom\u00f3 el primer barco a Guayaquil con el nombre de Juan Bautista\nAraya Guerrero. A los pocos d\u00edas. <\/p>\n\n\n\n<p>El 1 de junio, el se\u00f1or Buen d\u00eda se dirig\u00eda a la sala para\ncenar cuando not\u00f3 un putrefacto olor que proven\u00eda del cuarto de inquilinos,\npreocupado llam\u00f3 a la polic\u00eda. Los inspectores rompieron el cerrojo y entraron\na la oscura y vac\u00eda habitaci\u00f3n, de inmediato notaron que el olor ven\u00eda del\ninterior de dos maletas hinchadas. Al abrir las maletas se encontraron con un repugnante\nescenario. Las investigaciones llevaron a los inspectores a las puertas del\nHotel Comercio. Subieron a la habitaci\u00f3n 89 en donde solo encontraron peque\u00f1os\nrastros Finalmente, el encargado de las investigaciones reconoci\u00f3 la foto de\nOrtiz en un pasaporte chileno que correspond\u00eda a un tal Juan Bautista Araya\nGuerrero que hab\u00eda escapado ya del pa\u00eds, al consultar al c\u00f3nsul chileno este confirm\u00f3\nque era un pasaporte falso. La polic\u00eda no perdi\u00f3 el tiempo y dio aviso\ninternacional al pa\u00eds de destino de Ortiz. <\/p>\n\n\n\n<p>La noticia caus\u00f3 un impacto nunca visto. Los diarios no perdieron\nla oportunidad para crear grandes portadas y crear una leyenda en torno al\nasesinato como al asesino, las ventas se disparaban m\u00e1s que nunca, el morbo de\nla gente iba creciendo mientras m\u00e1s sab\u00edan de tan macabro crimen. Al llegar\nGuayaquil vio que la noticia de su crimen ya hab\u00eda llegado hasta el pa\u00eds\nnorte\u00f1o, ya no pod\u00eda quedarse, otra vez ten\u00eda que huir, esta vez en direcci\u00f3n a\nPanam\u00e1. Pero la suerte solo le dur\u00f3 hasta el 10 de julio, d\u00eda en que es\ncapturado gracias al apoyo de la polic\u00eda paname\u00f1a y llevado de vuelta al Per\u00fa.\nEn su maleta encontraron el bot\u00edn en joyas. Cuan do se le pregunt\u00f3 por el\nmotivo del homicidio solo atino a responder: \u201cMe encomiendo a las manos de Dios,\nlo hecho, hecho est\u00e1\u201d. \u201c <\/p>\n\n\n\n<p>Cada peri\u00f3dico que public\u00f3 una noticia sobre el crimen o\nGenaro subi\u00f3 en ventas inmediatamente. La fascinaci\u00f3n por ver al famoso\ndescuartizador provoc\u00f3 que el d\u00eda de su llegada una inmensa muchedumbre llene\nel puerto del Callao. Al llegar Lima, el carro que lo transportaba fue de\ntenido varias veces, quienes m\u00e1s intentaron tener contacto con \u00e9l eran las\nmujeres, incr\u00e9dulas ante el hecho de que una persona atractiva sea capaz de\nsemejante atrocidad, hasta hab\u00eda quienes imploraban piedad por \u00e9l. As\u00ed Ortiz\npas\u00f3 de ser un criminal a una celebridad. La sentencia que recibi\u00f3 fue de 25\na\u00f1os, pero esto no impidi\u00f3 que siguiera siendo el centro de atenci\u00f3n. En los a\u00f1os\n50 el presidente Manuel Prado Ugarteche le cedi\u00f3 el indulto, quiz\u00e1s en una\nmovida pol\u00edtica para aparentar benevolencia. Genaro Ortiz cambi\u00f3 de nombre y\npas\u00f3 a vivir el resto de sus d\u00edas en Per\u00fa escondido en el anonimato. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 1 de julio de 1930, hace 90 a\u00f1os, la capital se estremeci\u00f3 ante un horrendo crimen, los peri\u00f3dicos publicaron el hallazgo de un cad\u00e1ver descuartizado en dos maletas. El responsable del crimen: Genaro Ortiz. Por primera vez Lima ten\u00eda un crimen espantoso, un crimen que atrap\u00f3 a la ciudad entera. Once d\u00edas antes, el [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":5052,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5051"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=5051"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5051\/revisions"}],"predecessor-version":[{"id":5060,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5051\/revisions\/5060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/5052"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=5051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=5051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=5051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}