{"id":5169,"date":"2020-12-18T01:31:37","date_gmt":"2020-12-18T06:31:37","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=5169"},"modified":"2020-12-22T22:32:15","modified_gmt":"2020-12-23T03:32:15","slug":"en-2020-peru-ha-tenido-ocho-ministros-del-interior","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/en-2020-peru-ha-tenido-ocho-ministros-del-interior\/","title":{"rendered":"En 2020, Per\u00fa ha tenido ocho ministros del interior"},"content":{"rendered":"\n<p>Cluber\nAliaga, quien reemplaz\u00f3 a Rub\u00e9n Vargas, primer ministro del gobierno\ntransitorio de Francisco Sagasti, present\u00f3 su renuncia a la PCM tras asumir el\ncargo por solo cinco d\u00edas <a href=\"https:\/\/diariouno.pe\/renuncia-ministro-del-interior-ruben-vargas-ante-ola-de-cuestionamientos\/#:~:text=Renuncia%20ministro%20del%20Interior%2C%20Rub%C3%A9n%20Vargas%2C%20ante%20ola,retiro%20y%20en%20actividad%20de%20la%20Polic%C3%ADa%20\">ante la ola de cuestionamientos por parte de oficiales en retiro<\/a>\ntras asumir el cargo por solo cinco d\u00edas. <a href=\"https:\/\/diariocorreo.pe\/politica\/ministro-del-interior-cluber-aliaga-renuncia-carta-de-renuncia-generales-noticia\/\">Diario Correo<\/a> indic\u00f3 que las\nrazones para dimitir fue el estar obligado a retirar al personal de Rub\u00e9n\nVargas, este medio, citando a Latina, tambi\u00e9n indic\u00f3 la existencia de\ndiscrepancia con Francisco Sagasti, presidente de la Rep\u00fablica. <\/p>\n\n\n\n<p><a href=\"https:\/\/peru21.pe\/politica\/presidenta-del-congreso-cluber-aliaga-no-era-la-persona-correcta-para-ministro-del-interior-mirtha-vasquez-pnp-nndc-noticia\/\">Mirtha\nV\u00e1squez, presidenta del Consejo de Ministros, se pronunci\u00f3 tras la renuncia de\nAliaga&nbsp; <\/a>indicando que es una\nbuena decisi\u00f3n y que Cluber Aliaga no era la persona correcta para ministro del\nInterior, como se\u00f1ala Per\u00fa 21. V\u00e1squez se excus\u00f3 indicando que la \u201cpremura del\ntiempo de un Gobierno que ingresa en una circunstancia de emergencia, a veces,\nhace escoger a una persona que no es la m\u00e1s correcta\u201d.<\/p>\n\n\n\n<p>Jos\u00e9 Elice es ahora ministro de Interior\nen reemplazo de Aliaga. Tras aceptar el cargo, se\u00f1ala el medio Lima al d\u00eda, <a href=\"https:\/\/limaaldia.pe\/2020\/12\/10\/durante-el-presente-ano-2020-ocho-ministros-han-ocupado-el-despacho-del-ministerio-interior-senal-alternativa\/\">la\ncuenta de ministros del Interior que ha tenido Per\u00fa durante 2020 ha subido a\nocho<\/a>,\naunque Gast\u00f3n Rodr\u00edguez estuvo en dos per\u00edodos, por lo que Elice es el s\u00e9timo\nministro que hemos tenido este a\u00f1o. \u00bfPodr\u00e1 un pa\u00eds combatir realmente la\ndelincuencia, uno de los problemas que m\u00e1s preocupa a la ciudadan\u00eda, con un\nministerio de encargados espor\u00e1dicos?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cluber Aliaga, quien reemplaz\u00f3 a Rub\u00e9n Vargas, primer ministro del gobierno transitorio de Francisco Sagasti, present\u00f3 su renuncia a la PCM tras asumir el cargo por solo cinco d\u00edas ante la ola de cuestionamientos por parte de oficiales en retiro tras asumir el cargo por solo cinco d\u00edas. Diario Correo indic\u00f3 que las razones para [&hellip;]<\/p>\n","protected":false},"author":99,"featured_media":5179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[329,33],"tags":[89],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5169"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=5169"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5169\/revisions"}],"predecessor-version":[{"id":5860,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5169\/revisions\/5860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/5179"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=5169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=5169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=5169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}