{"id":5342,"date":"2020-12-18T16:35:27","date_gmt":"2020-12-18T21:35:27","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=5342"},"modified":"2021-01-14T01:47:15","modified_gmt":"2021-01-14T06:47:15","slug":"el-mito-del-racismo-inverso","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/el-mito-del-racismo-inverso\/","title":{"rendered":"El mito del \u201cracismo inverso\u201d"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>El \u201cracismo\u201d hacia personas blancas o tambi\u00e9n llamado \u201cracismo inverso\u201d es un discurso difundido para legitimar la posibilidad de un racismo bidireccional, que afecta a las personas blancas de igual manera que a otros grupos raciales. \u00bfEs esto cierto? No realmente,&nbsp; veamos por qu\u00e9. <\/strong><\/h4>\n\n\n\n<p>El concepto de \u201cracismo inverso\u201d es usado para explicar el caso de racismo del que son sujetos las personas no racializadas, es decir, las personas blancas o con <a href=\"https:\/\/www.purewow.com\/wellness\/what-is-white-passing\"><strong><em>white passing<\/em><\/strong><strong>.<\/strong><\/a><strong> <\/strong>Seg\u00fan quienes utilizan este t\u00e9rmino, el racismo no es un fen\u00f3meno unidireccional y as\u00ed como hay racismo ejercido contra personas afrodescendientes, ellas tambi\u00e9n pueden ser racistas contra personas blancas. \u201cEl racismo es hacia todas las razas\u201d suelen comentar. \u00bfEs esto cierto?<\/p>\n\n\n\n<p>Y\u00e1snaya Elena\nAguilar, ling\u00fcista mixe y columnista de EL PA\u00cdS indica que \u201cpara que el racismo\nfuera al rev\u00e9s tendr\u00edas que tener la situaci\u00f3n contraria a la que se ha vivido\npor siglos: que la poblaci\u00f3n blanca hubiera sido esclavizada, que no hubiera\npodido tener acceso a universidades, que se hubiera traficado con ellos y que\nel canon de personas fuera de personas no blancas y que los puestos de poder\nfueran ocupados por personas no blancas\u201d, <a href=\"https:\/\/verne.elpais.com\/verne\/2020\/06\/17\/mexico\/1592409000_664849.html\">expres\u00f3 al medio digital <strong>Verne<\/strong>.<\/a> <\/p>\n\n\n\n<p>\u00bfQu\u00e9 ser\u00eda\nentonces, el llamar despectivamente a alguien \u201cblanquito\u201d o prejuzgar sus\nactitudes por su apariencia? Concretamente, ser\u00edan prejuicios raciales, no\nracismo.&nbsp; Es importante establecer una\ndiferencia entre prejuicios y racismo. Muchas\nveces, las personas optan por recurrir a la RAE para definir lo que es racismo;\nsin embargo, la RAE no es la fuente m\u00e1s adecuada para esta tarea.<\/p>\n\n\n\n<p>La RAE define\nal racismo como: \u201cexacerbaci\u00f3n del sentido racial de un grupo \u00e9tnico que suele\nmotivar la discriminaci\u00f3n o persecuci\u00f3n de otro u otros con los que convive\u201d.\nComo se observa, esa definici\u00f3n&nbsp; a pesar\nde ser parcialmente cierta, a\u00fan es incompleta, inexacta y muy superficial para\ndefinir din\u00e1micas sociales. <\/p>\n\n\n\n<p>El racismo es\nun fen\u00f3meno social y su explicaci\u00f3n m\u00e1s cercana nos la pueden dar las ciencias\nsociales. El soci\u00f3logo Ram\u00f3n Grosfoguel lo define como un principio organizador\no una l\u00f3gica estructurante de todas las estructuras sociales y relaciones de\ndominaci\u00f3n de la modernidad. Este fen\u00f3meno se sustenta en la colonialidad e\ninvolucra a un grupo hist\u00f3ricamente opresor y una minor\u00eda hist\u00f3ricamente\noprimida. <\/p>\n\n\n\n<p>Mientras tanto, los prejuicios son conductas que podemos tener todas las personas hacia otros, producto de la esterotipaci\u00f3n y aprendizaje social. Nadie deber\u00eda sufrir de ello, por supuesto. No obstante, no es lo mismo sufrir de prejuicios que sufrir de racismo. Tal como explica la activista <a href=\"https:\/\/www.instagram.com\/chica.afroperuana\/?hl=es-la\">Una chica afroperuana<\/a><em>: \u201c<\/em>Tener preconceptos raciales nunca va a ser algo bueno. Pero en tu d\u00eda a d\u00eda, cuando salgas por la puerta de tu casa esto no te impide ning\u00fan derecho\u201d. <\/p>\n\n\n\n<p>Finalmente, se entiende que el \u201cracismo inverso\u201d, \u201cracismo hacia blancos\u201d, \u201cracismo de arriba hacia abajo\u201d como prefiera llamarse, no existe. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u201cracismo\u201d hacia personas blancas o tambi\u00e9n llamado \u201cracismo inverso\u201d es un discurso difundido para legitimar la posibilidad de un racismo bidireccional, que afecta a las personas blancas de igual manera que a otros grupos raciales. \u00bfEs esto cierto? No realmente,&nbsp; veamos por qu\u00e9. El concepto de \u201cracismo inverso\u201d es usado para explicar el caso [&hellip;]<\/p>\n","protected":false},"author":125,"featured_media":5360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[292],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5342"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=5342"}],"version-history":[{"count":4,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5342\/revisions"}],"predecessor-version":[{"id":5781,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5342\/revisions\/5781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/5360"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=5342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=5342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=5342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}