{"id":5396,"date":"2020-12-22T21:55:11","date_gmt":"2020-12-23T02:55:11","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=5396"},"modified":"2020-12-22T21:55:13","modified_gmt":"2020-12-23T02:55:13","slug":"las-apps-que-ayudan-a-tener-clases-virtuales","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/las-apps-que-ayudan-a-tener-clases-virtuales\/","title":{"rendered":"Las apps que ayudan a tener clases virtuales"},"content":{"rendered":"\n<p><strong>La emergencia sanitaria causada por la <a href=\"https:\/\/covid19.minsa.gob.pe\/sala_situacional.asp\">COVID-19<\/a>, provoc\u00f3 que diferentes plataformas virtuales sean utilizadas constantemente para las clases.<\/strong><\/p>\n\n\n\n<p>En lo que va del a\u00f1o gran\nparte de profesores les ha resultado dif\u00edcil adecuarse a este nuevo tipo de\nense\u00f1anza, pasar de lo presencial a lo virtual los oblig\u00f3 a cambiar\ndr\u00e1sticamente sus metodolog\u00edas. Tuvieron que pasar un proceso de aprendizaje\nr\u00e1pido durante varias horas y d\u00edas, al igual que los estudiantes que deb\u00edan acomodarse\na estas situaciones y, por \u00faltimo, los padres, que deben apoyar a sus hijos. <\/p>\n\n\n\n<p>El tener un buen desarrollo en\neste tipo de clases implica mantener permanente comunicaci\u00f3n con los alumnos,\nadem\u00e1s de tener una buena estrategia que permita al estudiante entender las\nclases. As\u00ed mismo, bajo esta modalidad, las actividades se realizan de forma\nsincr\u00f3nica y asincr\u00f3nica. Sin embargo,\nexisten limitaciones que no permite al alumno llevar una fluida clase, entre\nello se menciona los siguientes factores: la lentitud de internet, la\ndesconcentraci\u00f3n de los alumnos debido a esta modalidad, no tener en casa una\ncomputadora, celular, tablet, etc., por desconocimiento de las herramientas\nvirtuales, seg\u00fan la p\u00e1gina web educaci\u00f3nalfuturo.com<\/p>\n\n\n\n<p>Por otro\nlado, las herramientas digitales han servido de gran ayuda para la educaci\u00f3n,\nya que ahora estas plataformas cumplen el rol de un sal\u00f3n de clases como lo es\nMeet o Zoom, y otras que sirven para el env\u00edo de tareas y material educativo,\nque es el caso de Clasroom, WhatsApp, etc. <\/p>\n\n\n\n<p>De acuerdo con un informe publicado por la p\u00e1gina web <a aria-label=\"trecebits.com (opens in a new tab)\" href=\"https:\/\/www.trecebits.com\/2020\/03\/23\/10-herramientas-para-impartir-o-recibir-clases-virtuales-durante-el-confinamiento\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">trecebits.com<\/a>, hay una lista de apps gratuitas para Android e IOS&nbsp; que son las m\u00e1s utilizadas por j\u00f3venes de diferente edad para las clases virtuales.<\/p>\n\n\n\n<p><strong>Zoom:<\/strong><\/p>\n\n\n\n<p>Es una\nherramienta que se usa para conferencias o para realizar videollamadas. Es una\nalternativa a Skype o herramientas de este estilo, pero funciona de forma\nsimilar. Cada usuario debe tener su sesi\u00f3n activa para conectarse y usar la\nplataforma.<\/p>\n\n\n\n<p><strong>Microsoft Teams:<\/strong><\/p>\n\n\n\n<p>Esta\naplicaci\u00f3n se incluye en el paquete de Office 365 de Microsoft. Es de pago,\npero resulta bastante \u00fatil para dar clases online. Tiene funciones de correcci\u00f3n\nde trabajos y se pueden crear numerosas salas de chat con diversas tem\u00e1ticas.<\/p>\n\n\n\n<p><strong>ClassRoom:<\/strong><\/p>\n\n\n\n<p>Es una plataforma\nque permite acercar a los alumnos y profesores de una manera profesional. Es\nuna herramienta f\u00e1cil de usar, con el que se pueden crear y administrar las\nasignaciones generales de un curso.<\/p>\n\n\n\n<p><strong>GoToWebinar:<\/strong><\/p>\n\n\n\n<p>Es una\nherramienta compatible con Windows y Mac que permite dictar clases online, adem\u00e1s\nse puede desarrollar encuestas en vivo, compartir archivos, enviar correos\nelectr\u00f3nicos, mostrar presentaciones, etc.<\/p>\n\n\n\n<p><strong>Social Studies de Apple: <\/strong><\/p>\n\n\n\n<p>Esta plataforma fue creada por\nApple para facilitar el seguimiento y evaluaci\u00f3n de las actividades,\nrendimiento y desempe\u00f1o de los alumnos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La emergencia sanitaria causada por la COVID-19, provoc\u00f3 que diferentes plataformas virtuales sean utilizadas constantemente para las clases. En lo que va del a\u00f1o gran parte de profesores les ha resultado dif\u00edcil adecuarse a este nuevo tipo de ense\u00f1anza, pasar de lo presencial a lo virtual los oblig\u00f3 a cambiar dr\u00e1sticamente sus metodolog\u00edas. Tuvieron que [&hellip;]<\/p>\n","protected":false},"author":114,"featured_media":5397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[27,29,37,28],"tags":[641,642,86,66],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5396"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=5396"}],"version-history":[{"count":4,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5396\/revisions"}],"predecessor-version":[{"id":5846,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5396\/revisions\/5846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/5397"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=5396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=5396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=5396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}