{"id":5472,"date":"2020-12-18T19:31:47","date_gmt":"2020-12-19T00:31:47","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=5472"},"modified":"2021-01-18T18:04:51","modified_gmt":"2021-01-18T23:04:51","slug":"por-que-sigue-habiendo-racismo-en-el-peru","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/por-que-sigue-habiendo-racismo-en-el-peru\/","title":{"rendered":"Realidad nacional: \u00bfPor qu\u00e9 sigue habiendo racismo en el Per\u00fa?"},"content":{"rendered":"\n<p style=\"text-align:left\" class=\"has-normal-font-size\"><strong>Las pr\u00e1cticas discriminatorias en el Per\u00fa, a pesar de los a\u00f1os no se han erradicado, y hoy en d\u00eda siguen saliendo nuevos casos de v\u00edctimas de discriminaci\u00f3n, en una realidad en la que el \u2018cholo\u2019 se ha acostumbrado a \u2018cholear\u2019. <\/strong><\/p>\n\n\n\n<p style=\"font-size:15px\">Seg\u00fan Avil\u00e9s, en el Per\u00fa se podr\u00eda decir que <a href=\"https:\/\/www.bbva.com\/es\/racismo-en-peru-nos-criamos-en-un-pais-estructuralmente-racista\/\" class=\"ek-link\">los grupos m\u00e1s afectados por el racismo hist\u00f3ricamente son los ind\u00edgenas y los afroperuanos<\/a>, pero a decir verdad, el racismo violenta la realidad entera. Adem\u00e1s, menciona que los cholos migrantes como \u00e9l sufren una fuerte presi\u00f3n social para dejar de hablar quechua. En su caso particular, el no haber aprendido el idioma genera barreras en los lazos de comunicaci\u00f3n para con su abuela y personas de su comunidad de no contar con un int\u00e9rprete. Casos como el de Avil\u00e9s se repiten generando una <a href=\"http:\/\/dspace.unitru.edu.pe\/bitstream\/handle\/UNITRU\/7983\/FERNANDEZ%20VILLA-QUILICHE%20VARGAS-VALDIVIA%20AREDO.pdf?sequence=1&amp;isAllowed=y\" class=\"ek-link\">disminuci\u00f3n de la poblaci\u00f3n nativo hablante quechua en el Per\u00fa<\/a>.   <br>Las razones por las cuales he podido evidenciar que no se ha erradicado el racismo en el Per\u00fa son producto de la herencia colonial, la reproducci\u00f3n de estereotipos por color de piel y el desconocimiento del tema. <\/p>\n\n\n\n<p class=\"has-normal-font-size\"><strong>Herencia colonial <\/strong><\/p>\n\n\n\n<p style=\"font-size:15px\">Los antecedentes hist\u00f3ricos del Per\u00fa est\u00e1n fuertemente marcados por la colonizaci\u00f3n espa\u00f1ola que supuso un antes y un despu\u00e9s en la cultura de nuestros antepasados ind\u00edgenas, no solo por la aculturaci\u00f3n, es decir, la recepci\u00f3n y adopci\u00f3n de su cultura sino, tambi\u00e9n, por la <a href=\"https:\/\/dialnet.unirioja.es\/servlet\/articulo?codigo=3673703\" class=\"ek-link\">excusa para que impusieran su cultura<\/a>, tild\u00e1ndolos de b\u00e1rbaros y salvajes. Llevando, as\u00ed, a discriminarlos por sus or\u00edgenes, abriendo paso a que tiempo despu\u00e9s la sociedad peruana adopte los t\u00e9rminos <a href=\"https:\/\/puntoedu.pucp.edu.pe\/opinion\/por-que-serrano-es-un-insulto-en-el-peru\/\" class=\"ek-link\">serrano<\/a> y <a href=\"https:\/\/ssociologos.com\/2014\/05\/08\/el-racismo-en-el-peru-el-cholo-que-cholea-al-cholo\/\" class=\"ek-link\">cholo<\/a> para ofender a personas de etnias con or\u00edgenes en el territorio peruano. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"798\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Foto-Saga-Falabella.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Foto-Saga-Falabella.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Foto-Saga-Falabella-256x300.jpg 256w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Foto: Saga Falabella<\/figcaption><\/figure><\/div>\n\n\n\n<p style=\"text-align:left\" class=\"has-normal-font-size\"><strong>Reproducci\u00f3n de estereotipos por color piel <\/strong><\/p>\n\n\n\n<p style=\"font-size:15px\">Dejando de lado la herencia colonial, otro punto que se debe ver es lo que nos vende la publicidad. En muchos cat\u00e1logos de ropa aparecen rostros de tez blanca, pongamos el caso de <a href=\"https:\/\/www.falabella.com.pe\/falabella-pe\/\" class=\"ek-link\">Saga Falabella<\/a>. Ellos usan un prototipo de modelos en su mayor\u00eda con tez clara que se puede evidenciar en la portadas de sus revistas como la titulada Oto\u00f1o invierno 2020: moda post covid, sacada semanas antes de fiestas patrias (28 de julio).  El grupo en su totalidad evidencia, claramente,  rasgos cauc\u00e1sicos que no representan al peruano promedio, uno con tez m\u00e1s oscura, tal vez no tan alto. Lo que indica que inconscientemente m\u00e1s haya de vender la ropa, vende una est\u00e9tica estereotipada, \u00bfpor qu\u00e9 no usar m\u00e1s mestizos, m\u00e1s gente de ac\u00e1, m\u00e1s afroperuanos? A trav\u00e9s de esa imagen promueven a generar un &#8216;estatus&#8217; que se lograr\u00eda al vestir como los modelos. <\/p>\n\n\n\n<p class=\"has-normal-font-size\"><strong>Desconocimiento<\/strong><\/p>\n\n\n\n<p style=\"font-size:15px\">Por \u00faltimo, tenemos que mencionar que el desconocimiento y la falta de informaci\u00f3n sobre la diversidad de etnias y culturas existentes en el Per\u00fa. Muchas veces, estos temas son tocados en el sistema educativo escolar de forma deficiente. Yo misma he experimentado ello estando en el colegio, generalizan como \u2018etnia peruana\u2019 a todos, no son m\u00e1s rigurosos, y no todos podemos entrar en la misma lista porque no somos iguales, tenemos una diversidad tanto \u00e9tnica como cultural y si no nos dan una adecuada formaci\u00f3n en el tema, el desconocimiento nos puede hacer caer en pr\u00e1cticas de discriminaci\u00f3n. Tal situaci\u00f3n se refleja en el estudio de Pazos (2015) con su obra titulada <a href=\"http:\/\/revistas.urp.edu.pe\/index.php\/Scientia\/article\/view\/383\/379\" class=\"ek-link\">\u201cRacismo en la educaci\u00f3n peruana\u201d<\/a>, en donde se tom\u00f3 como muestra a maestros de educaci\u00f3n primaria y secundaria para saber sobre las pr\u00e1cticas discriminatorias entre los estudiantes, entre otras variables, resultando que s\u00ed existe un fuerte vocabulario peyorativo del uso de t\u00e9rminos como \u2018serrano\u2019 y \u2018cholo\u2019 entre los estudiantes.<\/p>\n\n\n\n<p style=\"font-size:15px\">Y ustedes, \u00bfcu\u00e1nto han hecho para cambiar esta realidad?<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las pr\u00e1cticas discriminatorias en el Per\u00fa, a pesar de los a\u00f1os no se han erradicado, y hoy en d\u00eda siguen saliendo nuevos casos de v\u00edctimas de discriminaci\u00f3n, en una realidad en la que el \u2018cholo\u2019 se ha acostumbrado a \u2018cholear\u2019. Seg\u00fan Avil\u00e9s, en el Per\u00fa se podr\u00eda decir que los grupos m\u00e1s afectados por el [&hellip;]<\/p>\n","protected":false},"author":133,"featured_media":5796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,190,335],"tags":[800],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5472"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=5472"}],"version-history":[{"count":19,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5472\/revisions"}],"predecessor-version":[{"id":8483,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5472\/revisions\/8483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/5796"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=5472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=5472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=5472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}